{"id":1291,"date":"2021-06-15T22:55:19","date_gmt":"2021-06-16T02:55:19","guid":{"rendered":"http:\/\/somnomed.gsqtest1.com\/en\/?page_id=1291"},"modified":"2025-10-30T15:54:01","modified_gmt":"2025-10-30T14:54:01","slug":"dentists","status":"publish","type":"page","link":"https:\/\/somnomed.com\/chgerman\/dentists\/","title":{"rendered":"Dentists"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1291\" class=\"elementor elementor-1291\" data-elementor-post-type=\"page\">\n\t\t\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-4abd43d2 e-con-full e-flex e-con e-parent\" data-id=\"4abd43d2\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-13e6dcfa elementor-pagination-position-at the bottom elementor-pagination-type-bullets elementor-arrows-position-inside elementor-widget elementor-widget-n-carousel\" data-id=\"13e6dcfa\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;carousel_items&quot;:[{&quot;slide_title&quot;:&quot;Our Journey Begins&quot;,&quot;_id&quot;:&quot;ae5dbe5&quot;},{&quot;slide_title&quot;:&quot;Discover the Difference&quot;,&quot;_id&quot;:&quot;0b3347d&quot;}],&quot;slides_to_show&quot;:&quot;1&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:32,&quot;sizes&quot;:[]},&quot;slides_to_show_tablet&quot;:&quot;1&quot;,&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;offset_sides&quot;:&quot;none&quot;,&quot;arrows&quot;:&quot;yes&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-carousel swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Gallery\" dir=\"ltr\">\n\t\t\t<div class=\"swiper-wrapper\" aria-live=\"polite\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"1\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 2\">\n\t\t\t\t\t\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-a33aeab e-flex e-con-boxed e-con e-child\" data-id=\"a33aeab\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-40d8d096 elementor-widget elementor-widget-heading\" data-id=\"40d8d096\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Vielen Dank<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-446cedfd elementor-widget-tablet__width-initial elementor-widget elementor-widget-heading\" data-id=\"446cedfd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Sie sind einer von Millionen \u2013 dank Ihnen haben wir weltweit \u00fcber eine Million Patienten erreicht.<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-2cd6c505 e-con-full e-flex e-con e-child\" data-id=\"2cd6c505\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4bfce71e elementor-widget__width-auto elementor-widget elementor-widget-button\" data-id=\"4bfce71e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/somnomed.com\/chgerman\/dentists\/one-million-sleep-apnea-patients-lives-improved\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Erfahren Sie mehr<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"2\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 2\">\n\t\t\t\t\t\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-79048807 e-flex e-con-boxed e-con e-child\" data-id=\"79048807\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e200f16 elementor-widget elementor-widget-heading\" data-id=\"e200f16\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Weltweit f\u00fchrend f\u00fcr komfortable Unterkieferprotrusionsschienen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-50c39060 elementor-widget-tablet__width-initial elementor-widget elementor-widget-heading\" data-id=\"50c39060\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">SomnoMed bietet komfortable Unterkieferprotrusionsschienen, die Ihre Patienten lieben werden \u2013 bereit, Ihre Praxis gemeinsam mit uns wachsen zu lassen?<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-element elementor-element-3103b5c0 e-con-full e-flex e-con e-child\" data-id=\"3103b5c0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5e7dfb6a elementor-widget__width-auto elementor-widget elementor-widget-button\" data-id=\"5e7dfb6a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/somnomed.com\/chgerman\/dentists\/clinical\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Erfahren Sie mehr \u00fcber die Zahn\u00e4rztliche Schlafmedizin<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Voriger\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t<\/div>\n\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"N\u00e4chster\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t<\/div>\n\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-4552a52f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4552a52f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5ec71827\" data-id=\"5ec71827\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7889b983 elementor-widget elementor-widget-Custom_El_Help_Search\" data-id=\"7889b983\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"Custom_El_Help_Search.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div id=\"el-help-search-6a04a547eb500\" class=\"el-help-search\">\r\n\t\t\t<form action=\"https:\/\/somnomed.com\/chgerman\" class=\"el-help-search__form\">\r\n\t\t\t\t\t\t\t\t\t\t\t<input type=\"hidden\" name=\"post_type\" value=\"primary_menu\">\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"row\">\r\n\t\t\t\t\t<div class=\"col-lg-8 position-relative\">\r\n\t\t\t\t\t\t<label for=\"el-help-search-6a04a547eb500-search\" class=\"sr-only\">Search<\/label>\r\n\t\t\t\t\t\t<input type=\"search\" name=\"s\" class=\"form-control\" value=\"\" id=\"el-help-search-6a04a547eb500-search\" placeholder=\"Wie k\u00f6nnen wir helfen?\">\r\n\r\n\t\t\t\t\t\t<button type=\"submit\" class=\"btn-link\">Search<\/button>\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t<div class=\"col-lg-4\">\r\n\t\t\t\t\t\t<select class=\"form-select\" aria-label=\"I am looking for\" name=\"user\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"patient\"  selected='selected'>Ich bin Patient<\/option>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"physician\" >Ich bin Arzt <\/option>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<option value=\"dentist\" >Ich bin Zahnarzt<\/option>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/select>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/form>\r\n\t\t<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-30126050 elementor-section-content-middle elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"30126050\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-614556b2\" data-id=\"614556b2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-21e96357 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"21e96357\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/somnomed.com\/chgerman\/wp-content\/uploads\/sites\/23\/elementor\/thumbs\/Dentist-Fitting-Patient-With-SomnoDent-Fusion-q2vmkv3drix6rxhdjcbvucya3f7t9ria0yyut3f95c.jpg\" title=\"Dentist Fitting Patient With SomnoDent Fusion\" alt=\"Dentist Fitting Patient With SomnoDent Fusion\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7f5570e4 padding-col--right\" data-id=\"7f5570e4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-7e579af3 elementor-section-full_width elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"7e579af3\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-6d0e367\" data-id=\"6d0e367\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-48302a40 elementor-widget elementor-widget-heading\" data-id=\"48302a40\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Warum sollte die Unterkieferprotrusions-schiene von einem Schlafzahnarzt angepasst werden?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7354f255 elementor-widget elementor-widget-text-editor\" data-id=\"7354f255\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Um sicherzustellen, dass das Gebiss des Patienten f\u00fcr eine Unterkieferprotrusionsschiene geeignet ist<\/li><li>Um einen genauen Intraoral-Scan oder konventionellen Abdruck durchzuf\u00fchren, mit denen wir f\u00fcr jeden Patienten die am besten passende Schiene herstellen k\u00f6nnen.\u00a0\u00a0<\/li><li>Um die Patienten einzuweisen, wie man die Schiene titriert und pflegt<\/li><li>Nachsorge bei Patienten, wenn sich seine Retention oder OSA \u00e4ndert<\/li><\/ul><p>Wir unterst\u00fctzen Sie bei der Behandlung Ihrer Patienten mit obstruktiver Schlafapnoe durch beste Technologie in der zahn\u00e4rztlichen Schlafmedizin und helfen Ihnen, Ihre Praxis im Bereich zahn\u00e4rztliche Schlafmedizin auszubauen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c9cd1d8 elementor-widget elementor-widget-button\" data-id=\"5c9cd1d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/somnomed.com\/chgerman\/dentists\/clinical\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Mehr erfahren<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-02be78b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"02be78b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7e725e0\" data-id=\"7e725e0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-56742a5 elementor-widget elementor-widget-spacer\" data-id=\"56742a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-52fa9ca0 elementor-section-content-middle elementor-section-full_width elementor-reverse-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"52fa9ca0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-52595fb7 padding-col--left\" data-id=\"52595fb7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1543b49c elementor-widget elementor-widget-video\" data-id=\"1543b49c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/cWjvGQQTDtU&quot;,&quot;lazy_load&quot;:&quot;yes&quot;,&quot;show_image_overlay&quot;:&quot;yes&quot;,&quot;image_overlay&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/somnomed.com\\\/chgerman\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2025\\\/03\\\/DE-1.png&quot;,&quot;id&quot;:15732,&quot;size&quot;:&quot;&quot;,&quot;alt&quot;:&quot;&quot;,&quot;source&quot;:&quot;library&quot;},&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t\t\t<div class=\"elementor-custom-embed-image-overlay\" style=\"background-image: url(https:\/\/somnomed.com\/chgerman\/wp-content\/uploads\/sites\/23\/2025\/03\/DE-1.png);\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-custom-embed-play\" role=\"button\" aria-label=\"Video abspielen\" tabindex=\"0\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-play\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-26237f51\" data-id=\"26237f51\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-9770ee7 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"9770ee7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-3756fc7\" data-id=\"3756fc7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f89f2eb elementor-widget elementor-widget-heading\" data-id=\"f89f2eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Einf\u00fchrung in SomAccount<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fd5f566 elementor-widget elementor-widget-text-editor\" data-id=\"fd5f566\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wir bei SomnoMed sind bestrebt, die Behandlung unserer Patienten nahtlos zu gestalten. Um die Art und Weise, wie Sie bei SomnoMed bestellen, zu ver\u00e4ndern, haben wir SomAccount entwickelt, unser neues Kundenportal, das es Zahn\u00e4rzten erm\u00f6glicht, ihre Ger\u00e4te einfach online zu bestellen.<\/p><p>In diesem Portal k\u00f6nnen Sie Ihre Pr\u00e4ferenzen speichern, IOS-Datens\u00e4tze versenden und Rechnungen einsehen und bezahlen.<\/p><p>Wenn Sie bereits Kunde sind, setzen Sie sich bitte mit uns in Verbindung, um Ihre Daten zu \u00fcberpr\u00fcfen und einen reibungslosen \u00dcbergang f\u00fcr Ihre Online-Bestellung zu gew\u00e4hrleisten. Bitte rufen Sie uns unter +41 41 501 46 40 an oder klicken Sie auf den unten stehenden Link, um Ihre Daten einzugeben.<\/p><p>F\u00fcr neue Kunden setzen Sie sich bitte mit uns in Verbindung, um Ihr Konto einzurichten oder senden Sie uns eine E-Mail an swissinfo@somnomed.com.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8015a52 elementor-widget elementor-widget-text-editor\" data-id=\"8015a52\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wenn Ihre Daten auf dem neuesten Stand sind, k\u00f6nnen Sie sich hier in Ihr Konto einloggen und Ihre Bestellungen aufgeben.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1abcb34 elementor-widget elementor-widget-button\" data-id=\"1abcb34\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/somaccount.somnomed.com\/ch_de\/customer\/account\/login\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">SomAccount login<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-02bd17d elementor-widget elementor-widget-text-editor\" data-id=\"02bd17d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>F\u00fcr diejenigen, die Informationen \u00fcber die Verwendung von SomAccount ben\u00f6tigen, sehen Sie sich hier unsere Videos an:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-863057d elementor-widget elementor-widget-button\" data-id=\"863057d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/somnomed.com\/chgerman\/dentists\/somaccount-home\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">SomAccount Anleitung<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-3af479e elementor-section-content-middle elementor-section-full_width elementor-reverse-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"3af479e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-484d4c2 padding-col--left\" data-id=\"484d4c2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-3e5d6e9 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"3e5d6e9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-815527e\" data-id=\"815527e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eb4f1aa elementor-widget elementor-widget-heading\" data-id=\"eb4f1aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">H\u00f6chster Tragekomfort und Effektivit\u00e4t<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d754457 elementor-widget elementor-widget-text-editor\" data-id=\"d754457\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #00549d;\"><strong>Patentierte b-flex Comfort Liner<sup>\u00ae<\/sup> Innenschicht f\u00fcr h\u00f6chsten\u00a0 Tragekomfort\u00a0<\/strong><\/span><\/p><p style=\"background: white; margin: 0cm 0cm 18.75pt 0cm;\"><span style=\"font-size: 13.5pt; font-family: 'Arial',sans-serif; color: #3d3d3d;\">Die patentierte b-flex Comfort Liner Innenschicht erm\u00f6glicht den hohen Tragekomfort der SomnoDent-Schienen.<br \/><\/span><span style=\"font-size: 13.5pt; font-family: 'Arial',sans-serif; color: #3d3d3d;\">Unsere b-flex Comfort Liner Innenschicht bietet beispiellosen Tragekomfort und hervorragende Retention. Durch diese Materialtechnologie st\u00fctzen und polstern die SomnoMed Unterkieferprotrusionsschienen jeden Zahn, reduzieren den Druck und verteilen die okklusalen Belastungen gleichm\u00e4ssig, wodurch der Tragekomfort maximiert wird. Dadurch erh\u00f6ht sich die Akzeptanz (Compliance) der Patienten und somit der Behandlungserfolg.<br \/><\/span><span style=\"font-size: 13.5pt; font-family: 'Arial',sans-serif; color: #3d3d3d;\">Weitere Informationen finden Sie rechts in unserem\u00a0<strong style=\"box-sizing: border-box;\"><a style=\"box-sizing: border-box; color: inherit; box-shadow: none;\" href=\"https:\/\/vimeo.com\/636851529\" target=\"_blank\" rel=\"noopener\"><span style=\"box-sizing: border-box;\"><span style=\"text-decoration: none; text-underline: none;\">b-flex Video<\/span><\/span><\/a><\/strong><\/span>\u00a0(in Englisch)<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6a0332a\" data-id=\"6a0332a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f5c4289 elementor-widget elementor-widget-video\" data-id=\"f5c4289\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;lazy_load&quot;:&quot;yes&quot;,&quot;show_image_overlay&quot;:&quot;yes&quot;,&quot;image_overlay&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/somnomed.co\\\/au\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/10\\\/BFlex-1.png&quot;,&quot;id&quot;:11831,&quot;size&quot;:&quot;&quot;,&quot;alt&quot;:&quot;&quot;,&quot;source&quot;:&quot;library&quot;},&quot;video_type&quot;:&quot;vimeo&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<iframe class=\"elementor-video-iframe\" allowfullscreen allow=\"clipboard-write\" title=\"vimeo Video Player\" data-lazy-load=\"https:\/\/player.vimeo.com\/video\/636851529?color&amp;autopause=0&amp;loop=0&amp;muted=0&amp;title=0&amp;portrait=0&amp;byline=0#t=\"><\/iframe>\t\t\t\t<div class=\"elementor-custom-embed-image-overlay\" style=\"background-image: url(https:\/\/somnomed.com\/chgerman\/wp-content\/uploads\/sites\/23\/2021\/10\/BFlex-1.png);\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-custom-embed-play\" role=\"button\" aria-label=\"Video abspielen\" tabindex=\"0\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-play\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-7fecbaca elementor-section-content-middle elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"7fecbaca\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4b607606\" data-id=\"4b607606\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5eafdae5 elementor-invisible elementor-widget elementor-widget-video\" data-id=\"5eafdae5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;lazy_load&quot;:&quot;yes&quot;,&quot;show_image_overlay&quot;:&quot;yes&quot;,&quot;image_overlay&quot;:{&quot;url&quot;:&quot;http:\\\/\\\/somnomed.co\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/06\\\/Banner-AACP-2000x1200px-1.png&quot;,&quot;id&quot;:&quot;1835&quot;,&quot;size&quot;:&quot;&quot;},&quot;video_type&quot;:&quot;vimeo&quot;,&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<iframe class=\"elementor-video-iframe\" allowfullscreen allow=\"clipboard-write\" title=\"vimeo Video Player\" data-lazy-load=\"https:\/\/player.vimeo.com\/video\/568849617?color&amp;autopause=0&amp;loop=0&amp;muted=0&amp;title=1&amp;portrait=1&amp;byline=1#t=\"><\/iframe>\t\t\t\t<div class=\"elementor-custom-embed-image-overlay\" style=\"background-image: url(https:\/\/somnomed.com\/chgerman\/wp-content\/uploads\/sites\/23\/2021\/06\/Banner-AACP-2000x1200px-1.png);\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-custom-embed-play\" role=\"button\" aria-label=\"Video abspielen\" tabindex=\"0\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-play\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6c13dd1d padding-col--right\" data-id=\"6c13dd1d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-682a327f elementor-section-full_width elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"682a327f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-4ab33583\" data-id=\"4ab33583\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-66c000e2 elementor-widget elementor-widget-heading\" data-id=\"66c000e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Die Effektivit\u00e4ts-Gleichung\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4303fc91 elementor-widget elementor-widget-text-editor\" data-id=\"4303fc91\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wir haben die Effektivit\u00e4tsgleichung entwickelt \u2013 ein Tool, mit dem Sie eine Nacht f\u00fcr Ihren Patienten entweder mit CPAP oder einer Schlafapnoe-Schiene simulieren k\u00f6nnen. W\u00e4hrend die CPAP bei therapietreuen Patienten gut anschl\u00e4gt, werden Patienten, die die CPAP-Therapie nachts abbrechen m\u00fcssen, eher nicht optimal behandelt. Da Patienten in der Regel, die meiste Zeit der Nacht ihre Schiene tragen, kann die Verringerung des AHI \u00fcber die ganze Nacht hinweg bei beiden Therapien \u00e4hnlich sein.<br \/><br \/>Sehen Sie sich das Video an, um zu verstehen, wie die Wirksamkeit der Behandlung sowohl von der Effizienz als auch von der Compliance w\u00e4hrend der Nacht abh\u00e4ngt.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12e1a32a elementor-widget elementor-widget-button\" data-id=\"12e1a32a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/vimeo.com\/568849617\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Video ansehen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12d2a3d0 elementor-widget elementor-widget-text-editor\" data-id=\"12d2a3d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Vergleichen Sie die Ergebnisse einer Nacht mit CPAP oder einer n\u00e4chtlichen Therapie mit einer UKPS f\u00fcr einen Patienten aus einer klinischen Studie oder f\u00fcgen Sie Ihre eigenen Patientendaten ein um eine Simulation mit dem Tool \u201eEffectiveness Equation\u201c durchzuf\u00fchren.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6aeade18 elementor-widget elementor-widget-button\" data-id=\"6aeade18\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/somnomed.com\/en\/effectiveness-equation-tool\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Effektivit\u00e4tssimulator<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-5fcd2bac elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5fcd2bac\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5c0ae407\" data-id=\"5c0ae407\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-663c85b6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"663c85b6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-17de4ad8\" data-id=\"17de4ad8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-29a26fdc elementor-widget elementor-widget-heading\" data-id=\"29a26fdc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Weitere Informationen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-64978001 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"64978001\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-5e1d0bbe\" data-id=\"5e1d0bbe\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-528e7380\" data-id=\"528e7380\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-21bbea0c icon--hover elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"21bbea0c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/somnomed.com\/chgerman\/patients\/products\/somnodent\/somnodent-avant\/\" target=\"_blank\" class=\"elementor-icon\" tabindex=\"-1\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"142.915\" height=\"95.641\" viewBox=\"0 0 142.915 95.641\"><g transform=\"translate(-2.315 -31.259)\"><path d=\"M144.018,70.409c-.163-.244-.326-.407-.489-.652a2.07,2.07,0,0,0-2.852-.9c-2.363,1.222-4.808,2.119-7.171,3.26a3.662,3.662,0,0,0-1.793,1.711c-.163.326-.244.652-.652.652-1.874.163-3.667-.163-4.4-2.2-.244-.733-.57-1.548-.815-2.282a2.266,2.266,0,0,0-1.956-1.63,16.315,16.315,0,0,1-1.956-.326c-1.956-.407-3.83-.9-5.786-1.3a5.433,5.433,0,0,0-4.482.733,8.358,8.358,0,0,0-2.282,2.2,2,2,0,0,1-1.956.9c-1.059-.163-2.119-.326-3.178-.57-3.341-.407-6.682-.733-10.024-.815a3.34,3.34,0,0,0-2.282.733,13.386,13.386,0,0,0-2.363,2.445,2.794,2.794,0,0,1-3.015,1.3,48.07,48.07,0,0,0-6.845-.244,6.147,6.147,0,0,0-4.727,2.526,3.384,3.384,0,0,1-3.586,1.222,30.935,30.935,0,0,0-7.253-.815h-13.2a13.338,13.338,0,0,1-3.1-.326c-1.059-.244-1.222-.57-.57-1.467a3.764,3.764,0,0,1,.57-.57,5.617,5.617,0,0,0,1.711-1.956c.57-1.222,1.059-2.526,1.63-3.749a5.193,5.193,0,0,0,.081-4.89,2.041,2.041,0,0,1,.733-2.689,7.551,7.551,0,0,0,1.141-1.141c1.956-2.282,3.423-4.808,5.216-7.171.9-1.222,1.874-2.445,2.771-3.667a1.478,1.478,0,0,0,.081-1.874,13.006,13.006,0,0,0-2.282-2.852,3.425,3.425,0,0,0-3.749-.978,1.131,1.131,0,0,1-1.385-.326,5.611,5.611,0,0,1-.9-1.059,21.431,21.431,0,0,0-3.26-3.423,21.759,21.759,0,0,1-3.83-3.912,13.348,13.348,0,0,0-1.711-2.037,3.215,3.215,0,0,0-3.83-.652c-1.793.815-2.363,2.445-2.934,4.075-.407,1.385-.407,1.385-1.874,1.3a1.794,1.794,0,0,0-.652.081c-1.141.326-2.363.57-3.423.978-2.2.815-3.912,2.119-4.238,4.645a5.647,5.647,0,0,0-.244,1.63c0,.9-.57,1.141-1.3,1.059a13.175,13.175,0,0,0-3.1-.163,4.084,4.084,0,0,0-3.749,3.586,1.055,1.055,0,0,1-.815,1.059,5.942,5.942,0,0,0-3.5,5.216,13.163,13.163,0,0,1,0,1.793.958.958,0,0,1-1.467.9,1.122,1.122,0,0,0-1.3.407,4.918,4.918,0,0,0-1.059,4.238,3.378,3.378,0,0,1,.244,1.3,10.627,10.627,0,0,0,.163,3.586l-.326.081c-2.526.815-9.127,6.03-8.312,12.957.407,3.423,1.711,5.3,4.645,7.09A4.71,4.71,0,0,0,6.3,93.39,2.133,2.133,0,0,1,6.7,94.775c-.407,2.037.163,4.075.326,6.03A5.089,5.089,0,0,0,9.637,104.8c1.3.815,1.467.815,2.282-.57.407-.733.733-.652,1.222-.081a13.128,13.128,0,0,0,3.667,3.341,12.1,12.1,0,0,1,3.26,2.526,5.973,5.973,0,0,0,5.7,1.793,5.939,5.939,0,0,1,2.934.244,29.959,29.959,0,0,0,3.83,1.222,46.141,46.141,0,0,1,7.334,2.608c2.363.9,4.727,1.548,7.171.9a8.881,8.881,0,0,1,5.053.244c2.608.815,5.379,1.385,7.5,3.26a9.433,9.433,0,0,0,3.26,1.63,12.735,12.735,0,0,1,4.727,2.282,10.815,10.815,0,0,0,4.808,2.445,4.334,4.334,0,0,0,3.341-.163,23.049,23.049,0,0,0,3.83-2.363,3.567,3.567,0,0,1,4.156-.407l1.3.652c1.793.733,3.586,1.548,5.541,1.141a12.99,12.99,0,0,0,5.379-2.2c1.711-1.3,3.5-2.445,5.3-3.749a5.042,5.042,0,0,1,4.156-.978,20.37,20.37,0,0,0,2.363.407c1.711.244,3.5.489,5.134-.326a50.434,50.434,0,0,0,4.727-2.282,14.158,14.158,0,0,0,3.178.407c4.238,0,7.5-2.526,9.127-7.171.163-.407.244-.9.407-1.3a5.927,5.927,0,0,0,3.586-3.912,8.818,8.818,0,0,0,.244-3.586c-.407-2.445-.407-5.134-1.874-7.253-.978-1.548-.733-2.363.326-3.667,1.793-2.119,3.341-4.564,5.7-6.275a18.928,18.928,0,0,0,6.275-8.231,3.868,3.868,0,0,0-.57-4.971ZM120.874,114.5a10.322,10.322,0,0,1-3.83-.733c-5.46-1.956-11.327-5.7-18.825-6.275-7.5-.489-43.11-.9-73.262-14.506-11-4.89-16.054-6.6-18.336-8.8A7.073,7.073,0,0,1,4.911,79.7c-.163-3.178,1.548-5.46,3.5-7.579A7.875,7.875,0,0,1,11.1,70.164a1.125,1.125,0,0,0,.326-.244c.081,0,.163-.081.244-.081a25.654,25.654,0,0,1,.407,3.5s-4.319,4.319-3.26,7.171S38.241,94.368,44.516,96.16C57.636,99.909,85.1,104.473,97,104.473a32.826,32.826,0,0,0,3.993-.244c6.845-1.3,13.12-4.645,18.173-4.645a8.6,8.6,0,0,1,2.526.326c5.46,1.548,7.5,4.4,5.867,9.209a8.426,8.426,0,0,1-3.667,4.808,7.34,7.34,0,0,1-2.282.652h-.081A1.589,1.589,0,0,0,120.874,114.5Z\" transform=\"translate(0 0)\" fill=\"#65cbe0\"><\/path><path d=\"M151.122,122.9a3.161,3.161,0,0,0-6.322-.069,3.114,3.114,0,0,0,3.126,3.127A3.031,3.031,0,0,0,151.122,122.9Z\" transform=\"translate(-22.419 -15.485)\" fill=\"#65cbe0\"><\/path><\/g><\/svg>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tWeitere Informationen \u00fcber unsere bisher komfortabelste Schiene, die SomnoDent Avant<sup>\u00ae<\/sup>, finden SIe unter folgendem Link. \t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-55583860\" data-id=\"55583860\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5ec92ac3 icon--hover elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"5ec92ac3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/somnomed.com\/chgerman\/dentists\/dentists-contact\/\" target=\"_blank\" class=\"elementor-icon\" tabindex=\"-1\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-comment-alt\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tKontaktieren Sie SomnoMed<sup>\u00ae<\/sup> \t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-de2ae8b\" data-id=\"de2ae8b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-676fd3af elementor-section-content-middle elementor-section-full_width elementor-reverse-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"676fd3af\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4b426d1c padding-col--left\" data-id=\"4b426d1c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-6abdc26b elementor-section-full_width elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"6abdc26b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-6fef1fa4\" data-id=\"6fef1fa4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-27d05fad elementor-widget elementor-widget-heading\" data-id=\"27d05fad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/vimeo.com\/573281862\" target=\"_blank\" rel=\"noopener\">Was berichten SomnoMed<sup>\u00ae<\/sup> Patienten?<\/a><\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-46379091 elementor-widget elementor-widget-text-editor\" data-id=\"46379091\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #00549d;\"><strong>Jeder Patient ist unterschiedlich und wir haben schon viele auf ihrem Weg zu einer effektiven Behandlung begleitet.<\/strong><\/span><\/p><p>Sehen Sie ihre Geschichte und wie die SomnoDent<sup>\u00ae<\/sup> Unterkieferprotrusionsschiene ihnen geholfen hat.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-370e3478\" data-id=\"370e3478\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-36edfd0f elementor-invisible elementor-widget elementor-widget-video\" data-id=\"36edfd0f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;lazy_load&quot;:&quot;yes&quot;,&quot;show_image_overlay&quot;:&quot;yes&quot;,&quot;image_overlay&quot;:{&quot;url&quot;:&quot;http:\\\/\\\/somnomed.co\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/06\\\/Image-for-website-20.jpg&quot;,&quot;id&quot;:&quot;5666&quot;,&quot;size&quot;:&quot;&quot;},&quot;video_type&quot;:&quot;vimeo&quot;,&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<iframe class=\"elementor-video-iframe\" allowfullscreen allow=\"clipboard-write\" title=\"vimeo Video Player\" data-lazy-load=\"https:\/\/player.vimeo.com\/video\/213864189?color&amp;autopause=0&amp;loop=0&amp;muted=0&amp;title=0&amp;portrait=0&amp;byline=0#t=\"><\/iframe>\t\t\t\t<div class=\"elementor-custom-embed-image-overlay\" style=\"background-image: url(https:\/\/somnomed.com\/chgerman\/wp-content\/uploads\/sites\/23\/2021\/06\/Image-for-website-20.jpg);\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-5a969a8e elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"5a969a8e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1b709147\" data-id=\"1b709147\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6b87057d elementor-widget elementor-widget-heading\" data-id=\"6b87057d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Patienterfahrungen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6516588c elementor-widget elementor-widget-Custom_El_Slider_Text\" data-id=\"6516588c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"Custom_El_Slider_Text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t          <div id=\"el-slider-text-6a04a54800597\" class=\"el-slider-text\">\r\n        <div class=\"el-slider-text__slider\">\r\n                      <div class=\"el-slider-text__slide\">\r\n              <div class=\"el-slider-text__slide-inner balance-elements\" style=\"background-color: #C3E7EF; color: #000000; \">\r\n                <h3><b>Man sp\u00fcrt sie kaum<\/b><\/h3>\n<p>Ich habe die SomnoDent-Schiene seit einem halben Jahr und muss sagen, dass es mir dank dieser Schiene wesentlich besser geht. Es sind noch nicht alle Probleme beseitig, da sich mein K\u00f6rper durch jahrelange Ersch\u00f6pfung erst so langsam erholt. Ich kann jedem diese Schiene empfehlen, der nicht mit eine Maske leben m\u00f6chte. Die Schiene ist so leicht zu tragen und man sp\u00fcrt sie kaum. Ich kann es nicht anders ausdr\u00fccken, die SomnoDent-Schiene ist mein Lebensretter. Hoffe, ich kann vielen Menschen, die an Schlafapnoe leiden, durch meine positive Erfahrung weiterhelfen.<\/p>\n<p style=\"text-align: right;\"><strong>- Matthias<\/strong><\/p>\n              <\/div>\r\n            <\/div>\r\n                      <div class=\"el-slider-text__slide\">\r\n              <div class=\"el-slider-text__slide-inner balance-elements\" style=\"background-color: #C1CAE3; color: #000000; \">\r\n                <h3><b>Ich habe mein Leben zur\u00fcck<\/b><\/h3>\n<p>Ich habe mein Leben zur\u00fcck, dank SomnoDent<sup>\u00ae<\/sup>! Jetzt habe ich wieder die grenzenlose Energie, wie ich sie als Teenager hatte, bevor ich die Schlafapnoe bekam. Ich stehe fr\u00fch auf, gehe sp\u00e4t ins Bett, bin mit 51 in ein Sportstudio eingetreten (ich war nie zuvor in einem Sportstudio) und f\u00fchle mich zu 100 % voller Energie!<\/p>\n<p style=\"text-align: right;\"><strong>- Tjark<\/strong><\/p>\n              <\/div>\r\n            <\/div>\r\n                      <div class=\"el-slider-text__slide\">\r\n              <div class=\"el-slider-text__slide-inner balance-elements\" style=\"background-color: #7B91C4; color: #FFFFFF; \">\r\n                <h3><b>Keine Druckstellen<\/b><\/h3>\n<p>Der Tragekomfort der SomnoDent ist phantastisch! 100%ige Passgenauigkeit,<br \/>keine Reibungs- oder Druckpunkte an den \u00dcberg\u00e4ngen zum Zahnfleisch. Damit hatte ich bei anderen Schienen immer wieder Probleme und musste diese mehrmals neu anpassen.<\/p>\n<p style=\"text-align: right;\"><strong>- Gaby<\/strong><\/p>\n              <\/div>\r\n            <\/div>\r\n                      <div class=\"el-slider-text__slide\">\r\n              <div class=\"el-slider-text__slide-inner balance-elements\" style=\"background-color: #5175B3; color: #ffffff; \">\r\n                <h3><b>Mein Mann ist wieder fit<\/b><\/h3>\n<p>Mein Mann hatte mit der SomnoDent Schiene nur noch einen AHI von 6,6\/h. Mit der Schiene kommt er super klar. Er tr\u00e4gt sie jede Nacht w\u00e4hrend der kompletten Schlafzeit ohne Probleme. Nach vielen Jahren ist er dank der SomnoDent<sup>\u00ae<\/sup>-Schiene zum ersten Mal wieder so fit und gut drauf wie vor zehn Jahren, als ich ihn kennengelernt hatte.<\/p>\n<p style=\"text-align: right;\"><strong>- Mirja<\/strong><\/p>\n              <\/div>\r\n            <\/div>\r\n                      <div class=\"el-slider-text__slide\">\r\n              <div class=\"el-slider-text__slide-inner balance-elements\" style=\"background-color: #00549D; color: #ffffff; \">\r\n                <h3><b>Wie ein neuer Mensch<\/b><\/h3>\n<p>Seit ich sie benutze f\u00fchle ich mich wieder wie ein vollst\u00e4ndiger Mensch. Ich w\u00fcrde sie jedem empfehlen, der an Schlafapnoe leidet. Sie ist einfach klasse.<\/p>\n<p style=\"text-align: right;\"><strong>- Volker<\/strong><\/p>\n              <\/div>\r\n            <\/div>\r\n                  <\/div>\r\n      <\/div>\r\n\r\n      <script>\r\n        jQuery(document).ready(function($) {\r\n          $('#el-slider-text-6a04a54800597 .el-slider-text__slider').slick({\r\n            centerMode: true,\r\n            centerPadding: '300px',\r\n            slidesToShow: 2,\r\n            arrows: true,\r\n            dots: false,\r\n            infinite: true,\r\n            responsive: [\r\n              {\r\n                breakpoint: 1600,\r\n                settings: {\r\n                  arrows: false,\r\n                  dots: true,\r\n                  centerPadding: '150px',\r\n                  slidesToShow: 2\r\n                }\r\n              },\r\n              {\r\n                breakpoint: 768,\r\n                settings: {\r\n                  arrows: false,\r\n                  dots: true,\r\n                  centerPadding: '5px',\r\n                  slidesToShow: 1\r\n                }\r\n              }\r\n            ]\r\n          });\r\n        });\r\n      <\/script>\r\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-4ed6460c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4ed6460c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2c347539\" data-id=\"2c347539\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-63f92453 elementor-widget elementor-widget-spacer\" data-id=\"63f92453\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Vielen Dank Sie sind einer von Millionen \u2013 dank Ihnen haben wir weltweit \u00fcber eine Million Patienten erreicht. Erfahren Sie mehr Weltweit f\u00fchrend f\u00fcr komfortable Unterkieferprotrusionsschienen SomnoMed bietet komfortable Unterkieferprotrusionsschienen, die Ihre Patienten lieben werden \u2013 bereit, Ihre Praxis gemeinsam mit uns wachsen zu lassen? Erfahren Sie mehr \u00fcber die Zahn\u00e4rztliche Schlafmedizin Vielen Dank Sie &#8230;<\/p>\n","protected":false},"author":96,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1291","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/somnomed.com\/chgerman\/wp-json\/wp\/v2\/pages\/1291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/somnomed.com\/chgerman\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/somnomed.com\/chgerman\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/somnomed.com\/chgerman\/wp-json\/wp\/v2\/users\/96"}],"replies":[{"embeddable":true,"href":"https:\/\/somnomed.com\/chgerman\/wp-json\/wp\/v2\/comments?post=1291"}],"version-history":[{"count":10,"href":"https:\/\/somnomed.com\/chgerman\/wp-json\/wp\/v2\/pages\/1291\/revisions"}],"predecessor-version":[{"id":16625,"href":"https:\/\/somnomed.com\/chgerman\/wp-json\/wp\/v2\/pages\/1291\/revisions\/16625"}],"wp:attachment":[{"href":"https:\/\/somnomed.com\/chgerman\/wp-json\/wp\/v2\/media?parent=1291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}