{"id":3540,"date":"2021-07-05T05:00:41","date_gmt":"2021-07-05T09:00:41","guid":{"rendered":"http:\/\/somnomed.gsqtest1.com\/en\/?page_id=3540"},"modified":"2025-11-13T09:58:50","modified_gmt":"2025-11-13T08:58:50","slug":"somnodent","status":"publish","type":"page","link":"https:\/\/somnomed.com\/chgerman\/dentists\/products\/somnodent\/","title":{"rendered":"SomnoDent<sup>\u00ae<\/sup>"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"3540\" class=\"elementor elementor-3540\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-5ac85ff4 elementor-section-content-middle elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"5ac85ff4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5db404ec\" data-id=\"5db404ec\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1e132bdc elementor-widget elementor-widget-image\" data-id=\"1e132bdc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/somnomed.com\/chgerman\/wp-content\/uploads\/sites\/23\/2021\/07\/Image-for-website-15.jpg\" class=\"attachment-full size-full wp-image-4651\" alt=\"\" srcset=\"https:\/\/somnomed.com\/chgerman\/wp-content\/uploads\/sites\/23\/2021\/07\/Image-for-website-15.jpg 1200w, https:\/\/somnomed.com\/chgerman\/wp-content\/uploads\/sites\/23\/2021\/07\/Image-for-website-15-300x200.jpg 300w, https:\/\/somnomed.com\/chgerman\/wp-content\/uploads\/sites\/23\/2021\/07\/Image-for-website-15-1024x683.jpg 1024w, https:\/\/somnomed.com\/chgerman\/wp-content\/uploads\/sites\/23\/2021\/07\/Image-for-website-15-768x512.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2eb24230 padding-col--right\" data-id=\"2eb24230\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-6d3b2cdc elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"6d3b2cdc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-787a0029\" data-id=\"787a0029\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ac5f824 elementor-widget elementor-widget-heading\" data-id=\"4ac5f824\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">SomnoDent<sup>\u00ae<\/sup>-Schienen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7bb94491 elementor-widget elementor-widget-text-editor\" data-id=\"7bb94491\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Kein Patient gleicht dem anderen. Deshalb hat SomnoMed<sup>\u00ae<\/sup>\u00a0unterschiedliche Unterkieferprotrusionsschienen mit einer breiten Palette an Optionen zur Behandlung von Patienten mit obstruktiver Schlafapnoe (OSA) zur Auswahl.<\/p><p>SomnoMed\u00a0hat die SomnoDent-Familie entwickelt \u2013 klinisch bew\u00e4hrte Unterkieferprotrusionsschienen \u2013 die innovative Technologie nutzen.<\/p><p>In unseren hochmodernen, nach ISO 13485 zertifizierten Einrichtungen arbeiten qualifizierte Spezialisten von SomnoMed mit gr\u00f6sster Sorgfalt, Genauigkeit und Pr\u00e4zision nach h\u00f6chsten Qualit\u00e4tsstandards, um hochwertige, zuverl\u00e4ssige und wirksame Schienen zu fertigen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-da8eaa9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"da8eaa9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-eaa2523\" data-id=\"eaa2523\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3825061 elementor-widget elementor-widget-spacer\" data-id=\"3825061\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-2c945181 elementor-section-content-middle elementor-section-full_width elementor-reverse-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"2c945181\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-704d46a1 padding-col--left\" data-id=\"704d46a1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-625c4687 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"625c4687\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-78b40bfd\" data-id=\"78b40bfd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-30417b21 elementor-widget elementor-widget-heading\" data-id=\"30417b21\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Der Standard f\u00fcr Komfort und Effektivit\u00e4t<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3541cb68 elementor-widget elementor-widget-text-editor\" data-id=\"3541cb68\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>SomnoMed ist weltweit f\u00fchrend in der Entwicklung und Herstellung von Unterkieferprotrusionsschienen zur Behandlung von obstruktiver Schlafapnoe.\u00a0<\/p><p>Seit Beginn der Herstellung von Unterkieferprotrusionsschienen im Jahr 2004 hat SomnoMed das SomnoDent-Sortiment kontinuierlich verbessert, wobei der Schwerpunkt auf der Verbesserung des Tragekomforts und der Behandlung von Schlafapnoe liegt.<\/p><p>Der Komfort der SomnoDent-Schienen beruht auf unserer einzigartigen b-flex Comfort Liner<sup>\u00ae<\/sup> Innenschicht.<\/p><p>Die b-flex Comfort Liner Innenschicht umschliesst und st\u00fctzt jeden Zahn und reduziert den Druck auf die Z\u00e4hne, der zu Beschwerden und Zahnbewegungen f\u00fchren kann. Weitere Informationen finden Sie rechts in unserem <span style=\"text-decoration: underline;\"><strong><a href=\"https:\/\/vimeo.com\/636851529\" target=\"_blank\" rel=\"noopener\">b-flex Video<\/a><\/strong><\/span> (in Englisch)<\/p><p>Unsere neuesten Innovationen sind in der <span style=\"text-decoration: underline;\"><strong><a href=\"https:\/\/somnomed.com\/chgerman\/dentists\/products\/somnodent\/somnodent-avant\/\">SomnoDent Avant <\/a><\/strong><\/span>integriert. \u00a0Diese motiviert dazu, \u00fcber die Nase anstatt \u00fcber den Mund zu atmen, um so einen angenehmeren Schlaf zu gew\u00e4hrleisten.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-44f0c479\" data-id=\"44f0c479\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5e88d17f elementor-widget elementor-widget-video\" data-id=\"5e88d17f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;lazy_load&quot;:&quot;yes&quot;,&quot;show_image_overlay&quot;:&quot;yes&quot;,&quot;image_overlay&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/somnomed.co\\\/au\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2021\\\/10\\\/BFlex-1.png&quot;,&quot;id&quot;:11831,&quot;size&quot;:&quot;&quot;,&quot;alt&quot;:&quot;&quot;,&quot;source&quot;:&quot;library&quot;},&quot;video_type&quot;:&quot;vimeo&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<iframe class=\"elementor-video-iframe\" allowfullscreen allow=\"clipboard-write\" title=\"vimeo Video Player\" data-lazy-load=\"https:\/\/player.vimeo.com\/video\/636851529?color&amp;autopause=0&amp;loop=0&amp;muted=0&amp;title=0&amp;portrait=0&amp;byline=0#t=\"><\/iframe>\t\t\t\t<div class=\"elementor-custom-embed-image-overlay\" style=\"background-image: url(https:\/\/somnomed.com\/chgerman\/wp-content\/uploads\/sites\/23\/2021\/10\/BFlex-1.png);\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-custom-embed-play\" role=\"button\" aria-label=\"Video abspielen\" tabindex=\"0\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-play\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-2fecd2f0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2fecd2f0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4496eaf2\" data-id=\"4496eaf2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ee5d244 elementor-widget elementor-widget-spacer\" data-id=\"1ee5d244\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-65b6c1dc elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"65b6c1dc\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-44240644\" data-id=\"44240644\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3f1850d elementor-widget elementor-widget-heading\" data-id=\"3f1850d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Unsere Unterkieferprotrusionsschienen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-bb72a2f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bb72a2f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b6880e9\" data-id=\"b6880e9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d3d85db elementor-widget elementor-widget-text-editor\" data-id=\"d3d85db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">F\u00fcr weitere Informationen klicken Sie bitte auf die folgenden Bilder\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-147aa39d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"147aa39d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-28f6814f\" data-id=\"28f6814f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1f0430 elementor-widget elementor-widget-spacer\" data-id=\"1f0430\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-5b8ab16 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5b8ab16\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-ae6193e\" data-id=\"ae6193e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6c9f991 elementor-cta--skin-cover elementor-cta--valign-middle elementor-bg-transform elementor-bg-transform-zoom-out elementor-animated-content elementor-widget elementor-widget-call-to-action\" data-id=\"6c9f991\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<a class=\"elementor-cta\" href=\"https:\/\/somnomed.com\/chgerman\/dentists\/products\/somnodent\/somnodent-avant\/\" target=\"_blank\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/somnomed.com\/chgerman\/wp-content\/uploads\/sites\/23\/2021\/07\/Image-for-website-19-1024x683.jpg);\" role=\"img\" aria-label=\"Somnodent Avant\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-content-item elementor-cta__content-item elementor-cta__image elementor-animated-item--grow\">\n\t\t\t\t\t\t<img decoding=\"async\" width=\"1000\" height=\"191\" src=\"https:\/\/somnomed.com\/chgerman\/wp-content\/uploads\/sites\/23\/2021\/07\/somnodent-avant-logo-full-color-rgb-1000px@72ppi1-1.png\" class=\"attachment-large size-large wp-image-5497\" alt=\"\" srcset=\"https:\/\/somnomed.com\/chgerman\/wp-content\/uploads\/sites\/23\/2021\/07\/somnodent-avant-logo-full-color-rgb-1000px@72ppi1-1.png 1000w, https:\/\/somnomed.com\/chgerman\/wp-content\/uploads\/sites\/23\/2021\/07\/somnodent-avant-logo-full-color-rgb-1000px@72ppi1-1-300x57.png 300w, https:\/\/somnomed.com\/chgerman\/wp-content\/uploads\/sites\/23\/2021\/07\/somnodent-avant-logo-full-color-rgb-1000px@72ppi1-1-768x147.png 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-73ae69b\" data-id=\"73ae69b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6905376 elementor-cta--skin-cover elementor-bg-transform elementor-bg-transform-zoom-out elementor-animated-content elementor-widget elementor-widget-call-to-action\" data-id=\"6905376\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<a class=\"elementor-cta\" href=\"https:\/\/somnomed.com\/chgerman\/dentists\/products\/somnodent\/somnodent-fusion\/\" target=\"_blank\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/somnomed.com\/chgerman\/wp-content\/uploads\/sites\/23\/2021\/07\/SomnoDent-Fusion-angle-product-image.jpg);\" role=\"img\" aria-label=\"SomnoDent Fusion angle product image\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-content-item elementor-cta__content-item elementor-cta__image elementor-animated-item--grow\">\n\t\t\t\t\t\t<img decoding=\"async\" width=\"1000\" height=\"185\" src=\"https:\/\/somnomed.com\/chgerman\/wp-content\/uploads\/sites\/23\/2021\/07\/somnodent-fusion-logo-full-color-rgb-1000px@72ppi-1.png\" class=\"attachment-full size-full wp-image-3977\" alt=\"\" srcset=\"https:\/\/somnomed.com\/chgerman\/wp-content\/uploads\/sites\/23\/2021\/07\/somnodent-fusion-logo-full-color-rgb-1000px@72ppi-1.png 1000w, https:\/\/somnomed.com\/chgerman\/wp-content\/uploads\/sites\/23\/2021\/07\/somnodent-fusion-logo-full-color-rgb-1000px@72ppi-1-300x56.png 300w, https:\/\/somnomed.com\/chgerman\/wp-content\/uploads\/sites\/23\/2021\/07\/somnodent-fusion-logo-full-color-rgb-1000px@72ppi-1-768x142.png 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7f5e914\" data-id=\"7f5e914\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-51e83d5 elementor-cta--skin-cover elementor-cta--valign-middle elementor-bg-transform elementor-bg-transform-zoom-out elementor-animated-content elementor-widget elementor-widget-call-to-action\" data-id=\"51e83d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/somnomed.com\/chgerman\/wp-content\/uploads\/sites\/23\/2021\/07\/SomnoDent-Flex-angle-product-image.jpg);\" role=\"img\" aria-label=\"SomnoDent Flex angle product image\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-content-item elementor-cta__content-item elementor-cta__image elementor-animated-item--grow\">\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"214\" src=\"https:\/\/somnomed.com\/chgerman\/wp-content\/uploads\/sites\/23\/2021\/07\/somnodent-flex-logo-full-color-rgb-1000px@72ppi-1.png\" class=\"attachment-full size-full wp-image-3952\" alt=\"\" srcset=\"https:\/\/somnomed.com\/chgerman\/wp-content\/uploads\/sites\/23\/2021\/07\/somnodent-flex-logo-full-color-rgb-1000px@72ppi-1.png 1000w, https:\/\/somnomed.com\/chgerman\/wp-content\/uploads\/sites\/23\/2021\/07\/somnodent-flex-logo-full-color-rgb-1000px@72ppi-1-300x64.png 300w, https:\/\/somnomed.com\/chgerman\/wp-content\/uploads\/sites\/23\/2021\/07\/somnodent-flex-logo-full-color-rgb-1000px@72ppi-1-768x164.png 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-3d106c2a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3d106c2a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1eb004ba\" data-id=\"1eb004ba\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-57e4dc9b elementor-widget elementor-widget-spacer\" data-id=\"57e4dc9b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-29e8180f elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"29e8180f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2bbcb61f\" data-id=\"2bbcb61f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1d94938e elementor-widget elementor-widget-image\" data-id=\"1d94938e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/somnomed.com\/chgerman\/wp-content\/uploads\/sites\/23\/elementor\/thumbs\/SomTabs-and-Products-USA-19-q2vmkw14aslqq4b3h6tglq0nymwhs2y1b7cnv4h5xc.jpg\" title=\"Patient holding SomnoDent Avant\" alt=\"Patient holding SomnoDent Avant image\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6d7c5782\" data-id=\"6d7c5782\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-53eaa4fc elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"53eaa4fc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-30c01cc4\" data-id=\"30c01cc4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-34d2cc92 elementor-widget elementor-widget-heading\" data-id=\"34d2cc92\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Weltweit f\u00fchrend in der Therapie mit Schlafapnoe-Schienen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6085688b elementor-widget elementor-widget-text-editor\" data-id=\"6085688b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Mehr als 1.000.000 Patienten mit SomnoDent-Schienen weltweit<\/strong><\/p><p>Basierend auf der urspr\u00fcnglichen Erfindung von Dr. Richard Palmisano fertigt SomnoMed Schlafapnoe-Schienen weltweit. Mit kontinuierlicher Verbesserung und wissenschaftlich validierten Ergebnissen hat sich SomnoMed zu einem der weltweit gr\u00f6ssten Unternehmen f\u00fcr Unterkieferprotrusionsschienen zur Behandlung obstruktiver Schlafapnoe entwickelt.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-4e9785 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4e9785\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-374a3113\" data-id=\"374a3113\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-59ae3318 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"59ae3318\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-1a119194\" data-id=\"1a119194\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-272ae203 elementor-widget elementor-widget-heading\" data-id=\"272ae203\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Weitere Informationen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-8ac227f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8ac227f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-4a9cac9b\" data-id=\"4a9cac9b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-7f7eb75e\" data-id=\"7f7eb75e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3987ce9a icon--hover elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"3987ce9a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/somnomed.com\/chgerman\/patients\/products\/somnodent\/somnodent-avant\/\" target=\"_blank\" class=\"elementor-icon\" tabindex=\"-1\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"142.915\" height=\"95.641\" viewBox=\"0 0 142.915 95.641\"><g transform=\"translate(-2.315 -31.259)\"><path d=\"M144.018,70.409c-.163-.244-.326-.407-.489-.652a2.07,2.07,0,0,0-2.852-.9c-2.363,1.222-4.808,2.119-7.171,3.26a3.662,3.662,0,0,0-1.793,1.711c-.163.326-.244.652-.652.652-1.874.163-3.667-.163-4.4-2.2-.244-.733-.57-1.548-.815-2.282a2.266,2.266,0,0,0-1.956-1.63,16.315,16.315,0,0,1-1.956-.326c-1.956-.407-3.83-.9-5.786-1.3a5.433,5.433,0,0,0-4.482.733,8.358,8.358,0,0,0-2.282,2.2,2,2,0,0,1-1.956.9c-1.059-.163-2.119-.326-3.178-.57-3.341-.407-6.682-.733-10.024-.815a3.34,3.34,0,0,0-2.282.733,13.386,13.386,0,0,0-2.363,2.445,2.794,2.794,0,0,1-3.015,1.3,48.07,48.07,0,0,0-6.845-.244,6.147,6.147,0,0,0-4.727,2.526,3.384,3.384,0,0,1-3.586,1.222,30.935,30.935,0,0,0-7.253-.815h-13.2a13.338,13.338,0,0,1-3.1-.326c-1.059-.244-1.222-.57-.57-1.467a3.764,3.764,0,0,1,.57-.57,5.617,5.617,0,0,0,1.711-1.956c.57-1.222,1.059-2.526,1.63-3.749a5.193,5.193,0,0,0,.081-4.89,2.041,2.041,0,0,1,.733-2.689,7.551,7.551,0,0,0,1.141-1.141c1.956-2.282,3.423-4.808,5.216-7.171.9-1.222,1.874-2.445,2.771-3.667a1.478,1.478,0,0,0,.081-1.874,13.006,13.006,0,0,0-2.282-2.852,3.425,3.425,0,0,0-3.749-.978,1.131,1.131,0,0,1-1.385-.326,5.611,5.611,0,0,1-.9-1.059,21.431,21.431,0,0,0-3.26-3.423,21.759,21.759,0,0,1-3.83-3.912,13.348,13.348,0,0,0-1.711-2.037,3.215,3.215,0,0,0-3.83-.652c-1.793.815-2.363,2.445-2.934,4.075-.407,1.385-.407,1.385-1.874,1.3a1.794,1.794,0,0,0-.652.081c-1.141.326-2.363.57-3.423.978-2.2.815-3.912,2.119-4.238,4.645a5.647,5.647,0,0,0-.244,1.63c0,.9-.57,1.141-1.3,1.059a13.175,13.175,0,0,0-3.1-.163,4.084,4.084,0,0,0-3.749,3.586,1.055,1.055,0,0,1-.815,1.059,5.942,5.942,0,0,0-3.5,5.216,13.163,13.163,0,0,1,0,1.793.958.958,0,0,1-1.467.9,1.122,1.122,0,0,0-1.3.407,4.918,4.918,0,0,0-1.059,4.238,3.378,3.378,0,0,1,.244,1.3,10.627,10.627,0,0,0,.163,3.586l-.326.081c-2.526.815-9.127,6.03-8.312,12.957.407,3.423,1.711,5.3,4.645,7.09A4.71,4.71,0,0,0,6.3,93.39,2.133,2.133,0,0,1,6.7,94.775c-.407,2.037.163,4.075.326,6.03A5.089,5.089,0,0,0,9.637,104.8c1.3.815,1.467.815,2.282-.57.407-.733.733-.652,1.222-.081a13.128,13.128,0,0,0,3.667,3.341,12.1,12.1,0,0,1,3.26,2.526,5.973,5.973,0,0,0,5.7,1.793,5.939,5.939,0,0,1,2.934.244,29.959,29.959,0,0,0,3.83,1.222,46.141,46.141,0,0,1,7.334,2.608c2.363.9,4.727,1.548,7.171.9a8.881,8.881,0,0,1,5.053.244c2.608.815,5.379,1.385,7.5,3.26a9.433,9.433,0,0,0,3.26,1.63,12.735,12.735,0,0,1,4.727,2.282,10.815,10.815,0,0,0,4.808,2.445,4.334,4.334,0,0,0,3.341-.163,23.049,23.049,0,0,0,3.83-2.363,3.567,3.567,0,0,1,4.156-.407l1.3.652c1.793.733,3.586,1.548,5.541,1.141a12.99,12.99,0,0,0,5.379-2.2c1.711-1.3,3.5-2.445,5.3-3.749a5.042,5.042,0,0,1,4.156-.978,20.37,20.37,0,0,0,2.363.407c1.711.244,3.5.489,5.134-.326a50.434,50.434,0,0,0,4.727-2.282,14.158,14.158,0,0,0,3.178.407c4.238,0,7.5-2.526,9.127-7.171.163-.407.244-.9.407-1.3a5.927,5.927,0,0,0,3.586-3.912,8.818,8.818,0,0,0,.244-3.586c-.407-2.445-.407-5.134-1.874-7.253-.978-1.548-.733-2.363.326-3.667,1.793-2.119,3.341-4.564,5.7-6.275a18.928,18.928,0,0,0,6.275-8.231,3.868,3.868,0,0,0-.57-4.971ZM120.874,114.5a10.322,10.322,0,0,1-3.83-.733c-5.46-1.956-11.327-5.7-18.825-6.275-7.5-.489-43.11-.9-73.262-14.506-11-4.89-16.054-6.6-18.336-8.8A7.073,7.073,0,0,1,4.911,79.7c-.163-3.178,1.548-5.46,3.5-7.579A7.875,7.875,0,0,1,11.1,70.164a1.125,1.125,0,0,0,.326-.244c.081,0,.163-.081.244-.081a25.654,25.654,0,0,1,.407,3.5s-4.319,4.319-3.26,7.171S38.241,94.368,44.516,96.16C57.636,99.909,85.1,104.473,97,104.473a32.826,32.826,0,0,0,3.993-.244c6.845-1.3,13.12-4.645,18.173-4.645a8.6,8.6,0,0,1,2.526.326c5.46,1.548,7.5,4.4,5.867,9.209a8.426,8.426,0,0,1-3.667,4.808,7.34,7.34,0,0,1-2.282.652h-.081A1.589,1.589,0,0,0,120.874,114.5Z\" transform=\"translate(0 0)\" fill=\"#65cbe0\"><\/path><path d=\"M151.122,122.9a3.161,3.161,0,0,0-6.322-.069,3.114,3.114,0,0,0,3.126,3.127A3.031,3.031,0,0,0,151.122,122.9Z\" transform=\"translate(-22.419 -15.485)\" fill=\"#65cbe0\"><\/path><\/g><\/svg>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tWeitere Informationen \u00fcber unsere bisher komfortabelste Schiene, die SomnoDent Avant<sup>\u00ae<\/sup>, finden SIe unter folgendem Link\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-5f519d8e\" data-id=\"5f519d8e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c801f57 icon--hover elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"c801f57\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/somnomed.com\/chgerman\/contact\/\" target=\"_blank\" class=\"elementor-icon\" tabindex=\"-1\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-comment\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tKontaktieren Sie uns f\u00fcr weitere Informationen\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-35f3cdcf\" data-id=\"35f3cdcf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-76eeaac2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"76eeaac2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-361d3ec2\" data-id=\"361d3ec2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7306e922 elementor-widget elementor-widget-spacer\" data-id=\"7306e922\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-1165c67f elementor-section-content-middle elementor-section-full_width elementor-reverse-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"1165c67f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6b1674d4 padding-col--left\" data-id=\"6b1674d4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-3fb89917 elementor-section-full_width elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"3fb89917\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-7fcf492c\" data-id=\"7fcf492c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-287fd166 elementor-widget elementor-widget-heading\" data-id=\"287fd166\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/vimeo.com\/573281862\" target=\"_blank\" rel=\"noopener\">Was berichten SomnoMed<sup>\u00ae<\/sup> Patienten?<\/a><\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-158e2971 elementor-widget elementor-widget-text-editor\" data-id=\"158e2971\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #00549d;\"><strong>Jeder Patient ist unterschiedlich und wir haben schon viele auf ihrem Weg zu einer effektiven Behandlung begleitet.<\/strong><\/span><\/p><p>Sehen Sie ihre Geschichte und wie die SomnoDent<sup>\u00ae<\/sup>\u00a0Protrusionsschiene ihnen geholfen hat.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-781d77b1\" data-id=\"781d77b1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5e90b9be elementor-invisible elementor-widget elementor-widget-video\" data-id=\"5e90b9be\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;lazy_load&quot;:&quot;yes&quot;,&quot;show_image_overlay&quot;:&quot;yes&quot;,&quot;image_overlay&quot;:{&quot;url&quot;:&quot;http:\\\/\\\/somnomed.co\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/06\\\/Image-for-website-20.jpg&quot;,&quot;id&quot;:&quot;5666&quot;,&quot;size&quot;:&quot;&quot;},&quot;video_type&quot;:&quot;vimeo&quot;,&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<iframe class=\"elementor-video-iframe\" allowfullscreen allow=\"clipboard-write\" title=\"vimeo Video Player\" data-lazy-load=\"https:\/\/player.vimeo.com\/video\/213864189?color&amp;autopause=0&amp;loop=0&amp;muted=0&amp;title=0&amp;portrait=0&amp;byline=0#t=\"><\/iframe>\t\t\t\t<div class=\"elementor-custom-embed-image-overlay\" style=\"background-image: url(https:\/\/somnomed.com\/chgerman\/wp-content\/uploads\/sites\/23\/2021\/06\/Image-for-website-20.jpg);\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-2f7482ca elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"2f7482ca\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1a857613\" data-id=\"1a857613\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-24f50be5 elementor-widget elementor-widget-heading\" data-id=\"24f50be5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Patientenerfahrungen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-54d57514 elementor-widget elementor-widget-Custom_El_Slider_Text\" data-id=\"54d57514\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"Custom_El_Slider_Text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t          <div id=\"el-slider-text-6a04b90cd7cf9\" class=\"el-slider-text\">\r\n        <div class=\"el-slider-text__slider\">\r\n                      <div class=\"el-slider-text__slide\">\r\n              <div class=\"el-slider-text__slide-inner balance-elements\" style=\"background-color: #C3E7EF; color: #000000; \">\r\n                <h3><b>Man sp\u00fcrt sie kaum<\/b><\/h3>\n<p>Ich habe die SomnoDent-Schiene seit einem halben Jahr und muss sagen, dass es mir dank dieser Schiene wesentlich besser geht. Es sind noch nicht alle Probleme beseitig, da sich mein K\u00f6rper durch jahrelange Ersch\u00f6pfung erst so langsam erholt. Ich kann jedem diese Schiene empfehlen, der nicht mit eine Maske leben m\u00f6chte. Die Schiene ist so leicht zu tragen und man sp\u00fcrt sie kaum. Ich kann es nicht anders ausdr\u00fccken, die SomnoDent-Schiene ist mein Lebensretter. Hoffe, ich kann vielen Menschen, die an Schlafapnoe leiden, durch meine positive Erfahrung weiterhelfen.<\/p>\n<p style=\"text-align: right;\"><strong>- Matthias<\/strong><\/p>\n              <\/div>\r\n            <\/div>\r\n                      <div class=\"el-slider-text__slide\">\r\n              <div class=\"el-slider-text__slide-inner balance-elements\" style=\"background-color: #C1CAE3; color: #000000; \">\r\n                <h3><b>Ich habe mein Leben zur\u00fcck<\/b><\/h3>\n<p>Ich habe mein Leben zur\u00fcck, dank SomnoDent<sup>\u00ae<\/sup>! Jetzt habe ich wieder die grenzenlose Energie, wie ich sie als Teenager hatte, bevor ich die Schlafapnoe bekam. Ich stehe fr\u00fch auf, gehe sp\u00e4t ins Bett, bin mit 51 in ein Sportstudio eingetreten (ich war nie zuvor in einem Sportstudio) und f\u00fchle mich zu 100 % voller Energie!<\/p>\n<p style=\"text-align: right;\"><strong>- Tjark<\/strong><\/p>\n              <\/div>\r\n            <\/div>\r\n                      <div class=\"el-slider-text__slide\">\r\n              <div class=\"el-slider-text__slide-inner balance-elements\" style=\"background-color: #00549D; color: #ffffff; \">\r\n                <h3><b>Keine Druckstellen<\/b><\/h3>\n<p>Der Tragekomfort der SomnoDent ist phantastisch! 100%ige Passgenauigkeit,<br \/>keine Reibungs- oder Druckpunkte an den \u00dcberg\u00e4ngen zum Zahnfleisch. Damit hatte ich immer wieder Probleme bei der meiner Schiene und musste diese mehrmals neu anpassen.<\/p>\n<p style=\"text-align: right;\"><strong>- Gaby<\/strong><\/p>\n              <\/div>\r\n            <\/div>\r\n                      <div class=\"el-slider-text__slide\">\r\n              <div class=\"el-slider-text__slide-inner balance-elements\" style=\"background-color: #7B91C4; color: #FFFFFF; \">\r\n                <h3><b>Mein Mann ist wieder fit<\/b><\/h3>\n<p>Mein Mann hatte mit der SomnoDent Schiene nur noch einen AHI von 6,6\/h. Mit der Schiene kommt er super klar. Er tr\u00e4gt sie jede Nacht w\u00e4hrend der kompletten Schlafzeit ohne Probleme. Nach vielen Jahren ist er dank der SomnoDent<sup>\u00ae<\/sup>-Schiene zum ersten Mal wieder so fit und gut drauf wie vor zehn Jahren, als ich ihn kennengelernt hatte.<\/p>\n<p style=\"text-align: right;\"><strong>- Mirja<\/strong><\/p>\n              <\/div>\r\n            <\/div>\r\n                      <div class=\"el-slider-text__slide\">\r\n              <div class=\"el-slider-text__slide-inner balance-elements\" style=\"background-color: #5175B3; color: #ffffff; \">\r\n                <h3><b>Wie ein neuer Mensch<\/b><\/h3>\n<p>Seit ich sie benutze f\u00fchle ich mich wieder wie ein vollst\u00e4ndiger Mensch. Ich w\u00fcrde sie jedem empfehlen, der an Schlafapnoe leidet. Sie ist einfach klasse.<\/p>\n<p style=\"text-align: right;\"><strong>- Volker<\/strong><\/p>\n              <\/div>\r\n            <\/div>\r\n                  <\/div>\r\n      <\/div>\r\n\r\n      <script>\r\n        jQuery(document).ready(function($) {\r\n          $('#el-slider-text-6a04b90cd7cf9 .el-slider-text__slider').slick({\r\n            centerMode: true,\r\n            centerPadding: '300px',\r\n            slidesToShow: 2,\r\n            arrows: true,\r\n            dots: false,\r\n            infinite: true,\r\n            responsive: [\r\n              {\r\n                breakpoint: 1600,\r\n                settings: {\r\n                  arrows: false,\r\n                  dots: true,\r\n                  centerPadding: '150px',\r\n                  slidesToShow: 2\r\n                }\r\n              },\r\n              {\r\n                breakpoint: 768,\r\n                settings: {\r\n                  arrows: false,\r\n                  dots: true,\r\n                  centerPadding: '5px',\r\n                  slidesToShow: 1\r\n                }\r\n              }\r\n            ]\r\n          });\r\n        });\r\n      <\/script>\r\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>SomnoDent\u00ae-Schienen Kein Patient gleicht dem anderen. Deshalb hat SomnoMed\u00ae\u00a0unterschiedliche Unterkieferprotrusionsschienen mit einer breiten Palette an Optionen zur Behandlung von Patienten mit obstruktiver Schlafapnoe (OSA) zur Auswahl. SomnoMed\u00a0hat die SomnoDent-Familie entwickelt \u2013 klinisch bew\u00e4hrte Unterkieferprotrusionsschienen \u2013 die innovative Technologie nutzen. In unseren hochmodernen, nach ISO 13485 zertifizierten Einrichtungen arbeiten qualifizierte Spezialisten von SomnoMed mit gr\u00f6sster Sorgfalt, &#8230;<\/p>\n","protected":false},"author":96,"featured_media":0,"parent":3517,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-3540","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/somnomed.com\/chgerman\/wp-json\/wp\/v2\/pages\/3540","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/somnomed.com\/chgerman\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/somnomed.com\/chgerman\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/somnomed.com\/chgerman\/wp-json\/wp\/v2\/users\/96"}],"replies":[{"embeddable":true,"href":"https:\/\/somnomed.com\/chgerman\/wp-json\/wp\/v2\/comments?post=3540"}],"version-history":[{"count":3,"href":"https:\/\/somnomed.com\/chgerman\/wp-json\/wp\/v2\/pages\/3540\/revisions"}],"predecessor-version":[{"id":16658,"href":"https:\/\/somnomed.com\/chgerman\/wp-json\/wp\/v2\/pages\/3540\/revisions\/16658"}],"up":[{"embeddable":true,"href":"https:\/\/somnomed.com\/chgerman\/wp-json\/wp\/v2\/pages\/3517"}],"wp:attachment":[{"href":"https:\/\/somnomed.com\/chgerman\/wp-json\/wp\/v2\/media?parent=3540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}