{"id":235,"date":"2021-06-08T03:40:47","date_gmt":"2021-06-08T07:40:47","guid":{"rendered":"https:\/\/local.somnomed.com\/en\/?page_id=235"},"modified":"2025-11-13T11:00:55","modified_gmt":"2025-11-13T10:00:55","slug":"effective-cpap-alternative","status":"publish","type":"page","link":"https:\/\/somnomed.com\/de\/patients\/effective-cpap-alternative\/","title":{"rendered":"Effective CPAP Alternative"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"235\" class=\"elementor elementor-235\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-0c9a6ba elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0c9a6ba\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ac42efd\" data-id=\"ac42efd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4385a54 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"4385a54\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/somnomed.com\/de\/wp-content\/uploads\/sites\/8\/elementor\/thumbs\/item_22728-qo5361ybjzwkqotfsar2j0qx5bs02jibjhn7dolt94.jpg\" title=\"Wie die Schlafapnoe Ihres Partners Sie und Ihr Leben beeintr\u00e4chtigen kann\" alt=\"Ein im Bett liegendes Paar, von dem Einer an Schlafapnoe leidet\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-548d356\" data-id=\"548d356\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-31738dc elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"31738dc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-b304dcd\" data-id=\"b304dcd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-95f79c2 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"95f79c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Therapie von Schlafapnoe mit SomnoDent<sup>\u00ae<\/sup>-Schienen<br><\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-02ac1c4 elementor-widget elementor-widget-text-editor\" data-id=\"02ac1c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #00549d;\"><strong>Bei leichter oder mittelschwere obstruktiver Schlafapnoe (OSA) kann die Therapie mit einer SomnoDent-Schiene genauso effektiv sein wie mit einer CPAP-Maske. Die CPAP-Therapie ist eine sehr wirksame Behandlungsmethode f\u00fcr OSA \u2013 aber nur, wenn das Ger\u00e4t jede Nacht genutzt wird.<br \/><\/strong><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0d14b93 elementor-widget elementor-widget-text-editor\" data-id=\"0d14b93\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Vieles am CPAP-Ger\u00e4t behindert einen guten Schlaf: Sie sind an einen Schlauch angeschlossen, der Sie nachts am Umdrehen hindern kann. CPAP-Ger\u00e4te k\u00f6nnen laut sein und Sie und Ihren Partner wachhalten. Und es ist unangenehm, eine Maske zu tragen, w\u00e4hrend Sie versuchen, einzuschlafen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-78241ff4 elementor-section-content-middle elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"78241ff4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-55c6242b\" data-id=\"55c6242b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-32f5ca06 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"32f5ca06\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-6437bda\" data-id=\"6437bda\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-53a3d7bb elementor-widget elementor-widget-text-editor\" data-id=\"53a3d7bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wenn Sie eine CPAP-Therapie ausprobiert haben und diese nicht mehr weiter machen oder Sie sich direkt entschieden haben, dass CPAP nichts f\u00fcr Sie ist, sind Sie nicht allein.<\/p>\n<p>Klinische Studien haben gezeigt, dass sich bis zu 20 % der OSA-Patienten entschieden haben, keine<\/p>\n<p>CPAP-Therapie zu beginnen. Und bis zu 50 % der CPAP-Patienten haben die Anwendung innerhalb eines Jahres abgebrochen.<\/p>\n<p>Es ist aber wichtig, dass Sie Ihre OSA behandeln. Eine Schlafapnoe-Schiene, die genau auf Ihre Z\u00e4hne angepasst ist, kann Ihnen helfen, bequem zu schlafen. Keine Maske, kein Ger\u00e4usch, kein Schlauch und kein Ger\u00e4t zum Anschlie\u00dfen.<\/p>\n<p>Sprechen Sie mit Ihrem Schlafmediziner oder Zahnarzt \u00fcber SomnoDent Schlafapnoe-Schienen zur Behandlung Ihrer obstruktiven Schlafapnoe.&nbsp;<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-256727f elementor-widget elementor-widget-button\" data-id=\"256727f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/staging.somnomed.com\/au\/wp-content\/uploads\/sites\/4\/2021\/08\/somnomed_ebook_Australia.pdf\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Download a copy of our sleep apnea booklet<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-589816f3\" data-id=\"589816f3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-37793b43 elementor-widget elementor-widget-image\" data-id=\"37793b43\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/somnomed.com\/de\/wp-content\/uploads\/sites\/8\/elementor\/thumbs\/Man-Sleeping-With-CPAP-Mask-qo57rrvyhgrhnq3l3fk5mp9jhwyo5genzqa0cww28o.jpg\" title=\"Ist CPAP die einzige Behandlung f\u00fcr Schlafapnoe?\" alt=\"Ein Mann, der w\u00e4hrend seines Schlafes ein CPAP-Ger\u00e4t zur Behandlung von Schlafapnoe benutzt.\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-742e4b4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"742e4b4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-459879d\" data-id=\"459879d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9bb7975 elementor-widget elementor-widget-image\" data-id=\"9bb7975\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"860\" src=\"https:\/\/somnomed.com\/de\/wp-content\/uploads\/sites\/8\/2024\/05\/patients-around-the-world-768x860.png\" class=\"attachment-medium_large size-medium_large wp-image-15245\" alt=\"SomnoMed behandelt weltweit Schlafapnoe-Patienten.\" srcset=\"https:\/\/somnomed.com\/de\/wp-content\/uploads\/sites\/8\/2024\/05\/patients-around-the-world-768x860.png 768w, https:\/\/somnomed.com\/de\/wp-content\/uploads\/sites\/8\/2024\/05\/patients-around-the-world-268x300.png 268w, https:\/\/somnomed.com\/de\/wp-content\/uploads\/sites\/8\/2024\/05\/patients-around-the-world.png 825w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-cebaf22\" data-id=\"cebaf22\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d880af1 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"d880af1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><br><br><br>Warum sollte ich SomnoMed<sup>\u00ae<\/sup>bei der Behandlung meiner Schlafapnoe vertrauen?<br><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6fc114f elementor-widget elementor-widget-text-editor\" data-id=\"6fc114f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>SomnoMed ist der weltweit gr\u00f6\u00dfte Anbieter von Schlafapnoe-Schienen und in 28 L\u00e4ndern vertreten. Seit 2004 haben wir mehr als 1.000.000 Patienten zu einem komfortablen Schlaf verholfen und ihre obstruktive Schlafapnoe effektiv behandelt.<\/p><p>Wir fertigen Ihre Schlafapnoe-Schiene nach denselben Qualit\u00e4tsstandards f\u00fcr medizinische Ger\u00e4te, die auch f\u00fcr Herzschrittmacher verwendet werden, und stellen sicher, dass Ihre Schiene f\u00fcr Ihre erste Nacht \u2013 und jede weitere Nacht \u2013 komfortabel ist.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-c28556f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c28556f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f78a742\" data-id=\"f78a742\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-92c6ad4 elementor-widget elementor-widget-Custom_El_Slider_Vertical\" data-id=\"92c6ad4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"Custom_El_Slider_Vertical.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t      <div id=\"el-slider-vertical-6a049e5532338\" class=\"el-slider-vertical\">\r\n        <div class=\"row align-items-center flex-row-reverse\">\r\n          <div class=\"col-xl-6 ps-xl-5\">\r\n            <div class=\"el-slider-vertical__images\">\r\n                                                <div class=\"el-slider-vertical__image bg-center\" style=\"background-image:url('https:\/\/somnomed.com\/de\/wp-content\/uploads\/sites\/8\/2021\/06\/Manfacturing-small-file.jpg')\"><\/div>\r\n                                                                <div class=\"el-slider-vertical__image bg-center\" style=\"background-image:url('https:\/\/somnomed.com\/de\/wp-content\/uploads\/sites\/8\/2024\/05\/SomTabs-Web--1024x1024.jpg')\"><\/div>\r\n                                                                <div class=\"el-slider-vertical__image bg-center\" style=\"background-image:url('https:\/\/somnomed.com\/de\/wp-content\/uploads\/sites\/8\/2024\/06\/DE-2.jpg')\"><\/div>\r\n                                                                <div class=\"el-slider-vertical__image bg-center\" style=\"background-image:url('https:\/\/somnomed.com\/de\/wp-content\/uploads\/sites\/8\/2021\/06\/WorldMapwithlinkedbylines.jpg')\"><\/div>\r\n                                          <\/div>\r\n          <\/div>\r\n\r\n          <div class=\"col-xl-6\">\r\n            <div class=\"row g-0 align-items-center flex-row-reverse\">\r\n              <div class=\"col-xl-4 text-center\">\r\n                                  <div class=\"el-slider-vertical__nav d-flex flex-wrap flex-xl-column py-4 align-items-center justify-content-center\">\r\n                    <a href=\"#\" class=\"el-slider-vertical__nav--prev px-3\">\r\n                      <img decoding=\"async\" src=\"https:\/\/somnomed.com\/de\/wp-content\/themes\/somnomed-2021\/assets\/images\/chev-up.svg\" alt=\"Arrow\" class=\"img-fluid\" width=\"30\">\r\n                    <\/a>\r\n\r\n                    <span class=\"el-slider-vertical__nav--current\">01<\/span>\r\n\r\n                    <a href=\"#\" class=\"el-slider-vertical__nav--next px-3\">\r\n                      <img decoding=\"async\" src=\"https:\/\/somnomed.com\/de\/wp-content\/themes\/somnomed-2021\/assets\/images\/chev-down.svg\" alt=\"Arrow\" class=\"img-fluid\" width=\"30\">\r\n                    <\/a>\r\n                  <\/div>\r\n                              <\/div>\r\n\r\n              <div class=\"col-xl-8\">\r\n                                  <h2 class=\"mb-4\">Gr\u00fcnde warum SomnoMed Branchenf\u00fchrer ist<\/h2>\r\n                \r\n                <div class=\"el-slider-vertical__content\">\r\n                                      <div class=\"el-slider-vertical__content-inner\">\r\n                      <p><span style=\"color: #00549d;\"><strong>Modernste\u00a0 Technologie<\/strong><\/span><\/p>\n<p>Wir nutzen neueste Technologie - computergest\u00fctztes Design und robotergesteuerte Fertigung in Verbindung mit medizinischen Materialien - um sicherzustellen, dass Ihre Schiene perfekt sitzt.<\/p>\n<p>Scrollen Sie durch weitere Gr\u00fcnde, warum SomnoMed Branchenf\u00fchrer ist, indem Sie rechts auf die Pfeile klicken. \u00a0<\/p>\n\r\n                                          <\/div>\r\n                                      <div class=\"el-slider-vertical__content-inner\">\r\n                      <p><span style=\"color: #00549d;\"><strong>Wir helfen Schlafapnoe-Patienten weltweit<\/strong><\/span><\/p>\n<p>We have teams in 28 countries - working with doctors and dentists to help them customize your device, so it fits<\/p>\n<p>So stellen wir sicher, dass Ihre Schiene in der ersten Nacht -\u00a0 und jeder weiteren Nacht \u2013 komfortabel ist.<\/p>\n\r\n                                          <\/div>\r\n                                      <div class=\"el-slider-vertical__content-inner\">\r\n                      <p><span style=\"color: #00549d;\"><strong>b-flex Comfort Liner - F\u00fcr einen angenehmen Schlaf\u00a0<\/strong><\/span><\/p>\n<p>Die von SomnoMed entwickelte b-flex Comfort Liner<sup>\u00ae<\/sup> Soft-Innenschicht st\u00fctzt und polstert die Z\u00e4hne und bewirkt einen hohen Tragekomfort der Schiene, so dass Sie sie bequem die ganze Nacht tragen k\u00f6nnen.\u00a0<\/p>\n\r\n                                          <\/div>\r\n                                      <div class=\"el-slider-vertical__content-inner\">\r\n                      <p><span style=\"color: #00549d;\"><strong>Globales Kompetenzzentrum f\u00fcr die Fertigung<\/strong><\/span><\/p>\n<p>SomnoMed besch\u00e4ftigt mehr als 480 Mitarbeiter in unserer zentralisierten Hightech-Produktionsst\u00e4tte, um personalisierte Schlafapnoe-Schienen passgenau f\u00fcr Sie zu fertigen. Wir haben bereits \u00fcber 1.000.000 Schienen gefertigt und arbeiten jeden Tag daran, sie noch komfortabler zu machen.<\/p>\n\r\n                                          <\/div>\r\n                                  <\/div>\r\n              <\/div>\r\n            <\/div>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n\r\n      <script>\r\n        jQuery(document).ready(function($) {\r\n          $('#el-slider-vertical-6a049e5532338 .el-slider-vertical__images').slick({\r\n            slidesToShow: 1,\r\n            slidesToScroll: 1,\r\n            arrows: false,\r\n            dots: false,\r\n            fade: true,\r\n            asNavFor: '#el-slider-vertical-6a049e5532338 .el-slider-vertical__content',\r\n            responsive: [\r\n              {\r\n                breakpoint: 1200,\r\n                settings: {\r\n                  fade: false,\r\n                }\r\n              }\r\n            ]\r\n          });\r\n\r\n          $('#el-slider-vertical-6a049e5532338 .el-slider-vertical__content').slick({\r\n            slidesToShow: 1,\r\n            slidesToScroll: 1,\r\n            asNavFor: '#el-slider-vertical-6a049e5532338 .el-slider-vertical__images',\r\n            prevArrow: '#el-slider-vertical-6a049e5532338 .el-slider-vertical__nav--prev',\r\n            nextArrow: '#el-slider-vertical-6a049e5532338 .el-slider-vertical__nav--next',\r\n            arrows: true,\r\n            fade: true,\r\n            dots: false,\r\n            responsive: [\r\n              {\r\n                breakpoint: 1200,\r\n                settings: {\r\n                  adaptiveHeight: true,\r\n                  fade: false,\r\n                }\r\n              }\r\n            ]\r\n          });\r\n\r\n          $('#el-slider-vertical-6a049e5532338 .el-slider-vertical__content').on('beforeChange', function(event, slick, currentSlide, nextSlide) {\r\n            $('#el-slider-vertical-6a049e5532338 .el-slider-vertical__nav--current').text('0' + (nextSlide + 1));\r\n          });\r\n        });\r\n      <\/script>\r\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-9936260 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9936260\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-905d599\" data-id=\"905d599\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-30c04e92 elementor-widget__width-initial e-transform elementor-widget elementor-widget-image\" data-id=\"30c04e92\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_rotateZ_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_tablet&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_mobile&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/somnomed.com\/de\/wp-content\/uploads\/sites\/8\/elementor\/thumbs\/Woman-patient-holding-SomnoDent-Avant-with-box-scaled-qo55snflcrda8qq7qjfhwfpwkmmf663h0q7p19aiyw.jpg\" title=\"SomnoMed Schiene\" alt=\"Patentierte und auf den Patienten angepasste SomnoMed Zahnschienen f\u00fcr die Behandlung von Schlafapnoe\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5fa1dac\" data-id=\"5fa1dac\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-46090f6 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"46090f6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-ed80d3e\" data-id=\"ed80d3e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6fce538 elementor-widget elementor-widget-heading\" data-id=\"6fce538\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Warum muss meine Schlafapnoe-Schiene individuell angefertigt werden?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a7384c4 elementor-widget elementor-widget-text-editor\" data-id=\"a7384c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Der Schl\u00fcssel zu gutem Schlaf ist eine komfortable, gutsitzende Schiene.<\/p><p>Es gibt sehr g\u00fcnstige \u201eBoil and Bite\u201c Schienen zu kaufen, die man zuhause im Wasserbad erhitzt und dann durch Draufbei\u00dfen an die Z\u00e4hne anpasst.<\/p><p>Studien zeigen, dass diese aber weniger effektiv sind. Sie sind unbequem und werden seltener getragen als die SomnoDent-Schienen, die f\u00fcr Ihre Z\u00e4hne individuell angefertigt sind.<\/p><p>Sehen Sie einen <a href=\"https:\/\/www.youtube.com\/watch?v=2pDtboiPYCI\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\"><span style=\"color: #00549d; text-decoration: underline;\"><em><strong> Bericht zu, Boil and Bite-Schienen<\/strong><\/em><\/span><\/span><\/a>\u00a0von HNO-Chirurg Dr. Vik Veer (in Englisch)<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-1f88c97 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1f88c97\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9556dac\" data-id=\"9556dac\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1d21ab2 elementor-widget elementor-widget-heading\" data-id=\"1d21ab2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Warum sollte ich vom Zahnarzt eine individuell angefertigte Schiene anpassen lassen?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-839329e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"839329e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4e26ffa\" data-id=\"4e26ffa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-80d1c33 elementor-widget elementor-widget-text-editor\" data-id=\"80d1c33\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>G\u00fcnstige Schienen, wie sie z.B. im Internet erh\u00e4ltlich sind, werden allgemein als \u201eBoil-and-Bite\u201c-Schienen bezeichnet. Diese werden in kochendes Wasser geben, um das Plastik weich zu machen. Danach bei\u00dft man hinein, um sie an die Z\u00e4hne anzupassen.<\/p><p>Klinische Studien haben jedoch gezeigt, dass individuell angefertigte Schienen, die speziell f\u00fcr Ihre Z\u00e4hne hergestellt werden, den \u201eBoil-and-Bite\u201c-Schienen deutlich \u00fcberlegen sind.<\/p><p>Unten finden Sie eine Zusammenfassung der klinischen Studien.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-5050560 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5050560\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d7f62b8\" data-id=\"d7f62b8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-cbb52a9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cbb52a9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-dcfc8f2\" data-id=\"dcfc8f2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-31efcc5 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"31efcc5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"142.915\" height=\"95.641\" viewBox=\"0 0 142.915 95.641\"><g transform=\"translate(-2.315 -31.259)\"><path d=\"M144.018,70.409c-.163-.244-.326-.407-.489-.652a2.07,2.07,0,0,0-2.852-.9c-2.363,1.222-4.808,2.119-7.171,3.26a3.662,3.662,0,0,0-1.793,1.711c-.163.326-.244.652-.652.652-1.874.163-3.667-.163-4.4-2.2-.244-.733-.57-1.548-.815-2.282a2.266,2.266,0,0,0-1.956-1.63,16.315,16.315,0,0,1-1.956-.326c-1.956-.407-3.83-.9-5.786-1.3a5.433,5.433,0,0,0-4.482.733,8.358,8.358,0,0,0-2.282,2.2,2,2,0,0,1-1.956.9c-1.059-.163-2.119-.326-3.178-.57-3.341-.407-6.682-.733-10.024-.815a3.34,3.34,0,0,0-2.282.733,13.386,13.386,0,0,0-2.363,2.445,2.794,2.794,0,0,1-3.015,1.3,48.07,48.07,0,0,0-6.845-.244,6.147,6.147,0,0,0-4.727,2.526,3.384,3.384,0,0,1-3.586,1.222,30.935,30.935,0,0,0-7.253-.815h-13.2a13.338,13.338,0,0,1-3.1-.326c-1.059-.244-1.222-.57-.57-1.467a3.764,3.764,0,0,1,.57-.57,5.617,5.617,0,0,0,1.711-1.956c.57-1.222,1.059-2.526,1.63-3.749a5.193,5.193,0,0,0,.081-4.89,2.041,2.041,0,0,1,.733-2.689,7.551,7.551,0,0,0,1.141-1.141c1.956-2.282,3.423-4.808,5.216-7.171.9-1.222,1.874-2.445,2.771-3.667a1.478,1.478,0,0,0,.081-1.874,13.006,13.006,0,0,0-2.282-2.852,3.425,3.425,0,0,0-3.749-.978,1.131,1.131,0,0,1-1.385-.326,5.611,5.611,0,0,1-.9-1.059,21.431,21.431,0,0,0-3.26-3.423,21.759,21.759,0,0,1-3.83-3.912,13.348,13.348,0,0,0-1.711-2.037,3.215,3.215,0,0,0-3.83-.652c-1.793.815-2.363,2.445-2.934,4.075-.407,1.385-.407,1.385-1.874,1.3a1.794,1.794,0,0,0-.652.081c-1.141.326-2.363.57-3.423.978-2.2.815-3.912,2.119-4.238,4.645a5.647,5.647,0,0,0-.244,1.63c0,.9-.57,1.141-1.3,1.059a13.175,13.175,0,0,0-3.1-.163,4.084,4.084,0,0,0-3.749,3.586,1.055,1.055,0,0,1-.815,1.059,5.942,5.942,0,0,0-3.5,5.216,13.163,13.163,0,0,1,0,1.793.958.958,0,0,1-1.467.9,1.122,1.122,0,0,0-1.3.407,4.918,4.918,0,0,0-1.059,4.238,3.378,3.378,0,0,1,.244,1.3,10.627,10.627,0,0,0,.163,3.586l-.326.081c-2.526.815-9.127,6.03-8.312,12.957.407,3.423,1.711,5.3,4.645,7.09A4.71,4.71,0,0,0,6.3,93.39,2.133,2.133,0,0,1,6.7,94.775c-.407,2.037.163,4.075.326,6.03A5.089,5.089,0,0,0,9.637,104.8c1.3.815,1.467.815,2.282-.57.407-.733.733-.652,1.222-.081a13.128,13.128,0,0,0,3.667,3.341,12.1,12.1,0,0,1,3.26,2.526,5.973,5.973,0,0,0,5.7,1.793,5.939,5.939,0,0,1,2.934.244,29.959,29.959,0,0,0,3.83,1.222,46.141,46.141,0,0,1,7.334,2.608c2.363.9,4.727,1.548,7.171.9a8.881,8.881,0,0,1,5.053.244c2.608.815,5.379,1.385,7.5,3.26a9.433,9.433,0,0,0,3.26,1.63,12.735,12.735,0,0,1,4.727,2.282,10.815,10.815,0,0,0,4.808,2.445,4.334,4.334,0,0,0,3.341-.163,23.049,23.049,0,0,0,3.83-2.363,3.567,3.567,0,0,1,4.156-.407l1.3.652c1.793.733,3.586,1.548,5.541,1.141a12.99,12.99,0,0,0,5.379-2.2c1.711-1.3,3.5-2.445,5.3-3.749a5.042,5.042,0,0,1,4.156-.978,20.37,20.37,0,0,0,2.363.407c1.711.244,3.5.489,5.134-.326a50.434,50.434,0,0,0,4.727-2.282,14.158,14.158,0,0,0,3.178.407c4.238,0,7.5-2.526,9.127-7.171.163-.407.244-.9.407-1.3a5.927,5.927,0,0,0,3.586-3.912,8.818,8.818,0,0,0,.244-3.586c-.407-2.445-.407-5.134-1.874-7.253-.978-1.548-.733-2.363.326-3.667,1.793-2.119,3.341-4.564,5.7-6.275a18.928,18.928,0,0,0,6.275-8.231,3.868,3.868,0,0,0-.57-4.971ZM120.874,114.5a10.322,10.322,0,0,1-3.83-.733c-5.46-1.956-11.327-5.7-18.825-6.275-7.5-.489-43.11-.9-73.262-14.506-11-4.89-16.054-6.6-18.336-8.8A7.073,7.073,0,0,1,4.911,79.7c-.163-3.178,1.548-5.46,3.5-7.579A7.875,7.875,0,0,1,11.1,70.164a1.125,1.125,0,0,0,.326-.244c.081,0,.163-.081.244-.081a25.654,25.654,0,0,1,.407,3.5s-4.319,4.319-3.26,7.171S38.241,94.368,44.516,96.16C57.636,99.909,85.1,104.473,97,104.473a32.826,32.826,0,0,0,3.993-.244c6.845-1.3,13.12-4.645,18.173-4.645a8.6,8.6,0,0,1,2.526.326c5.46,1.548,7.5,4.4,5.867,9.209a8.426,8.426,0,0,1-3.667,4.808,7.34,7.34,0,0,1-2.282.652h-.081A1.589,1.589,0,0,0,120.874,114.5Z\" transform=\"translate(0 0)\" fill=\"#65cbe0\"><\/path><path d=\"M151.122,122.9a3.161,3.161,0,0,0-6.322-.069,3.114,3.114,0,0,0,3.126,3.127A3.031,3.031,0,0,0,151.122,122.9Z\" transform=\"translate(-22.419 -15.485)\" fill=\"#65cbe0\"><\/path><\/g><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tIm Durchschnitt reduzieren <span style=\"white-space: normal\">individuell angefertigte&nbsp;<\/span>Schienen bei leichter Schlafapnoe die Anzahl der Apnoen um 23% mehr als die \"Boil-and-Bite\"-Schienen.\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-d086374\" data-id=\"d086374\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-afd92a7 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"afd92a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 180 180\"><path d=\"M81.5 12.4C53.2 18.9 33 42.9 31.3 72c-.9 15.4 3.6 30.1 13.2 42.7 3.9 5.3 4.2 5.9 2.8 7.9-5.4 8.3-2 18.3 6.9 20.3 5.7 1.3 11.8-1.4 14.6-6.5.8-1.4 1.6-1.3 8.3.8 10.5 3.2 26.3 3.2 36.9 0 20.2-6.3 35.8-21.4 42.7-41.5 2.5-7.3 2.8-9.5 2.8-20.7-.1-10.9-.4-13.4-2.7-19.8-3.7-10.4-8.3-17.6-15.8-25.2-12.3-12.2-25.7-18-43-18.6-6.6-.2-12.7.1-16.5 1zM78 58.5c0 1.4-2.5 8-5.5 14.7-3.1 6.6-5.4 12.3-5.1 12.5.3.3 3.7 0 7.6-.7 3.9-.7 7.3-1 7.5-.9.2.2.5 1.7.7 3.4l.3 3L71 92.7c-6.9 1.2-13.1 2-13.7 1.8-2.3-.8-1.4-4 4.7-16.9 3.3-7 6-12.9 6-13 0-.2-3.2.2-7.2 1-3.9.8-7.2 1.3-7.3 1.1-.1-.1-.5-1.6-.8-3.3l-.6-3.2 9.7-1.7c5.3-.9 10.2-1.8 10.7-2 .6-.2 2-.4 3.3-.4 1.7-.1 2.2.4 2.2 2.4zm56 .4c4 .6 4.5 1 4.2 3-.1 1.3-4.3 7.1-9.2 13l-9 10.6 3.8.7c2 .4 5.6.7 8 .7 4 .1 4.2.3 4.2 3 0 1.7-.4 3.3-1 3.6-1.8 1.1-26.2-1.8-26.7-3.2-.7-1.8 1.1-4.4 10.7-15.5 9.1-10.4 9.1-10.5-1.2-10.7L113 64v-7.2l8.3.7c4.5.4 10.2 1 12.7 1.4zm-29 10.4c0 1.2-2.5 5.8-5.6 10.2l-5.5 8 6 .3c5.7.3 6.1.4 6.1 2.7 0 2.5-.1 2.5-10 2.5-9.4 0-10-.1-10-2 0-1.1 2.5-5.6 5.5-9.9 3-4.3 5.5-8.1 5.5-8.5 0-.3-2.2-.6-5-.6-4.7 0-5-.2-5-2.5 0-2.5.1-2.5 9-2.5 8.7 0 9 .1 9 2.3zM35.5 146.5c-6 6 .6 15.8 8.4 12.5 5.3-2.1 6.5-8.2 2.6-12.4-3.2-3.4-7.7-3.5-11-.1zM21.4 161.5c-1.5 2.3-1.5 2.7 0 5 1.8 2.7 6.3 3.4 8.4 1.3 1.5-1.5 1.5-6.1 0-7.6-2.1-2.1-6.6-1.4-8.4 1.3z\" style=\"fill: #65cbe0;\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tSchlafapnoe-Patienten f\u00fchlen sich am n\u00e4chsten Tag weniger m\u00fcde, wenn sie eine <span style=\"white-space: normal\">individuell angefertigte&nbsp;<\/span>Schiene getragen haben als wenn sie eine \"Boil-and-Bite\"-Schiene getragen haben. \t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-2ce6237\" data-id=\"2ce6237\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b0ee459 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"b0ee459\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" width=\"63.75pt\" height=\"63.749998pt\" viewBox=\"0 0 63.75 63.749998\"><defs><clipPath id=\"clip1\"><path d=\"M 8.476562 28 L 22 28 L 22 55.089844 L 8.476562 55.089844 Z M 8.476562 28 \"><\/path><\/clipPath><clipPath id=\"clip2\"><path d=\"M 27 16 L 41 16 L 41 55.089844 L 27 55.089844 Z M 27 16 \"><\/path><\/clipPath><clipPath id=\"clip3\"><path d=\"M 46 4.40625 L 59.160156 4.40625 L 59.160156 55.089844 L 46 55.089844 Z M 46 4.40625 \"><\/path><\/clipPath><\/defs><g id=\"surface1\"><g clip-path=\"url(#clip1)\" clip-rule=\"nonzero\"><path style=\" stroke:none;fill-rule:nonzero;fill:rgb(39.608765%,79.60968%,87.838745%);fill-opacity:1;\" d=\"M 21.558594 29.746094 L 21.558594 53.453125 C 21.558594 54.351562 20.820312 55.089844 19.921875 55.089844 L 10.113281 55.089844 C 9.214844 55.089844 8.476562 54.351562 8.476562 53.453125 L 8.476562 29.746094 C 8.476562 28.847656 9.214844 28.113281 10.113281 28.113281 L 19.921875 28.113281 C 20.820312 28.113281 21.558594 28.847656 21.558594 29.746094 Z M 21.558594 29.746094 \"><\/path><\/g><g clip-path=\"url(#clip2)\" clip-rule=\"nonzero\"><path style=\" stroke:none;fill-rule:nonzero;fill:rgb(39.608765%,79.60968%,87.838745%);fill-opacity:1;\" d=\"M 40.359375 18.300781 L 40.359375 53.453125 C 40.359375 54.351562 39.621094 55.089844 38.722656 55.089844 L 28.914062 55.089844 C 28.015625 55.089844 27.277344 54.351562 27.277344 53.453125 L 27.277344 18.300781 C 27.277344 17.402344 28.015625 16.667969 28.914062 16.667969 L 38.722656 16.667969 C 39.621094 16.667969 40.359375 17.402344 40.359375 18.300781 Z M 40.359375 18.300781 \"><\/path><\/g><g clip-path=\"url(#clip3)\" clip-rule=\"nonzero\"><path style=\" stroke:none;fill-rule:nonzero;fill:rgb(39.608765%,79.60968%,87.838745%);fill-opacity:1;\" d=\"M 59.160156 6.039062 L 59.160156 53.453125 C 59.160156 54.351562 58.425781 55.089844 57.523438 55.089844 L 47.714844 55.089844 C 46.816406 55.089844 46.082031 54.351562 46.082031 53.453125 L 46.082031 6.039062 C 46.082031 5.140625 46.816406 4.40625 47.714844 4.40625 L 57.523438 4.40625 C 58.425781 4.40625 59.160156 5.140625 59.160156 6.039062 Z M 59.160156 6.039062 \"><\/path><\/g><path style=\"fill:none;stroke-width:1;stroke-linecap:round;stroke-linejoin:miter;stroke:rgb(39.608765%,79.60968%,87.838745%);stroke-opacity:1;stroke-miterlimit:4;\" d=\"M 0.499555 -0.000515721 L 16.164214 -0.000515721 \" transform=\"matrix(3.640261,0,0,3.642786,1.939301,58.763597)\"><\/path><path style=\"fill:none;stroke-width:1;stroke-linecap:round;stroke-linejoin:miter;stroke:rgb(39.608765%,79.60968%,87.838745%);stroke-opacity:1;stroke-miterlimit:4;\" d=\"M 0.500123 0.000526322 L 15.452454 0.000526322 \" transform=\"matrix(0.000000000000000223,-3.643872,3.642786,0.000000000000000223,3.759801,60.584104)\"><\/path><\/g><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tEine <span style=\"white-space: normal\">individuell angefertigte&nbsp;<\/span>Schiene hat einen h\u00f6heren Tragekomfort, so dass sie nachts l\u00e4nger getragen werden k\u00f6nnen. Eine klinische Studie ergab eine durchschnittliche Tragedauer von 6,5 Stunden pro Nacht bei ma\u00dfgefertigten Schienen im Vergleich zu 5 Stunden bei \"Boil-and-Bite\"-Schienen. \t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-b3f6ee4\" data-id=\"b3f6ee4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c4495e9 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"c4495e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 256 512\"><path d=\"M88 166.059V468c0 6.627 5.373 12 12 12h56c6.627 0 12-5.373 12-12V166.059h46.059c21.382 0 32.09-25.851 16.971-40.971l-86.059-86.059c-9.373-9.373-24.569-9.373-33.941 0l-86.059 86.059c-15.119 15.119-4.411 40.971 16.971 40.971H88z\" style=\"fill: #65cbe0;\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t74% der Patienten bevorzugen eine <span style=\"white-space: normal\">individuell angefertigte&nbsp;<\/span>Schiene gegen\u00fcber einer \"Boil-and-Bite\"-Schiene.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-36feaf6 elementor-widget elementor-widget-text-editor\" data-id=\"36feaf6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center\">Reference: Johal et al \u201cReady-made versus custom-made mandibular advancement appliances in obstructive sleep apnea: A systematic review and meta-analysis\u201d Sleep Res. 2018;27<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-260fb75a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"260fb75a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4058c55d\" data-id=\"4058c55d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-7e30bd18 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7e30bd18\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-32ef9d5c\" data-id=\"32ef9d5c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-af8d659 elementor-widget elementor-widget-heading\" data-id=\"af8d659\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">N\u00e4chste Schritte<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-6a038c75 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6a038c75\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-1c8d8fd4\" data-id=\"1c8d8fd4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-7cf8d27e\" data-id=\"7cf8d27e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-17c7396f icon--hover elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"17c7396f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/somnomed.com\/de\/patients\/products\/somnodent\/somnodent-avant\/\" target=\"_blank\" class=\"elementor-icon\" tabindex=\"-1\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"142.915\" height=\"95.641\" viewBox=\"0 0 142.915 95.641\"><g transform=\"translate(-2.315 -31.259)\"><path d=\"M144.018,70.409c-.163-.244-.326-.407-.489-.652a2.07,2.07,0,0,0-2.852-.9c-2.363,1.222-4.808,2.119-7.171,3.26a3.662,3.662,0,0,0-1.793,1.711c-.163.326-.244.652-.652.652-1.874.163-3.667-.163-4.4-2.2-.244-.733-.57-1.548-.815-2.282a2.266,2.266,0,0,0-1.956-1.63,16.315,16.315,0,0,1-1.956-.326c-1.956-.407-3.83-.9-5.786-1.3a5.433,5.433,0,0,0-4.482.733,8.358,8.358,0,0,0-2.282,2.2,2,2,0,0,1-1.956.9c-1.059-.163-2.119-.326-3.178-.57-3.341-.407-6.682-.733-10.024-.815a3.34,3.34,0,0,0-2.282.733,13.386,13.386,0,0,0-2.363,2.445,2.794,2.794,0,0,1-3.015,1.3,48.07,48.07,0,0,0-6.845-.244,6.147,6.147,0,0,0-4.727,2.526,3.384,3.384,0,0,1-3.586,1.222,30.935,30.935,0,0,0-7.253-.815h-13.2a13.338,13.338,0,0,1-3.1-.326c-1.059-.244-1.222-.57-.57-1.467a3.764,3.764,0,0,1,.57-.57,5.617,5.617,0,0,0,1.711-1.956c.57-1.222,1.059-2.526,1.63-3.749a5.193,5.193,0,0,0,.081-4.89,2.041,2.041,0,0,1,.733-2.689,7.551,7.551,0,0,0,1.141-1.141c1.956-2.282,3.423-4.808,5.216-7.171.9-1.222,1.874-2.445,2.771-3.667a1.478,1.478,0,0,0,.081-1.874,13.006,13.006,0,0,0-2.282-2.852,3.425,3.425,0,0,0-3.749-.978,1.131,1.131,0,0,1-1.385-.326,5.611,5.611,0,0,1-.9-1.059,21.431,21.431,0,0,0-3.26-3.423,21.759,21.759,0,0,1-3.83-3.912,13.348,13.348,0,0,0-1.711-2.037,3.215,3.215,0,0,0-3.83-.652c-1.793.815-2.363,2.445-2.934,4.075-.407,1.385-.407,1.385-1.874,1.3a1.794,1.794,0,0,0-.652.081c-1.141.326-2.363.57-3.423.978-2.2.815-3.912,2.119-4.238,4.645a5.647,5.647,0,0,0-.244,1.63c0,.9-.57,1.141-1.3,1.059a13.175,13.175,0,0,0-3.1-.163,4.084,4.084,0,0,0-3.749,3.586,1.055,1.055,0,0,1-.815,1.059,5.942,5.942,0,0,0-3.5,5.216,13.163,13.163,0,0,1,0,1.793.958.958,0,0,1-1.467.9,1.122,1.122,0,0,0-1.3.407,4.918,4.918,0,0,0-1.059,4.238,3.378,3.378,0,0,1,.244,1.3,10.627,10.627,0,0,0,.163,3.586l-.326.081c-2.526.815-9.127,6.03-8.312,12.957.407,3.423,1.711,5.3,4.645,7.09A4.71,4.71,0,0,0,6.3,93.39,2.133,2.133,0,0,1,6.7,94.775c-.407,2.037.163,4.075.326,6.03A5.089,5.089,0,0,0,9.637,104.8c1.3.815,1.467.815,2.282-.57.407-.733.733-.652,1.222-.081a13.128,13.128,0,0,0,3.667,3.341,12.1,12.1,0,0,1,3.26,2.526,5.973,5.973,0,0,0,5.7,1.793,5.939,5.939,0,0,1,2.934.244,29.959,29.959,0,0,0,3.83,1.222,46.141,46.141,0,0,1,7.334,2.608c2.363.9,4.727,1.548,7.171.9a8.881,8.881,0,0,1,5.053.244c2.608.815,5.379,1.385,7.5,3.26a9.433,9.433,0,0,0,3.26,1.63,12.735,12.735,0,0,1,4.727,2.282,10.815,10.815,0,0,0,4.808,2.445,4.334,4.334,0,0,0,3.341-.163,23.049,23.049,0,0,0,3.83-2.363,3.567,3.567,0,0,1,4.156-.407l1.3.652c1.793.733,3.586,1.548,5.541,1.141a12.99,12.99,0,0,0,5.379-2.2c1.711-1.3,3.5-2.445,5.3-3.749a5.042,5.042,0,0,1,4.156-.978,20.37,20.37,0,0,0,2.363.407c1.711.244,3.5.489,5.134-.326a50.434,50.434,0,0,0,4.727-2.282,14.158,14.158,0,0,0,3.178.407c4.238,0,7.5-2.526,9.127-7.171.163-.407.244-.9.407-1.3a5.927,5.927,0,0,0,3.586-3.912,8.818,8.818,0,0,0,.244-3.586c-.407-2.445-.407-5.134-1.874-7.253-.978-1.548-.733-2.363.326-3.667,1.793-2.119,3.341-4.564,5.7-6.275a18.928,18.928,0,0,0,6.275-8.231,3.868,3.868,0,0,0-.57-4.971ZM120.874,114.5a10.322,10.322,0,0,1-3.83-.733c-5.46-1.956-11.327-5.7-18.825-6.275-7.5-.489-43.11-.9-73.262-14.506-11-4.89-16.054-6.6-18.336-8.8A7.073,7.073,0,0,1,4.911,79.7c-.163-3.178,1.548-5.46,3.5-7.579A7.875,7.875,0,0,1,11.1,70.164a1.125,1.125,0,0,0,.326-.244c.081,0,.163-.081.244-.081a25.654,25.654,0,0,1,.407,3.5s-4.319,4.319-3.26,7.171S38.241,94.368,44.516,96.16C57.636,99.909,85.1,104.473,97,104.473a32.826,32.826,0,0,0,3.993-.244c6.845-1.3,13.12-4.645,18.173-4.645a8.6,8.6,0,0,1,2.526.326c5.46,1.548,7.5,4.4,5.867,9.209a8.426,8.426,0,0,1-3.667,4.808,7.34,7.34,0,0,1-2.282.652h-.081A1.589,1.589,0,0,0,120.874,114.5Z\" transform=\"translate(0 0)\" fill=\"#65cbe0\"><\/path><path d=\"M151.122,122.9a3.161,3.161,0,0,0-6.322-.069,3.114,3.114,0,0,0,3.126,3.127A3.031,3.031,0,0,0,151.122,122.9Z\" transform=\"translate(-22.419 -15.485)\" fill=\"#65cbe0\"><\/path><\/g><\/svg>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tWeitere Informationen \u00fcber unsere bisher komfortabelste Schiene, die  SomnoDent Avant<sup>\u00ae<\/sup>, finden SIe unter folgendem Link. \t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-470d345d\" data-id=\"470d345d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-382f039 icon--hover elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"382f039\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/somnomed.com\/de\/contact\/\" target=\"_blank\" class=\"elementor-icon\" tabindex=\"-1\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" data-name=\"Layer 1\" viewBox=\"0 0 180 180\"><circle cx=\"90\" cy=\"25.56\" r=\"21.37\" fill=\"#231f20\" transform=\"rotate(-78.51 90 25.554)\" style=\"fill: #65cbe0;\"><\/circle><path fill=\"#231f20\" d=\"M109.24 62.39a12.38 12.38 0 1 0 12.38 12.38 12.4 12.4 0 0 0-12.38-12.38zm9.21 10v4.76a1 1 0 0 1-1 .95h-4.93V83a1 1 0 0 1-.95 1h-4.76a1 1 0 0 1-1-1v-4.9H101a1 1 0 0 1-1-.95v-4.76a1 1 0 0 1 1-1h4.93V66.5a1 1 0 0 1 1-1h4.76a1 1 0 0 1 .95 1v4.93h4.93a1 1 0 0 1 .88.96z\" style=\"fill: #65cbe0;\"><\/path><path fill=\"#231f20\" d=\"M122.67 52.62H57.33A9.33 9.33 0 0 0 48 62v47.81a9.34 9.34 0 0 0 9.33 9.34h8.52v47.38a9.33 9.33 0 0 0 9.33 9.33h29.64a9.33 9.33 0 0 0 9.33-9.33V119.1h8.52a9.34 9.34 0 0 0 9.33-9.34V62a9.33 9.33 0 0 0-9.33-9.38zm.6 28.08a15.24 15.24 0 0 1-3.27 4.84 15.24 15.24 0 0 1-16.7 3.26 14.87 14.87 0 0 1-4.84-3.26 15.22 15.22 0 0 1-3.27-16.7 15.37 15.37 0 0 1 8.11-8.11A15.2 15.2 0 0 1 120 64a15.24 15.24 0 0 1 3.26 16.7z\" style=\"fill: #65cbe0;\"><\/path><\/svg>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tWir helfen Ihnen Ihre Behandlung zu beginnen. \t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-46d916bf\" data-id=\"46d916bf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-0303d85 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"0303d85\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c32b3f4\" data-id=\"c32b3f4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4d70751 elementor-widget elementor-widget-template\" data-id=\"4d70751\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"241\" class=\"elementor elementor-241\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-4a295eb elementor-section-content-middle elementor-section-full_width elementor-reverse-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"4a295eb\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f93fe14 padding-col--left\" data-id=\"f93fe14\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-a4086c2 elementor-section-full_width elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"a4086c2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-0dcdcaa\" data-id=\"0dcdcaa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-72cff3b elementor-widget elementor-widget-heading\" data-id=\"72cff3b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/vimeo.com\/573281862\" target=\"_blank\" rel=\"noopener\">Was berichten SomnoMed  Patienten?<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c99b2c elementor-widget elementor-widget-text-editor\" data-id=\"1c99b2c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #00549d;\"><strong>Jeder Patient ist unterschiedlich und wir haben schon viele auf ihrem Weg zu einer effektiven Behandlung begleitet.\u00a0\u00a0<\/strong><\/span><\/p><p>Sehen Sie ihre Geschichte und wie die SomnoDent Protrusionsschiene ihnen geholfen hat.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-01e762d\" data-id=\"01e762d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eccdfbe elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-video\" data-id=\"eccdfbe\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;lazy_load&quot;:&quot;yes&quot;,&quot;show_image_overlay&quot;:&quot;yes&quot;,&quot;image_overlay&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/somnomed.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2021\\\/06\\\/Patient-stories.jpg&quot;,&quot;id&quot;:15237,&quot;size&quot;:&quot;&quot;,&quot;alt&quot;:&quot;Erfahrungsberichte von Patienten \\u00fcber die Schlafapnoe-Behandlung mit Schlafapnoe-Schienen.    &quot;,&quot;source&quot;:&quot;library&quot;},&quot;video_type&quot;:&quot;vimeo&quot;,&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<iframe class=\"elementor-video-iframe\" allowfullscreen allow=\"clipboard-write\" title=\"vimeo Video Player\" data-lazy-load=\"https:\/\/player.vimeo.com\/video\/213864189?color&amp;autopause=0&amp;loop=0&amp;muted=0&amp;title=0&amp;portrait=0&amp;byline=0#t=\"><\/iframe>\t\t\t\t<div class=\"elementor-custom-embed-image-overlay\" style=\"background-image: url(https:\/\/somnomed.com\/de\/wp-content\/uploads\/sites\/8\/2021\/06\/Patient-stories.jpg);\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-4442681 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"4442681\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8ae51aa\" data-id=\"8ae51aa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2bc5e5c elementor-widget elementor-widget-heading\" data-id=\"2bc5e5c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Patientenerfahrungen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fb7c08b elementor-widget elementor-widget-Custom_El_Slider_Text\" data-id=\"fb7c08b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"Custom_El_Slider_Text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t          <div id=\"el-slider-text-6a049e553ee08\" class=\"el-slider-text\">\r\n        <div class=\"el-slider-text__slider\">\r\n                      <div class=\"el-slider-text__slide\">\r\n              <div class=\"el-slider-text__slide-inner balance-elements\" style=\"background-color: #C3E7EF; color: #000000; \">\r\n                <h3><b>Man sp\u00fcrt sie kaum<\/b><\/h3>\n<p>Ich habe die SomnoDent-Schiene seit einem halben Jahr und muss sagen, dass es mir dank dieser Schiene wesentlich besser geht. Es sind noch nicht alle Probleme beseitig, da sich mein K\u00f6rper durch jahrelange Ersch\u00f6pfung erst so langsam erholt. Ich kann jedem diese Schiene empfehlen, der nicht mit eine Maske leben m\u00f6chte. Die Schiene ist so leicht zu tragen und man sp\u00fcrt sie kaum. Ich kann es nicht anders ausdr\u00fccken, die SomnoDent-Schiene ist mein Lebensretter. Hoffe, ich kann vielen Menschen, die an Schlafapnoe leiden, durch meine positive Erfahrung weiterhelfen.<\/p>\n<p style=\"text-align: right;\"><strong>- Matthias<\/strong><\/p>\n              <\/div>\r\n            <\/div>\r\n                      <div class=\"el-slider-text__slide\">\r\n              <div class=\"el-slider-text__slide-inner balance-elements\" style=\"background-color: #C1CAE3; color: #000000; \">\r\n                <h3><b>Ich habe mein Leben zur\u00fcck<\/b><\/h3>\n<p>Ich habe mein Leben zur\u00fcck, dank SomnoDent<sup>\u00ae<\/sup>! Jetzt habe ich wieder die grenzenlose Energie, wie ich sie als Teenager hatte, bevor ich die Schlafapnoe bekam. Ich stehe fr\u00fch auf, gehe sp\u00e4t ins Bett, bin mit 51 in ein Sportstudio eingetreten (ich war nie zuvor in einem Sportstudio) und f\u00fchle mich zu 100 % voller Energie!<\/p>\n<p style=\"text-align: right;\"><strong>- Tjark<\/strong><\/p>\n              <\/div>\r\n            <\/div>\r\n                      <div class=\"el-slider-text__slide\">\r\n              <div class=\"el-slider-text__slide-inner balance-elements\" style=\"background-color: #00549D; color: #ffffff; \">\r\n                <h3><b>Keine Druckstellen<\/b><\/h3>\n<p>Der Tragekomfort der SomnoDent ist phantastisch! 100%ige Passgenauigkeit,<br \/>keine Reibungs- oder Druckpunkte an den \u00dcberg\u00e4ngen zum Zahnfleisch. Damit hatte ich bei anderen Schienen immer wieder Probleme und musste diese mehrmals neu anpassen.<\/p>\n<p style=\"text-align: right;\"><strong>- Gaby<\/strong><\/p>\n              <\/div>\r\n            <\/div>\r\n                      <div class=\"el-slider-text__slide\">\r\n              <div class=\"el-slider-text__slide-inner balance-elements\" style=\"background-color: #7B91C4; color: #FFFFFF; \">\r\n                <h3><b>Mein Mann ist wieder fit<\/b><\/h3>\n<p>Mein Mann hatte mit der SomnoDent Schiene nur noch einen AHI von 6,6\/h. Mit der Schiene kommt er super klar. Er tr\u00e4gt sie jede Nacht w\u00e4hrend der kompletten Schlafzeit ohne Probleme. Nach vielen Jahren ist er dank der SomnoDent<sup>\u00ae<\/sup>-Schiene zum ersten Mal wieder so fit und gut drauf wie vor zehn Jahren, als ich ihn kennengelernt hatte.<\/p>\n<p style=\"text-align: right;\"><strong>- Mirja<\/strong><\/p>\n              <\/div>\r\n            <\/div>\r\n                      <div class=\"el-slider-text__slide\">\r\n              <div class=\"el-slider-text__slide-inner balance-elements\" style=\"background-color: #5175B3; color: #ffffff; \">\r\n                <h3><b>Wie ein neuer Mensch<\/b><\/h3>\n<p>Seit ich sie benutze f\u00fchle ich mich wieder wie ein vollst\u00e4ndiger Mensch. Ich w\u00fcrde sie jedem empfehlen, der an Schlafapnoe leidet. Sie ist einfach klasse.<\/p>\n<p style=\"text-align: right;\"><strong>- Volker<\/strong><\/p>\n              <\/div>\r\n            <\/div>\r\n                  <\/div>\r\n      <\/div>\r\n\r\n      <script>\r\n        jQuery(document).ready(function($) {\r\n          $('#el-slider-text-6a049e553ee08 .el-slider-text__slider').slick({\r\n            centerMode: true,\r\n            centerPadding: '300px',\r\n            slidesToShow: 2,\r\n            arrows: true,\r\n            dots: false,\r\n            infinite: true,\r\n            responsive: [\r\n              {\r\n                breakpoint: 1600,\r\n                settings: {\r\n                  arrows: false,\r\n                  dots: true,\r\n                  centerPadding: '150px',\r\n                  slidesToShow: 2\r\n                }\r\n              },\r\n              {\r\n                breakpoint: 768,\r\n                settings: {\r\n                  arrows: false,\r\n                  dots: true,\r\n                  centerPadding: '5px',\r\n                  slidesToShow: 1\r\n                }\r\n              }\r\n            ]\r\n          });\r\n        });\r\n      <\/script>\r\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Therapie von Schlafapnoe mit SomnoDent\u00ae-Schienen Bei leichter oder mittelschwere obstruktiver Schlafapnoe (OSA) kann die Therapie mit einer SomnoDent-Schiene genauso effektiv sein wie mit einer CPAP-Maske. Die CPAP-Therapie ist eine sehr wirksame Behandlungsmethode f\u00fcr OSA \u2013 aber nur, wenn das Ger\u00e4t jede Nacht genutzt wird. Vieles am CPAP-Ger\u00e4t behindert einen guten Schlaf: Sie sind an einen &#8230;<\/p>\n","protected":false},"author":54,"featured_media":0,"parent":1044,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-235","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/somnomed.com\/de\/wp-json\/wp\/v2\/pages\/235","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/somnomed.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/somnomed.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/somnomed.com\/de\/wp-json\/wp\/v2\/users\/54"}],"replies":[{"embeddable":true,"href":"https:\/\/somnomed.com\/de\/wp-json\/wp\/v2\/comments?post=235"}],"version-history":[{"count":10,"href":"https:\/\/somnomed.com\/de\/wp-json\/wp\/v2\/pages\/235\/revisions"}],"predecessor-version":[{"id":16970,"href":"https:\/\/somnomed.com\/de\/wp-json\/wp\/v2\/pages\/235\/revisions\/16970"}],"up":[{"embeddable":true,"href":"https:\/\/somnomed.com\/de\/wp-json\/wp\/v2\/pages\/1044"}],"wp:attachment":[{"href":"https:\/\/somnomed.com\/de\/wp-json\/wp\/v2\/media?parent=235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}