{"id":322,"date":"2021-06-09T01:43:41","date_gmt":"2021-06-09T05:43:41","guid":{"rendered":"https:\/\/local.somnomed.com\/en\/?page_id=322"},"modified":"2025-07-31T11:29:45","modified_gmt":"2025-07-31T09:29:45","slug":"obstructive-sleep-apnea-osa","status":"publish","type":"page","link":"https:\/\/somnomed.com\/es\/patients\/sleep\/obstructive-sleep-apnea-osa\/","title":{"rendered":"Apnea Obstructiva del Sue\u00f1o (AOS)"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"322\" class=\"elementor elementor-322\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-4ed0627b elementor-section-content-top elementor-section-full_width elementor-reverse-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"4ed0627b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-729a920a padding-col--left\" data-id=\"729a920a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-57331af6 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"57331af6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-7f0dfbd5\" data-id=\"7f0dfbd5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-349fc121 elementor-widget elementor-widget-heading\" data-id=\"349fc121\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">\u00bfQu\u00e9 es la apnea obstructiva del sue\u00f1o (AOS)?<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4319eb08 elementor-widget elementor-widget-text-editor\" data-id=\"4319eb08\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #00549d;\"><strong>La apnea obstructiva del sue\u00f1o (AOS) es un trastorno en el que la respiraci\u00f3n se interrumpe involuntariamente por breves lapsos de tiempo durante el sue\u00f1o. Est\u00e1 causada normalmente por el estrechamiento de las v\u00edas respiratorias en la parte posterior de la garganta. Esas interrupciones de la respiraci\u00f3n se denominan apneas o episodios de apnea. <\/strong><\/span><\/p><p>Haga clic en el video para ver una breve explicaci\u00f3n sobre la apnea obstructiva del sue\u00f1o y c\u00f3mo puede estar afectando a su sue\u00f1o y a su bienestar personal.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6adac9ef\" data-id=\"6adac9ef\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c3c2a7d elementor-widget elementor-widget-video\" data-id=\"c3c2a7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;lazy_load&quot;:&quot;yes&quot;,&quot;show_image_overlay&quot;:&quot;yes&quot;,&quot;image_overlay&quot;:{&quot;url&quot;:&quot;http:\\\/\\\/somnomed.co\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/06\\\/What-is-sleep-apnea-animation.png&quot;,&quot;id&quot;:&quot;1769&quot;,&quot;size&quot;:&quot;&quot;},&quot;video_type&quot;:&quot;vimeo&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<iframe class=\"elementor-video-iframe\" allowfullscreen allow=\"clipboard-write\" title=\"Reproductor de v\u00eddeo vimeo\" data-lazy-load=\"https:\/\/player.vimeo.com\/video\/568781933?color&amp;autopause=0&amp;loop=0&amp;muted=0&amp;title=1&amp;portrait=1&amp;byline=1#t=\"><\/iframe>\t\t\t\t<div class=\"elementor-custom-embed-image-overlay\" style=\"background-image: url(https:\/\/somnomed.com\/es\/wp-content\/uploads\/sites\/14\/2021\/06\/What-is-sleep-apnea-animation.png);\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-custom-embed-play\" role=\"button\" aria-label=\"Reproducir v\u00eddeo\" tabindex=\"0\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-play\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-fbca781 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fbca781\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1d4fe28\" data-id=\"1d4fe28\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e5a0b00 elementor-widget elementor-widget-Custom_El_Slider_Vertical\" data-id=\"e5a0b00\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"Custom_El_Slider_Vertical.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t      <div id=\"el-slider-vertical-6a04a39dc1387\" class=\"el-slider-vertical\">\r\n        <div class=\"row align-items-center \">\r\n          <div class=\"col-xl-6 pe-xl-5\">\r\n            <div class=\"el-slider-vertical__images\">\r\n                                                <div class=\"el-slider-vertical__image bg-center\" style=\"background-image:url('https:\/\/somnomed.com\/es\/wp-content\/uploads\/sites\/14\/2022\/05\/Spanish-images-wordings-translated-2.png')\"><\/div>\r\n                                                                <div class=\"el-slider-vertical__image bg-center\" style=\"background-image:url('https:\/\/somnomed.com\/es\/wp-content\/uploads\/sites\/14\/2022\/05\/Narrow.png')\"><\/div>\r\n                                                                <div class=\"el-slider-vertical__image bg-center\" style=\"background-image:url('https:\/\/somnomed.com\/es\/wp-content\/uploads\/sites\/14\/2023\/01\/Spanish-images-wordings-translated-obstruida-1024x1024.png')\"><\/div>\r\n                                          <\/div>\r\n          <\/div>\r\n\r\n          <div class=\"col-xl-6\">\r\n            <div class=\"row g-0 align-items-center \">\r\n              <div class=\"col-xl-4 text-center\">\r\n                                  <div class=\"el-slider-vertical__nav d-flex flex-wrap flex-xl-column py-4 align-items-center justify-content-center\">\r\n                    <a href=\"#\" class=\"el-slider-vertical__nav--prev px-3\">\r\n                      <img decoding=\"async\" src=\"https:\/\/somnomed.com\/es\/wp-content\/themes\/somnomed-2021\/assets\/images\/chev-up.svg\" alt=\"Arrow\" class=\"img-fluid\" width=\"30\">\r\n                    <\/a>\r\n\r\n                    <span class=\"el-slider-vertical__nav--current\">01<\/span>\r\n\r\n                    <a href=\"#\" class=\"el-slider-vertical__nav--next px-3\">\r\n                      <img decoding=\"async\" src=\"https:\/\/somnomed.com\/es\/wp-content\/themes\/somnomed-2021\/assets\/images\/chev-down.svg\" alt=\"Arrow\" class=\"img-fluid\" width=\"30\">\r\n                    <\/a>\r\n                  <\/div>\r\n                              <\/div>\r\n\r\n              <div class=\"col-xl-8\">\r\n                                  <h2 class=\"mb-4\">Causas de la apnea del sue\u00f1o<\/h2>\r\n                \r\n                <div class=\"el-slider-vertical__content\">\r\n                                      <div class=\"el-slider-vertical__content-inner\">\r\n                      <p>Existen dos tipos de apnea del sue\u00f1o: apnea obstructiva del sue\u00f1o (AOS) y apnea central del sue\u00f1o. El 85% de las personas con apnea sufren AOS, y su m\u00e9dico podr\u00e1 determinar cu\u00e1l de ellas padece realiz\u00e1ndole un estudio del sue\u00f1o o m\u00e1s conocido como polisomnograf\u00eda.\u00a0<\/p>\n<p>La apnea obstructiva del sue\u00f1o est\u00e1 causada por la relajaci\u00f3n de los m\u00fasculos de la parte posterior de la garganta, que interrumpen la respiraci\u00f3n mientras duerme.<\/p>\n<p>La imagen de la izquierda muestra la v\u00eda a\u00e9rea normal, c\u00f3mo el flujo de aire pasa a trav\u00e9s de la nariz y la boca en una persona que no sufre apnea del sue\u00f1o.<\/p>\n<p>Haga clic para ver qu\u00e9 sucede con la v\u00eda a\u00e9rea obstruida.\u00a0<\/p>\n\r\n                                          <\/div>\r\n                                      <div class=\"el-slider-vertical__content-inner\">\r\n                      <h5>V\u00eda a\u00e9rea estrecha<\/h5>\n<p>En la imagen de la izquierda, vemos c\u00f3mo los m\u00fasculos de la parte posterior de la garganta se relajan cuando vas a dormir. Como la v\u00eda a\u00e9rea est\u00e1 parcialmente bloqueada, empezar\u00e1 a roncar. Si la v\u00eda a\u00e9rea se bloquea por completo, no llega aire a los pulmones y por lo tanto sufrir\u00e1 apnea del sue\u00f1o.\u00a0<\/p>\n<p>Durante la noche, sin que se de cuenta su v\u00eda a\u00e9rea puede estrecharse o bloquearse provocando que se reduzca que llegue ox\u00edgeno al cerebro provocando que al d\u00eda siguiente se sienta somnoliento y sin energ\u00eda.\u00a0<\/p>\n\r\n                                          <\/div>\r\n                                      <div class=\"el-slider-vertical__content-inner\">\r\n                      <h5>V\u00eda a\u00e9rea obstruida<\/h5>\n<p>Cuando su v\u00eda a\u00e9rea est\u00e1 completamente obstruida, su cerebro responde al bajo nivel de ox\u00edgeno en su sangre despert\u00e1ndolo para que pueda respirar. Si duerme con su pareja oir\u00e1 un sonido de asfixia o jadeo.\u00a0<\/p>\n<p>Al\u00a0 levantarse se notar\u00e1 con poca energ\u00eda porque durante la noche\u00a0 no ha dormido profundamente y se ha ido despertando.\u00a0<\/p>\n\r\n                                          <\/div>\r\n                                  <\/div>\r\n              <\/div>\r\n            <\/div>\r\n          <\/div>\r\n        <\/div>\r\n      <\/div>\r\n\r\n      <script>\r\n        jQuery(document).ready(function($) {\r\n          $('#el-slider-vertical-6a04a39dc1387 .el-slider-vertical__images').slick({\r\n            slidesToShow: 1,\r\n            slidesToScroll: 1,\r\n            arrows: false,\r\n            dots: false,\r\n            fade: true,\r\n            asNavFor: '#el-slider-vertical-6a04a39dc1387 .el-slider-vertical__content',\r\n            responsive: [\r\n              {\r\n                breakpoint: 1200,\r\n                settings: {\r\n                  fade: false,\r\n                }\r\n              }\r\n            ]\r\n          });\r\n\r\n          $('#el-slider-vertical-6a04a39dc1387 .el-slider-vertical__content').slick({\r\n            slidesToShow: 1,\r\n            slidesToScroll: 1,\r\n            asNavFor: '#el-slider-vertical-6a04a39dc1387 .el-slider-vertical__images',\r\n            prevArrow: '#el-slider-vertical-6a04a39dc1387 .el-slider-vertical__nav--prev',\r\n            nextArrow: '#el-slider-vertical-6a04a39dc1387 .el-slider-vertical__nav--next',\r\n            arrows: true,\r\n            fade: true,\r\n            dots: false,\r\n            responsive: [\r\n              {\r\n                breakpoint: 1200,\r\n                settings: {\r\n                  adaptiveHeight: true,\r\n                  fade: false,\r\n                }\r\n              }\r\n            ]\r\n          });\r\n\r\n          $('#el-slider-vertical-6a04a39dc1387 .el-slider-vertical__content').on('beforeChange', function(event, slick, currentSlide, nextSlide) {\r\n            $('#el-slider-vertical-6a04a39dc1387 .el-slider-vertical__nav--current').text('0' + (nextSlide + 1));\r\n          });\r\n        });\r\n      <\/script>\r\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-2c23ce28 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2c23ce28\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4fef3c95\" data-id=\"4fef3c95\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-67c18738 elementor-widget elementor-widget-image\" data-id=\"67c18738\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/somnomed.com\/es\/wp-content\/uploads\/sites\/14\/elementor\/thumbs\/Union-5-1-pfshewbp751if077yhpz4arzqj95d9i4yciiilarsw.jpg\" title=\"Union 5\" alt=\"Union 5\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2c57e45c\" data-id=\"2c57e45c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-3cd9590e elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"3cd9590e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-1fcb3330\" data-id=\"1fcb3330\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4e01c64f elementor-widget elementor-widget-heading\" data-id=\"4e01c64f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">S\u00edntomas de la apnea del sue\u00f1o<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3301b0f1 elementor-widget elementor-widget-text-editor\" data-id=\"3301b0f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Roncar es la raz\u00f3n m\u00e1s com\u00fan por la que la mayor\u00eda de personas visitan a su m\u00e9dico para hablar del sue\u00f1o.\u00a0\u00a0<\/p><p>Otra se\u00f1al de alerta de la apnea obstructiva del sue\u00f1o (AOS) es quedarse dormido durante el d\u00eda, normalmente viendo la televisi\u00f3n o en el transporte p\u00fablico.<\/p><p><strong><span style=\"color: #00549d;\">Otros s\u00edntomas de sufrir AOS:<\/span><\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c104ee elementor-widget elementor-widget-text-editor\" data-id=\"3c104ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<span style=\"color: #00549d;\"><strong>\u2022 Somnolencia diurna o fatiga\u00a0 \u00a0 \u00a0 <\/strong><\/span><br\/><span style=\"color: #00549d;\"><strong>\u2022 Problemas de concentraci\u00f3n<\/strong><\/span><br\/>\n<span style=\"color: #00549d;\"><strong>\u2022 Dolor de cabeza<\/strong><\/span><br\/>\n<span style=\"color: #00549d;\"><strong>\u2022 Bajo estado an\u00edmico<\/strong><\/span><br\/>\n<span style=\"color: #00549d;\"><strong>\u2022 Obesidad<\/strong><\/span><br\/>\n<span style=\"color: #00549d;\"><strong>\u2022 Disminuci\u00f3n de la libido<\/strong><\/span><br\/>\n<span style=\"color: #00549d;\"><strong>\u2022 Disfunci\u00f3n er\u00e9ctil<\/strong><\/span><br\/>\n<span style=\"color: #00549d;\"><strong>\u2022 Sudoraci\u00f3n nocturna<\/strong><\/span><br\/>\n<span style=\"color: #00549d;\"><strong>\u2022 Micci\u00f3n frecuente durante la noche\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/strong><\/span>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-724d62d8 elementor-section-content-middle elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"724d62d8\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1d418162\" data-id=\"1d418162\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-1fcc20f1 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"1fcc20f1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-75a7a8c2\" data-id=\"75a7a8c2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e16a56f elementor-widget elementor-widget-heading\" data-id=\"e16a56f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bfQu\u00e9 pasa si no se trata la apnea del sue\u00f1o?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2eaf329e elementor-widget elementor-widget-text-editor\" data-id=\"2eaf329e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La apnea del sue\u00f1o es un trastorno grave y relativamente com\u00fan. M\u00e1s de 1.000 millones de personas de todo el mundo padecen este trastorno y hasta un 80% de estas personas no siguen ning\u00fan tratamiento. La apnea del sue\u00f1o sin tratar puede dar lugar a:<\/p><p><strong><span style=\"color: #00549d;\">\u2022 Hipertensi\u00f3n<\/span><\/strong><br \/><strong><span style=\"color: #00549d;\">\u2022 Afecciones o arritmias card\u00edacas\u00a0<\/span><\/strong><br \/><strong><span style=\"color: #00549d;\">\u2022 Diabetes tipo 2<\/span><\/strong><br \/><strong><span style=\"color: #00549d;\">\u2022 Insuficiencia card\u00edaca<\/span><\/strong><br \/><strong><span style=\"color: #00549d;\">\u2022 Accidentes de tr\u00e1fico<\/span><\/strong><br \/><strong><span style=\"color: #00549d;\">\u2022 Accidentes laborales<\/span><\/strong><br \/><strong><span style=\"color: #00549d;\">\u2022 Ictus<\/span><\/strong><\/p><p>Un buen diagn\u00f3stico y un buen tratamiento pueden aliviar los s\u00edntomas y reducir los riesgos a largo plazo para la salud.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-888537d\" data-id=\"888537d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7ae356a7 elementor-widget elementor-widget-image\" data-id=\"7ae356a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/somnomed.com\/es\/wp-content\/uploads\/sites\/14\/elementor\/thumbs\/Measuring-Blood-Pressure-e1625019307362-pfshewbp751if077yhpz4arzqj95d9i4yciiilarsw.jpg\" title=\"Measuring Blood Pressure\" alt=\"Measuring Blood Pressure\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-caf8c3b elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"caf8c3b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b8745e5\" data-id=\"b8745e5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fc845d1 elementor-widget elementor-widget-template\" data-id=\"fc845d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"241\" class=\"elementor elementor-241\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-4442681 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"4442681\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8ae51aa\" data-id=\"8ae51aa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2bc5e5c elementor-widget elementor-widget-heading\" data-id=\"2bc5e5c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nuestros pacientes cuentan su historia<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fb7c08b elementor-widget elementor-widget-Custom_El_Slider_Text\" data-id=\"fb7c08b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"Custom_El_Slider_Text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t          <div id=\"el-slider-text-6a04a39dcec5f\" class=\"el-slider-text\">\r\n        <div class=\"el-slider-text__slider\">\r\n                      <div class=\"el-slider-text__slide\">\r\n              <div class=\"el-slider-text__slide-inner balance-elements\" style=\"background-color: #C3E7EF; color: #000000; \">\r\n                <p>\u201cTras hacer una investigaci\u00f3n de mercado, el dispositivo oral de SomnoMed me pareci\u00f3 el m\u00e1s interesante y me puse manos a la obra. Despu\u00e9s del estudio por parte del especialista en maxilofacial pude empezar mi tratamiento en junio de 2020 y para m\u00ed est\u00e1 funcionando a pleno rendimiento. Sigo teniendo apneas, pocas y cortas (tambi\u00e9n con la CPAP, por otra parte) pero mi vida ha cambiado sustancialmente ya que no necesito dormir al lado de una fuente de electricidad, ya no tengo la presi\u00f3n de la m\u00e1scara en la piel d\u00eda y noche, me he quitado el estigma de la apnea en la cara y, adem\u00e1s, este DAM es muy confortable. Si antes ten\u00eda que dormir con una f\u00e9rula de descarga (tambi\u00e9n soy bruxista) pues ahora duermo con un dispositivo oral de SomnoMed que tambi\u00e9n lo trata.<br \/>\nAdem\u00e1s, en cuanto me retiro el dispositivo oral por la ma\u00f1ana hago ejercicios para no da\u00f1ar mi ATM.<br \/>\nEstoy muy contenta ya que puedo descansar todas las noches y me resulta f\u00e1cil el uso de este dispositivo\u201d.<\/p>\n<p style=\"text-align: right;\"><strong>- Aurora C. (Vitoria, Espa\u00f1a)<\/strong><\/p>\n              <\/div>\r\n            <\/div>\r\n                      <div class=\"el-slider-text__slide\">\r\n              <div class=\"el-slider-text__slide-inner balance-elements\" style=\"background-color: #C1CAE3; color: #000000; \">\r\n                <p>\u201cSupe de SomnoMed a ra\u00edz de un comentario que me hizo un amigo que ten\u00eda el mismo problema que yo a la hora de dormir, y su favorable experiencia con las f\u00e9rulas SomnoMed.<br \/>\nAs\u00ed que fui al dentista que le hab\u00eda atendido. Tras obtener la impresi\u00f3n de mis dientes y en cuesti\u00f3n de unos pocos d\u00edas comenzamos a ajustar las f\u00e9rulas hasta lograr la posici\u00f3n \u00f3ptima en unas pocas semanas. La adaptaci\u00f3n a ellas no supuso ning\u00fan problema.<br \/>\nDesde entonces puedo disfrutar de noches tranquilas y sin molestar a nadie. Adem\u00e1s, su limpieza y mantenimiento es sumamente sencillo y r\u00e1pido\u201d.<\/p>\n<p style=\"text-align: right;\"><strong>- Carlos M. (Burgos, Espa\u00f1a) <\/strong><\/p>\n              <\/div>\r\n            <\/div>\r\n                      <div class=\"el-slider-text__slide\">\r\n              <div class=\"el-slider-text__slide-inner balance-elements\" style=\"background-color: #00549D; color: #ffffff; \">\r\n                <p>\"Imprescindible. Esa es la palabra exacta para describir lo que ha sido para mi un antes y un despu\u00e9s en mi calidad de vida. Recuerdo perfectamente aquel d\u00eda que recib\u00ed el informe donde se me indicaba que padec\u00eda de apnea severa con tan solo 29 a\u00f1os, incre\u00edble pero cierto. Me explicaron que derivado de mi apnea no lograba llegar a la fase REM de descanso reparador y notaba que me despertaba como si no hubiera descansado pr\u00e1cticamente, afectando a mi rendimiento laboral y vida personal. Buscando soluciones la doctora puso sobre la mesa probar este novedoso dispositivo en lugar del CPAP tan aparatoso, molesto y triste para alguien tan joven. Los avances tecnol\u00f3gicos siempre son bienvenidos y apost\u00e9 por \u00e9l sin dudar. La adaptaci\u00f3n al aparato fue bastante r\u00e1pida, despert\u00e1ndome tras la primera noche sintiendo una mejor\u00eda a nivel general indescriptible. \u00bfSabes esa sensaci\u00f3n de haber descansado plenamente? Exacto, justo esa. Cu\u00e1nto lo echaba de menos. Mejorando mi descanso mejor\u00e9 otros problemas asociados que ten\u00eda, entre ellos digestivo, ya que me sent\u00eda muy hinchado por la falta de descanso. Empec\u00e9 a perder peso y a notar una energ\u00eda que no ten\u00eda desde a\u00f1os. Desde aquel primer d\u00eda me sigue acompa\u00f1ando cada noche, en casa o de viaje y sinceramente espero que tengamos una relaci\u00f3n de larga duraci\u00f3n. Yo ser\u00e9 fiel y espero ser correspondido\".\u00a0<\/p>\n<p style=\"text-align: right;\"><strong>Alberto (Madrid, Espa\u00f1a)<\/strong><\/p>\n              <\/div>\r\n            <\/div>\r\n                      <div class=\"el-slider-text__slide\">\r\n              <div class=\"el-slider-text__slide-inner balance-elements\" style=\"background-color: #00549D; color: #ffffff; \">\r\n                <p>\u201cUn gran invento para el descanso y no es Pikolin. Y es que no dormir ni dejar dormir por respirar como los b\u00fafalos se acab\u00f3. El bozalito, as\u00ed le llamamos en casa, es uno m\u00e1s de la familia. Te lo pones por la noche y la paz reina en la habitaci\u00f3n. La verdad es que no siempre lo utilizo y no s\u00e9 porque; quiz\u00e1 cuando veo a mi pareja muy cansada, creo que no le voy a despertar o por descanso del personal (como en los bares).<br \/>\nLo que s\u00ed puedo decir es que, si te lo pones, las ma\u00f1anas son de luz y de color, y te alegras porque sabes que esa noche si has descansado como te mereces.<br \/>\nPues eso, estoy feliz con mi bozalito. Se lo recomiendo a todo b\u00fafalo nocturno. Y la verdad es mucho m\u00e1s sexi que la m\u00e1quina roncadora de la Seguridad Social\u201d.<\/p>\n<p style=\"text-align: right;\"><strong>Jota (Valencia, Espa\u00f1a) <\/strong><\/p>\n              <\/div>\r\n            <\/div>\r\n                  <\/div>\r\n      <\/div>\r\n\r\n      <script>\r\n        jQuery(document).ready(function($) {\r\n          $('#el-slider-text-6a04a39dcec5f .el-slider-text__slider').slick({\r\n            centerMode: true,\r\n            centerPadding: '300px',\r\n            slidesToShow: 2,\r\n            arrows: true,\r\n            dots: false,\r\n            infinite: true,\r\n            responsive: [\r\n              {\r\n                breakpoint: 1600,\r\n                settings: {\r\n                  arrows: false,\r\n                  dots: true,\r\n                  centerPadding: '150px',\r\n                  slidesToShow: 2\r\n                }\r\n              },\r\n              {\r\n                breakpoint: 768,\r\n                settings: {\r\n                  arrows: false,\r\n                  dots: true,\r\n                  centerPadding: '5px',\r\n                  slidesToShow: 1\r\n                }\r\n              }\r\n            ]\r\n          });\r\n        });\r\n      <\/script>\r\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u00bfQu\u00e9 es la apnea obstructiva del sue\u00f1o (AOS)? La apnea obstructiva del sue\u00f1o (AOS) es un trastorno en el que la respiraci\u00f3n se interrumpe involuntariamente por breves lapsos de tiempo durante el sue\u00f1o. Est\u00e1 causada normalmente por el estrechamiento de las v\u00edas respiratorias en la parte posterior de la garganta. Esas interrupciones de la respiraci\u00f3n &#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":576,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-322","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/somnomed.com\/es\/wp-json\/wp\/v2\/pages\/322","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/somnomed.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/somnomed.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/somnomed.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/somnomed.com\/es\/wp-json\/wp\/v2\/comments?post=322"}],"version-history":[{"count":3,"href":"https:\/\/somnomed.com\/es\/wp-json\/wp\/v2\/pages\/322\/revisions"}],"predecessor-version":[{"id":17800,"href":"https:\/\/somnomed.com\/es\/wp-json\/wp\/v2\/pages\/322\/revisions\/17800"}],"up":[{"embeddable":true,"href":"https:\/\/somnomed.com\/es\/wp-json\/wp\/v2\/pages\/576"}],"wp:attachment":[{"href":"https:\/\/somnomed.com\/es\/wp-json\/wp\/v2\/media?parent=322"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}