{"id":3544,"date":"2021-07-05T05:00:40","date_gmt":"2021-07-05T09:00:40","guid":{"rendered":"http:\/\/somnomed.gsqtest1.com\/en\/?page_id=3544"},"modified":"2025-07-31T10:52:08","modified_gmt":"2025-07-31T08:52:08","slug":"somnodent-avant","status":"publish","type":"page","link":"https:\/\/somnomed.com\/es\/dentists\/products-somnodent\/somnodent\/somnodent-avant\/","title":{"rendered":"SomnoDent Avant<sup>\u00ae<\/sup>"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"3544\" class=\"elementor elementor-3544\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-628e76e2 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"628e76e2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1bf411e8\" data-id=\"1bf411e8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-721a329 elementor-widget elementor-widget-shortcode\" data-id=\"721a329\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div id=\"sm360_view-avant\" class=\"sm360-viewer-container sm360-embed\" style=\"width:550px; height:450px; background-color:#ffffff;\" data-config=\"\/wp-content\/themes\/somnomed-2021\/assets\/files-2\/products-360\/avant\/SOMNOMED.xml\" data-rootpath=\"\" data-skin=\"modern\"><\/div><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2852b73 elementor-widget elementor-widget-image\" data-id=\"2852b73\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1000\" height=\"191\" src=\"https:\/\/somnomed.com\/es\/wp-content\/uploads\/sites\/14\/2025\/07\/SomnoDent-Avant-logo.jpg\" class=\"attachment-large size-large wp-image-17708\" alt=\"\" srcset=\"https:\/\/somnomed.com\/es\/wp-content\/uploads\/sites\/14\/2025\/07\/SomnoDent-Avant-logo.jpg 1000w, https:\/\/somnomed.com\/es\/wp-content\/uploads\/sites\/14\/2025\/07\/SomnoDent-Avant-logo-300x57.jpg 300w, https:\/\/somnomed.com\/es\/wp-content\/uploads\/sites\/14\/2025\/07\/SomnoDent-Avant-logo-768x147.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7894c723\" data-id=\"7894c723\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-7e3e568b elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"7e3e568b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-280a8fb1\" data-id=\"280a8fb1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-34b36f03 elementor-widget elementor-widget-heading\" data-id=\"34b36f03\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">SomnoDent Avant<sup>\u00ae<\/sup><\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-42a0f20b elementor-widget elementor-widget-text-editor\" data-id=\"42a0f20b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<blockquote><p>SomnoDent Avant es nuestra f\u00e9rula m\u00e1s c\u00f3moda hasta ahora. Las f\u00e9rulas superior e inferior han sido dise\u00f1adas por ordenador y fabricadas con robots para adaptarse a la forma de su dentadura. Est\u00e1n elaboradas en una \u00fanica pieza de material acr\u00edlico dental que las hace m\u00e1s resistentes y duraderas.<\/p><p><span style=\"color: var( --e-global-color-text );\">La comodidad de los aparatos SomnoDent<sup><sup>\u00ae<\/sup>\u00a0<\/sup> se debe nuestro revestimiento exclusivo b-flex Comfort Liner<sup>\u00ae<\/sup>, se amolda y se sujeta a la dentadura minimizando los movimientos dentales. Al ser m\u00e1s c\u00f3moda, es m\u00e1s probable que el paciente la use y que, por lo tanto, cumpla mejor su tratamiento contra la apnea del sue\u00f1o.<\/span><\/p><p>\u201cAjuste a la primera\u201d de la f\u00e9rula gracias al escaneado bucal y registros de mordida por parte del dentista y sin necesidad de modificaciones posteriores.<\/p><p>El dise\u00f1o innovador de SomnoDent Avant induce al paciente a cerrar suavemente la boca y, por lo tanto, a respirar por la nariz mientras duerme. Con eso se eliminan los ronquidos en la mayor\u00eda de personas y se evita la sensaci\u00f3n de sequedad en la boca (queja habitual con otras f\u00e9rulas y con m\u00e1quinas CPAP).<\/p><\/blockquote>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-3b48deee elementor-section-content-middle elementor-section-full_width elementor-reverse-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"3b48deee\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5f064852 padding-col--left\" data-id=\"5f064852\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-4e1a1f01 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"4e1a1f01\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-385d9dd7\" data-id=\"385d9dd7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1451824a elementor-widget elementor-widget-heading\" data-id=\"1451824a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">C\u00f3mo fabricamos SomnoDent Avant <\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-41eb93d9 elementor-widget elementor-widget-text-editor\" data-id=\"41eb93d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<blockquote><blockquote><p>La fabricaci\u00f3n de SomnoDent\u00a0Avant\u00a0comienza con una fotograf\u00eda digital de su dentadura que nos env\u00eda su dentista. Con esta fotograf\u00eda, SomnoMed\u00a0 dise\u00f1a un dispositivo oral espec\u00edficamente adaptado a la forma de su dentadura y maxilar utilizando herramientas de dise\u00f1o asistido por ordenador o herramientas CAD\/CAM.<\/p><\/blockquote><p>Una vez creado el molde, empezamos a fabricar el dispositivo oral con ayuda de robots fresadores controlados por ordenador. El robot talla su modelo en un bloque monol\u00edtico de pl\u00e1stico dental, ya que los estudios demuestran que de esa manera se consiguen f\u00e9rulas m\u00e1s resistentes. A continuaci\u00f3n, a\u00f1adimos el suave revestimiento interior b-flex Comfort Liner para un m\u00e1ximo confort y pulimos la f\u00e9rula para eliminar posibles bordes afilados y sea c\u00f3moda en su boca.<\/p><p>Cuando la f\u00e9rula est\u00e1 fabricada, la probamos utilizando un modelo impreso en 3D de sus dientes\u00a0 y verificamos que se ajuste bien, que no se salga y que siga exactamente las especificaciones facilitadas por su dentista. Finalmente, se la enviamos a su odont\u00f3logo y en un plazo de 14 d\u00edas ya puede empezar su tratamiento para la apnea del sue\u00f1o.\u00a0<\/p><p>Para m\u00e1s informaci\u00f3n sobre la fabricaci\u00f3n de nuestras f\u00e9rulas, haga clic en la imagen para ver el v\u00eddeo.\u00a0<\/p><\/blockquote>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-63ca8f43\" data-id=\"63ca8f43\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6bb56aaa elementor-widget elementor-widget-video\" data-id=\"6bb56aaa\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=mIefldHMb5k&quot;,&quot;lazy_load&quot;:&quot;yes&quot;,&quot;show_image_overlay&quot;:&quot;yes&quot;,&quot;image_overlay&quot;:{&quot;url&quot;:&quot;http:\\\/\\\/somnomed.co\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/07\\\/SomTabs-and-Products-USA-20.jpg&quot;,&quot;id&quot;:&quot;3470&quot;,&quot;size&quot;:&quot;&quot;},&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t\t\t<div class=\"elementor-custom-embed-image-overlay\" style=\"background-image: url(https:\/\/somnomed.com\/es\/wp-content\/uploads\/sites\/14\/2021\/07\/SomTabs-and-Products-USA-20.jpg);\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-custom-embed-play\" role=\"button\" aria-label=\"Reproducir v\u00eddeo\" tabindex=\"0\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-play\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-6a149cdd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6a149cdd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1d5ebbc1\" data-id=\"1d5ebbc1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-aecf4c3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"aecf4c3\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-38a339c3\" data-id=\"38a339c3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1e6d119 elementor-widget elementor-widget-spacer\" data-id=\"1e6d119\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-1f73613d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1f73613d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-54d5216b\" data-id=\"54d5216b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4dc0aba5 elementor-widget elementor-widget-heading\" data-id=\"4dc0aba5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nuestro compromiso de calidad<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e175669 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"4e175669\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-2de7b3d6 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2de7b3d6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2f8a9d1a\" data-id=\"2f8a9d1a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4d05c6e4 elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"4d05c6e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tISO 13485\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tTodos los dispositivos orales se fabrican de acuerdo con las normas ISO 13485 para ofrecer productos m\u00e9dicos de calidad.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-359627d elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"359627d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-microscope\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tMonitorizaci\u00f3n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tSeguimiento de principio a fin de su dispositivo durante la producci\u00f3n, desde los escaneos hasta la fabricaci\u00f3n y la entrega.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f30126d elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"7f30126d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-file-medical\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tMateriales de calidad m\u00e9dica\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tMateriales probados y comprobados que incluyen el acr\u00edlico dental y el revestimiento interior b-flex Comfort Liner. \t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-158f635f elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"158f635f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-laptop\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tOrden de pedido online \t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tPedidos online y pago de facturas (solo en EE. UU. y ANZ, pr\u00f3ximamente en otros mercados).\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1540c664 elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"1540c664\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-star\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tAjuste a la primera \t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tRevisi\u00f3n de las medidas tomadas con el esc\u00e1ner intraoral o las impresiones antes de la fabricaci\u00f3n del dispositivo para garantizar que sea c\u00f3modo para el paciente.\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-60ae817c elementor-widget elementor-widget-spacer\" data-id=\"60ae817c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e4b34b6\" data-id=\"e4b34b6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-27d408d elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"27d408d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-68d1d5bd\" data-id=\"68d1d5bd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c1ad4a5 elementor-widget elementor-widget-template\" data-id=\"c1ad4a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"241\" class=\"elementor elementor-241\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-4442681 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"4442681\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8ae51aa\" data-id=\"8ae51aa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2bc5e5c elementor-widget elementor-widget-heading\" data-id=\"2bc5e5c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nuestros pacientes cuentan su historia<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fb7c08b elementor-widget elementor-widget-Custom_El_Slider_Text\" data-id=\"fb7c08b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"Custom_El_Slider_Text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t          <div id=\"el-slider-text-6a04cfdeab7a3\" class=\"el-slider-text\">\r\n        <div class=\"el-slider-text__slider\">\r\n                      <div class=\"el-slider-text__slide\">\r\n              <div class=\"el-slider-text__slide-inner balance-elements\" style=\"background-color: #C3E7EF; color: #000000; \">\r\n                <p>\u201cTras hacer una investigaci\u00f3n de mercado, el dispositivo oral de SomnoMed me pareci\u00f3 el m\u00e1s interesante y me puse manos a la obra. Despu\u00e9s del estudio por parte del especialista en maxilofacial pude empezar mi tratamiento en junio de 2020 y para m\u00ed est\u00e1 funcionando a pleno rendimiento. Sigo teniendo apneas, pocas y cortas (tambi\u00e9n con la CPAP, por otra parte) pero mi vida ha cambiado sustancialmente ya que no necesito dormir al lado de una fuente de electricidad, ya no tengo la presi\u00f3n de la m\u00e1scara en la piel d\u00eda y noche, me he quitado el estigma de la apnea en la cara y, adem\u00e1s, este DAM es muy confortable. Si antes ten\u00eda que dormir con una f\u00e9rula de descarga (tambi\u00e9n soy bruxista) pues ahora duermo con un dispositivo oral de SomnoMed que tambi\u00e9n lo trata.<br \/>\nAdem\u00e1s, en cuanto me retiro el dispositivo oral por la ma\u00f1ana hago ejercicios para no da\u00f1ar mi ATM.<br \/>\nEstoy muy contenta ya que puedo descansar todas las noches y me resulta f\u00e1cil el uso de este dispositivo\u201d.<\/p>\n<p style=\"text-align: right;\"><strong>- Aurora C. (Vitoria, Espa\u00f1a)<\/strong><\/p>\n              <\/div>\r\n            <\/div>\r\n                      <div class=\"el-slider-text__slide\">\r\n              <div class=\"el-slider-text__slide-inner balance-elements\" style=\"background-color: #C1CAE3; color: #000000; \">\r\n                <p>\u201cSupe de SomnoMed a ra\u00edz de un comentario que me hizo un amigo que ten\u00eda el mismo problema que yo a la hora de dormir, y su favorable experiencia con las f\u00e9rulas SomnoMed.<br \/>\nAs\u00ed que fui al dentista que le hab\u00eda atendido. Tras obtener la impresi\u00f3n de mis dientes y en cuesti\u00f3n de unos pocos d\u00edas comenzamos a ajustar las f\u00e9rulas hasta lograr la posici\u00f3n \u00f3ptima en unas pocas semanas. La adaptaci\u00f3n a ellas no supuso ning\u00fan problema.<br \/>\nDesde entonces puedo disfrutar de noches tranquilas y sin molestar a nadie. Adem\u00e1s, su limpieza y mantenimiento es sumamente sencillo y r\u00e1pido\u201d.<\/p>\n<p style=\"text-align: right;\"><strong>- Carlos M. (Burgos, Espa\u00f1a) <\/strong><\/p>\n              <\/div>\r\n            <\/div>\r\n                      <div class=\"el-slider-text__slide\">\r\n              <div class=\"el-slider-text__slide-inner balance-elements\" style=\"background-color: #00549D; color: #ffffff; \">\r\n                <p>\"Imprescindible. Esa es la palabra exacta para describir lo que ha sido para mi un antes y un despu\u00e9s en mi calidad de vida. Recuerdo perfectamente aquel d\u00eda que recib\u00ed el informe donde se me indicaba que padec\u00eda de apnea severa con tan solo 29 a\u00f1os, incre\u00edble pero cierto. Me explicaron que derivado de mi apnea no lograba llegar a la fase REM de descanso reparador y notaba que me despertaba como si no hubiera descansado pr\u00e1cticamente, afectando a mi rendimiento laboral y vida personal. Buscando soluciones la doctora puso sobre la mesa probar este novedoso dispositivo en lugar del CPAP tan aparatoso, molesto y triste para alguien tan joven. Los avances tecnol\u00f3gicos siempre son bienvenidos y apost\u00e9 por \u00e9l sin dudar. La adaptaci\u00f3n al aparato fue bastante r\u00e1pida, despert\u00e1ndome tras la primera noche sintiendo una mejor\u00eda a nivel general indescriptible. \u00bfSabes esa sensaci\u00f3n de haber descansado plenamente? Exacto, justo esa. Cu\u00e1nto lo echaba de menos. Mejorando mi descanso mejor\u00e9 otros problemas asociados que ten\u00eda, entre ellos digestivo, ya que me sent\u00eda muy hinchado por la falta de descanso. Empec\u00e9 a perder peso y a notar una energ\u00eda que no ten\u00eda desde a\u00f1os. Desde aquel primer d\u00eda me sigue acompa\u00f1ando cada noche, en casa o de viaje y sinceramente espero que tengamos una relaci\u00f3n de larga duraci\u00f3n. Yo ser\u00e9 fiel y espero ser correspondido\".\u00a0<\/p>\n<p style=\"text-align: right;\"><strong>Alberto (Madrid, Espa\u00f1a)<\/strong><\/p>\n              <\/div>\r\n            <\/div>\r\n                      <div class=\"el-slider-text__slide\">\r\n              <div class=\"el-slider-text__slide-inner balance-elements\" style=\"background-color: #00549D; color: #ffffff; \">\r\n                <p>\u201cUn gran invento para el descanso y no es Pikolin. Y es que no dormir ni dejar dormir por respirar como los b\u00fafalos se acab\u00f3. El bozalito, as\u00ed le llamamos en casa, es uno m\u00e1s de la familia. Te lo pones por la noche y la paz reina en la habitaci\u00f3n. La verdad es que no siempre lo utilizo y no s\u00e9 porque; quiz\u00e1 cuando veo a mi pareja muy cansada, creo que no le voy a despertar o por descanso del personal (como en los bares).<br \/>\nLo que s\u00ed puedo decir es que, si te lo pones, las ma\u00f1anas son de luz y de color, y te alegras porque sabes que esa noche si has descansado como te mereces.<br \/>\nPues eso, estoy feliz con mi bozalito. Se lo recomiendo a todo b\u00fafalo nocturno. Y la verdad es mucho m\u00e1s sexi que la m\u00e1quina roncadora de la Seguridad Social\u201d.<\/p>\n<p style=\"text-align: right;\"><strong>Jota (Valencia, Espa\u00f1a) <\/strong><\/p>\n              <\/div>\r\n            <\/div>\r\n                  <\/div>\r\n      <\/div>\r\n\r\n      <script>\r\n        jQuery(document).ready(function($) {\r\n          $('#el-slider-text-6a04cfdeab7a3 .el-slider-text__slider').slick({\r\n            centerMode: true,\r\n            centerPadding: '300px',\r\n            slidesToShow: 2,\r\n            arrows: true,\r\n            dots: false,\r\n            infinite: true,\r\n            responsive: [\r\n              {\r\n                breakpoint: 1600,\r\n                settings: {\r\n                  arrows: false,\r\n                  dots: true,\r\n                  centerPadding: '150px',\r\n                  slidesToShow: 2\r\n                }\r\n              },\r\n              {\r\n                breakpoint: 768,\r\n                settings: {\r\n                  arrows: false,\r\n                  dots: true,\r\n                  centerPadding: '5px',\r\n                  slidesToShow: 1\r\n                }\r\n              }\r\n            ]\r\n          });\r\n        });\r\n      <\/script>\r\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>SomnoDent Avant\u00ae SomnoDent Avant es nuestra f\u00e9rula m\u00e1s c\u00f3moda hasta ahora. Las f\u00e9rulas superior e inferior han sido dise\u00f1adas por ordenador y fabricadas con robots para adaptarse a la forma de su dentadura. Est\u00e1n elaboradas en una \u00fanica pieza de material acr\u00edlico dental que las hace m\u00e1s resistentes y duraderas. La comodidad de los aparatos &#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":3540,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-3544","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/somnomed.com\/es\/wp-json\/wp\/v2\/pages\/3544","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/somnomed.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/somnomed.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/somnomed.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/somnomed.com\/es\/wp-json\/wp\/v2\/comments?post=3544"}],"version-history":[{"count":3,"href":"https:\/\/somnomed.com\/es\/wp-json\/wp\/v2\/pages\/3544\/revisions"}],"predecessor-version":[{"id":17774,"href":"https:\/\/somnomed.com\/es\/wp-json\/wp\/v2\/pages\/3544\/revisions\/17774"}],"up":[{"embeddable":true,"href":"https:\/\/somnomed.com\/es\/wp-json\/wp\/v2\/pages\/3540"}],"wp:attachment":[{"href":"https:\/\/somnomed.com\/es\/wp-json\/wp\/v2\/media?parent=3544"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}