{"id":748,"date":"2021-06-10T00:55:25","date_gmt":"2021-06-10T04:55:25","guid":{"rendered":"https:\/\/local.somnomed.com\/en\/?page_id=748"},"modified":"2025-10-14T06:01:32","modified_gmt":"2025-10-14T04:01:32","slug":"about-us","status":"publish","type":"page","link":"https:\/\/somnomed.com\/es\/about-us\/","title":{"rendered":"Sobre nosotros"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"748\" class=\"elementor elementor-748\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-5a6518c6 elementor-section-content-top elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"5a6518c6\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-20935e85\" data-id=\"20935e85\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4af27cd elementor-widget elementor-widget-image\" data-id=\"4af27cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1280\" height=\"800\" src=\"https:\/\/somnomed.com\/es\/wp-content\/uploads\/sites\/14\/2025\/08\/Over-SomnoMed.jpg\" class=\"attachment-full size-full wp-image-17822\" alt=\"\" srcset=\"https:\/\/somnomed.com\/es\/wp-content\/uploads\/sites\/14\/2025\/08\/Over-SomnoMed.jpg 1280w, https:\/\/somnomed.com\/es\/wp-content\/uploads\/sites\/14\/2025\/08\/Over-SomnoMed-300x188.jpg 300w, https:\/\/somnomed.com\/es\/wp-content\/uploads\/sites\/14\/2025\/08\/Over-SomnoMed-1024x640.jpg 1024w, https:\/\/somnomed.com\/es\/wp-content\/uploads\/sites\/14\/2025\/08\/Over-SomnoMed-768x480.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3b29c40 padding-col--right\" data-id=\"3b29c40\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-63116baf elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"63116baf\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-7518b2cb\" data-id=\"7518b2cb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-16e8be6d elementor-widget elementor-widget-heading\" data-id=\"16e8be6d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Qui\u00e9nes somos<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a48a1d2 elementor-widget elementor-widget-text-editor\" data-id=\"5a48a1d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>SomnoMed<span style=\"font-size: 12pt;\"><sup>\u00ae<\/sup><\/span>, fundada en 2004, es un compa\u00f1\u00eda de dispositivos m\u00e9dicos cotizada en el \u00edndice ASX con presencia en 28 pa\u00edses. <\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-14e2831 elementor-widget elementor-widget-text-editor\" data-id=\"14e2831\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Con sede en S\u00eddney (Australia) y oficinas en Europa y Estados Unidos, SomnoMed se dedica al desarrollo y fabricaci\u00f3n de dispositivos m\u00e9dicos cl\u00ednicamente probados para el tratamiento de la apnea obstructiva del sue\u00f1o (AOS).\u00a0 Pacientes de todo el mundo con AOS leve o moderada han recibido tratamiento con \u00e9xito gracias a nuestras f\u00e9rulas dentales.<\/p><p>SomnoMed es l\u00edder mundial en el desarrollo de f\u00e9rulas para AOS, fabricadas todas y cada una de ellas adaptadas al paciente\u00a0 usando las t\u00e9cnicas m\u00e1s avanzadas, y proporciona soluciones precisas, c\u00f3modas y que encajan perfectamente a la primera. La mejora continuada de los productos SomnoMed garantiza unas f\u00e9rulas para medicina del sue\u00f1o de eficacia y comodidad insuperables. Nuestras f\u00e9rulas han obtenido la autorizaci\u00f3n 510(K) de la FDA (Administraci\u00f3n para Alimentos y Medicamentos de EE.UU.) y se fabrican conforme al est\u00e1ndar de calidad ISO 13485.<\/p><p>En SomnoMed, nuestro compromiso es ofrecer una alternativa c\u00f3moda y efectiva al tratamiento de la apnea obstructiva del sue\u00f1o con CPAP que sea eficaz y est\u00e9 cl\u00ednicamente probada, y nos entregamos con pasi\u00f3n a lograr que nuestros pacientes recobren las riendas de su vida durmiendo pl\u00e1cidamente mientras se tratan de forma efectiva contra la AOS.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-355ceaf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"355ceaf\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a813d93\" data-id=\"a813d93\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-434105b elementor-widget elementor-widget-spacer\" data-id=\"434105b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-f5a4de5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f5a4de5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0d61271\" data-id=\"0d61271\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9052d4d elementor-widget elementor-widget-heading\" data-id=\"9052d4d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nuestra misi\u00f3n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-4fd5b97 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4fd5b97\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a8c6362\" data-id=\"a8c6362\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-d8f593e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d8f593e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e491bb2\" data-id=\"e491bb2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-00e6de7 elementor-widget elementor-widget-text-editor\" data-id=\"00e6de7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><em><span style=\"font-family: arial, helvetica, sans-serif;\">Como lider mundial en terapia con dispositivos orales, establecemos el est\u00e1ndar en cuanto a resultados, innovaci\u00f3n y experiencia del paciente, impulsando la transformaci\u00f3n de la medicina del sue\u00f1o en todo el mundo.<\/span><\/em><\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-7bb779c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7bb779c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ac939e8\" data-id=\"ac939e8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d0e568b elementor-widget elementor-widget-spacer\" data-id=\"d0e568b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-e2e1c65 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"e2e1c65\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-98c29f1\" data-id=\"98c29f1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-092d7ae elementor-widget elementor-widget-heading\" data-id=\"092d7ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nuestra historia<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-9c8adc1 elementor-section-full_width elementor-section-height-min-height elementor-section-height-default elementor-section-items-middle\" data-id=\"9c8adc1\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-93335a0\" data-id=\"93335a0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8830be7 elementor-widget elementor-widget-Custom_El_Slider_Text\" data-id=\"8830be7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"Custom_El_Slider_Text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t          <div id=\"el-slider-text-6a04b889578bc\" class=\"el-slider-text\">\r\n        <div class=\"el-slider-text__slider\">\r\n                      <div class=\"el-slider-text__slide\">\r\n              <div class=\"el-slider-text__slide-inner balance-elements\" style=\"background-color: #FFFFFF; color: #3D3D3D; \">\r\n                <h2 style=\"text-align: center;\"><span style=\"font-family: arial, helvetica, sans-serif;\"><strong><span style=\"color: #00549d!important;\">2005<\/span><\/strong><\/span><\/h2>\n<p style=\"text-align: left;\"><span style=\"font-family: arial, helvetica, sans-serif;\">Lanzamiento de SomnoDent Classic, la primera f\u00e9rula dental con aleta dorsal para el tratamiento de la AOS. <\/span><\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-9876\" src=\"https:\/\/somnomed.com\/en\/wp-content\/uploads\/sites\/2\/2021\/08\/Untitled-design-2.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><img decoding=\"async\" class=\"aligncenter size-medium wp-image-3845\" src=\"https:\/\/somnomed.com\/en\/wp-content\/uploads\/sites\/2\/2021\/07\/SomnoDent-Classic-angle-product-image.jpg\" alt=\"\" width=\"1\" height=\"1\" \/><\/p>\n              <\/div>\r\n            <\/div>\r\n                      <div class=\"el-slider-text__slide\">\r\n              <div class=\"el-slider-text__slide-inner balance-elements\" style=\"background-color: #FFFFFF; color: #3D3D3D; \">\r\n                <h2 style=\"text-align: center;\"><span style=\"font-family: arial, helvetica, sans-serif;\"><strong><span style=\"color: #00549d!important;\">2006<\/span><\/strong><\/span><\/h2>\n<p style=\"text-align: left;\">SomnoMed empieza a comercializar f\u00e9rulas SomnoDent en Am\u00e9rica del Norte.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-10019\" src=\"https:\/\/somnomed.com\/en\/wp-content\/uploads\/sites\/2\/2021\/08\/Untitled-design-17.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><\/p>\n              <\/div>\r\n            <\/div>\r\n                      <div class=\"el-slider-text__slide\">\r\n              <div class=\"el-slider-text__slide-inner balance-elements\" style=\"background-color: #FFFFFF; color: #3D3D3D; \">\r\n                <h2 style=\"text-align: center;\"><span style=\"font-family: arial, helvetica, sans-serif;\"><strong><span style=\"color: #00549d!important;\">2008<\/span><\/strong><\/span><\/h2>\n<p>SomnoMed incorpora la tecnolog\u00eda SMH BFlex a SomnoDent Classic, naciendo as\u00ed SomnoDent Flex. El revestimiento interior SMH BFlex ofrece una comodidad y encaje superiores a diferencia de otros modelos con ganchos de bola. SomnoDent Flex se convierte en la marca l\u00edder de ventas de SomnoMed.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-10014\" src=\"https:\/\/somnomed.com\/en\/wp-content\/uploads\/sites\/2\/2021\/08\/Untitled-design-15.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><\/p>\n              <\/div>\r\n            <\/div>\r\n                      <div class=\"el-slider-text__slide\">\r\n              <div class=\"el-slider-text__slide-inner balance-elements\" style=\"background-color: #FFFFFF; color: #3D3D3D; \">\r\n                <h2 style=\"text-align: center;\"><span style=\"font-family: arial, helvetica, sans-serif;\"><strong><span style=\"color: #00549d!important;\">2012<\/span><\/strong><\/span><\/h2>\n<p>SomnoMed lanza SomnoDent G2, una f\u00e9rula dental sin componentes met\u00e1licos para la apnea del sue\u00f1o.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-10010\" src=\"https:\/\/somnomed.com\/en\/wp-content\/uploads\/sites\/2\/2021\/08\/Untitled-design-14.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><\/p>\n              <\/div>\r\n            <\/div>\r\n                      <div class=\"el-slider-text__slide\">\r\n              <div class=\"el-slider-text__slide-inner balance-elements\" style=\"background-color: #FFFFFF; color: #3D3D3D; \">\r\n                <h2 style=\"text-align: center;\"><span style=\"font-family: arial, helvetica, sans-serif;\"><strong><span style=\"color: #00549d!important;\">2013<\/span><\/strong><\/span><\/h2>\n<p>SomnoDent lanza la f\u00e9rula dental para apnea del sue\u00f1o Herbst en el mercado de Medicaid\/ Medicare de EE.UU.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-3731\" src=\"https:\/\/somnomed.com\/en\/wp-content\/uploads\/sites\/2\/2021\/07\/Herbst-Advance-angled.jpg\" alt=\"\" width=\"1\" height=\"1\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-10474\" src=\"https:\/\/somnomed.com\/au\/wp-content\/uploads\/sites\/4\/2021\/08\/Untitled-design-5.png\" alt=\"\" width=\"312\" height=\"208\" \/><\/p>\n              <\/div>\r\n            <\/div>\r\n                      <div class=\"el-slider-text__slide\">\r\n              <div class=\"el-slider-text__slide-inner balance-elements\" style=\"background-color: #FFFFFF; color: #3D3D3D; \">\r\n                <h2 style=\"text-align: center;\"><span style=\"font-family: arial, helvetica, sans-serif;\"><strong><span style=\"color: #00549d!important;\">2014<\/span><\/strong><\/span><\/h2>\n<p>Lanzamiento de SomnoDent Fusion sobre la base del \u00e9xito de SMH BFlex y SomnoDent Flex. Adem\u00e1s de incluir las prestaciones de los modelos anteriores, SomnoDent Fusion dispone de 3 alas extra\u00edbles que aumentan su protrusi\u00f3n y eficacia.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-9980\" src=\"https:\/\/somnomed.com\/en\/wp-content\/uploads\/sites\/2\/2021\/08\/Untitled-design-11.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><\/p>\n              <\/div>\r\n            <\/div>\r\n                      <div class=\"el-slider-text__slide\">\r\n              <div class=\"el-slider-text__slide-inner balance-elements\" style=\"background-color: #FFFFFF; color: #3D3D3D; \">\r\n                <h2 style=\"text-align: center;\"><span style=\"font-family: arial, helvetica, sans-serif;\"><strong><span style=\"color: #00549d!important;\">2014<\/span><\/strong><\/span><\/h2>\n<p>Lanzamiento de SomnoDent Herbst <em>Advance<\/em>, primera f\u00e9rula intraoral con indicador visual de calibrado que permite determinar el grado de protrusi\u00f3n de la f\u00e9rula. \u00a0\u00a0<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-9984\" src=\"https:\/\/somnomed.com\/en\/wp-content\/uploads\/sites\/2\/2021\/08\/Untitled-design-12.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><\/p>\n              <\/div>\r\n            <\/div>\r\n                      <div class=\"el-slider-text__slide\">\r\n              <div class=\"el-slider-text__slide-inner balance-elements\" style=\"background-color: #FFFFFF; color: #3D3D3D; \">\r\n                <h2 style=\"text-align: center;\"><span style=\"font-family: arial, helvetica, sans-serif;\"><strong><span style=\"color: #00549d!important;\">2015<\/span><\/strong><\/span><\/h2>\n<p>Se incorporan a las f\u00e9rulas SomnoMed las Grabadoras de Cumplimiento Dentitrac<sup>\u00ae<\/sup>, que permiten una medici\u00f3n objetiva del seguimiento del tratamiento para cada paciente.<\/p>\n<p><span style=\"font-family: arial, helvetica, sans-serif;\"><br \/><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-9927\" src=\"https:\/\/somnomed.com\/en\/wp-content\/uploads\/sites\/2\/2021\/08\/Untitled-design-8.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><br \/><\/span><\/p>\n              <\/div>\r\n            <\/div>\r\n                      <div class=\"el-slider-text__slide\">\r\n              <div class=\"el-slider-text__slide-inner balance-elements\" style=\"background-color: #FFFFFF; color: #3D3D3D; \">\r\n                <h2 style=\"text-align: center;\"><span style=\"font-family: arial, helvetica, sans-serif;\"><strong><span style=\"color: #00549d!important;\">2015<\/span><\/strong><\/span><\/h2>\n<p>SomnoMed adquiere Strong Dental y ampl\u00eda sus actividades a Canad\u00e1, incorporando tambi\u00e9n la f\u00e9rula SUAD a la l\u00ednea de f\u00e9rulas SomnoDent.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-9941\" src=\"https:\/\/somnomed.com\/en\/wp-content\/uploads\/sites\/2\/2021\/08\/Untitled-design-10.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><\/p>\n              <\/div>\r\n            <\/div>\r\n                      <div class=\"el-slider-text__slide\">\r\n              <div class=\"el-slider-text__slide-inner balance-elements\" style=\"background-color: #FFFFFF; color: #3D3D3D; \">\r\n                <h2 style=\"text-align: center;\"><span style=\"font-family: arial, helvetica, sans-serif;\"><strong><span style=\"color: #00549d!important;\">2016<\/span><\/strong><\/span><\/h2>\n<p>SomnoMed presenta Morning Repositioner, un desprogramador de mordida dise\u00f1ado para devolver el maxilar del paciente a su posici\u00f3n normal tras el sue\u00f1o.<\/p>\n<p>Presentaci\u00f3n de SomnoDent Alpha, un dispositivo de transici\u00f3n que permite a los m\u00e9dicos evaluar la respuesta potencial del paciente al avance mandibular y establecer si tolera una f\u00e9rula.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-9901\" src=\"https:\/\/somnomed.com\/en\/wp-content\/uploads\/sites\/2\/2021\/08\/Untitled-design-6.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><\/p>\n              <\/div>\r\n            <\/div>\r\n                      <div class=\"el-slider-text__slide\">\r\n              <div class=\"el-slider-text__slide-inner balance-elements\" style=\"background-color: #FFFFFF; color: #3D3D3D; \">\r\n                <h2 style=\"text-align: center;\"><span style=\"font-family: arial, helvetica, sans-serif;\"><strong><span style=\"color: #00549d!important;\">2017<\/span><\/strong><\/span><\/h2>\n<p>Lanzamiento de SomGauge, registro de mordida esterilizable en autoclave, que permite a profesionales tomar f\u00e1cilmente unos registros de mordida m\u00e1s fiables y precisos.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-9894\" src=\"https:\/\/somnomed.com\/en\/wp-content\/uploads\/sites\/2\/2021\/08\/Untitled-design-5.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><\/p>\n              <\/div>\r\n            <\/div>\r\n                      <div class=\"el-slider-text__slide\">\r\n              <div class=\"el-slider-text__slide-inner balance-elements\" style=\"background-color: #FFFFFF; color: #3D3D3D; \">\r\n                <h2 style=\"text-align: center;\"><span style=\"font-family: arial, helvetica, sans-serif;\"><strong><span style=\"color: #00549d!important;\">2019<\/span><\/strong><\/span><\/h2>\n<p>Optimizaci\u00f3n del dise\u00f1o de Herbst Advance, incorporando un mecanismo antiregresi\u00f3n patentado que mantiene la protrusi\u00f3n y la refuerza con bucles de alambre. No hay ninguna devoluci\u00f3n de las siguientes 5.000 f\u00e9rulas que se fabrican. Lanzamiento en EE.UU. y Asia-Pac\u00edfico de SomnoDent Avant, nuestra f\u00e9rula m\u00e1s c\u00f3moda y de perfil m\u00e1s reducido. SomnoDent Avant utiliza una innovadora banda que sella los labios y fomenta la respiraci\u00f3n nasal, reduciendo los ronquidos y la sequedad bucal. SomnoDent Avant utiliza una plataforma de dise\u00f1o y fabricaci\u00f3n digital y se convierte r\u00e1pidamente en el fabricante de f\u00e9rulas con mayor crecimiento en el sector.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-9887\" src=\"https:\/\/somnomed.com\/en\/wp-content\/uploads\/sites\/2\/2021\/08\/Untitled-design-4.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><\/p>\n              <\/div>\r\n            <\/div>\r\n                      <div class=\"el-slider-text__slide\">\r\n              <div class=\"el-slider-text__slide-inner balance-elements\" style=\"background-color: #FFFFFF; color: #3D3D3D; \">\r\n                <h2 style=\"text-align: center;\"><span style=\"font-family: arial, helvetica, sans-serif;\"><strong><span style=\"color: #00549d!important;\">2020<\/span><\/strong><\/span><\/h2>\n<p>Lanzamiento de SomnoDent Herbst Advance Elite en EE.UU., la segunda f\u00e9rula fabricada con nuestra plataforma digital, que proporciona a los odont\u00f3logos una f\u00e9rula con una resistencia a la flexi\u00f3n un 18% superior y un plan de 3 a\u00f1os de sustituci\u00f3n del producto, sin necesidad de explicaciones.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-9872\" src=\"https:\/\/somnomed.com\/en\/wp-content\/uploads\/sites\/2\/2021\/08\/Untitled-design-1-1.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><\/p>\n              <\/div>\r\n            <\/div>\r\n                  <\/div>\r\n      <\/div>\r\n\r\n      <script>\r\n        jQuery(document).ready(function($) {\r\n          $('#el-slider-text-6a04b889578bc .el-slider-text__slider').slick({\r\n            centerMode: true,\r\n            centerPadding: '300px',\r\n            slidesToShow: 2,\r\n            arrows: true,\r\n            dots: false,\r\n            infinite: true,\r\n            responsive: [\r\n              {\r\n                breakpoint: 1600,\r\n                settings: {\r\n                  arrows: false,\r\n                  dots: true,\r\n                  centerPadding: '150px',\r\n                  slidesToShow: 2\r\n                }\r\n              },\r\n              {\r\n                breakpoint: 768,\r\n                settings: {\r\n                  arrows: false,\r\n                  dots: true,\r\n                  centerPadding: '5px',\r\n                  slidesToShow: 1\r\n                }\r\n              }\r\n            ]\r\n          });\r\n        });\r\n      <\/script>\r\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-ce25389 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ce25389\" data-element_type=\"section\" data-e-type=\"section\" id=\"careers\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-76e108e\" data-id=\"76e108e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9d4e625 elementor-widget elementor-widget-image\" data-id=\"9d4e625\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"1200\" src=\"https:\/\/somnomed.com\/es\/wp-content\/uploads\/sites\/14\/2022\/12\/7.png\" class=\"attachment-1536x1536 size-1536x1536 wp-image-15852\" alt=\"\" srcset=\"https:\/\/somnomed.com\/es\/wp-content\/uploads\/sites\/14\/2022\/12\/7.png 1200w, https:\/\/somnomed.com\/es\/wp-content\/uploads\/sites\/14\/2022\/12\/7-300x300.png 300w, https:\/\/somnomed.com\/es\/wp-content\/uploads\/sites\/14\/2022\/12\/7-1024x1024.png 1024w, https:\/\/somnomed.com\/es\/wp-content\/uploads\/sites\/14\/2022\/12\/7-150x150.png 150w, https:\/\/somnomed.com\/es\/wp-content\/uploads\/sites\/14\/2022\/12\/7-768x768.png 768w, https:\/\/somnomed.com\/es\/wp-content\/uploads\/sites\/14\/2022\/12\/elementor\/thumbs\/7-pywvvv3k2h433oca5idrdoapwqfhyufle82t0c09ig.png 900w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-fadf0a8\" data-id=\"fadf0a8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d219e6b elementor-widget elementor-widget-heading\" data-id=\"d219e6b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Trabaja con nosotros<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bdf1db2 elementor-widget elementor-widget-text-editor\" data-id=\"bdf1db2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<strong>Como l\u00edder global del sector de las f\u00e9rulas para apnea del sue\u00f1o, SomnoMed ha transformado la vida de muchos pacientes. Para ello se requiere pasi\u00f3n, compromiso e innovaci\u00f3n. <\/strong>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8acda3c elementor-widget elementor-widget-text-editor\" data-id=\"8acda3c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Trabajar en SomnoMed ofrece numerosas oportunidades para forjarse una carrera profesional. Si tiene motivaci\u00f3n, esp\u00edritu emprendedor y se crece en entornos din\u00e1micos, SomnoMed es el lugar adecuado para usted. Nuestros empleados trabajan en equipos interdisciplinares y desempe\u00f1an un papel vital para ofrecer innovadoras f\u00e9rulas dentales para el sue\u00f1o a profesionales sanitarios, odont\u00f3logos y pacientes.\u00a0<\/p><p>Descubra las inigualables oportunidades y beneficios de trabajar con nosotros en el sector dental y la medicina del sue\u00f1o. Es mucho m\u00e1s que un trabajo, es un lugar donde colaborar\u00e1 con otros para marcar la diferencia en la calidad de vida de millones de personas de todo el mundo.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f86ac4 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"6f86ac4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/somnomed.bamboohr.com\/careers\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Vacantes disponibles<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-37b6aa22 elementor-section-content-middle elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"37b6aa22\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7874ac8e\" data-id=\"7874ac8e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-7686433c elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"7686433c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-2bf14c0\" data-id=\"2bf14c0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-358b3eb9 elementor-widget elementor-widget-heading\" data-id=\"358b3eb9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Inversores y socios<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-778d8514 elementor-widget elementor-widget-text-editor\" data-id=\"778d8514\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nuestro objetivo es construir la mejor compa\u00f1\u00eda de dispositivos orales para la apnea del sue\u00f1o. Nuestros socios e inversores conf\u00edan en el continuo crecimiento e innovaci\u00f3n de nuestra empresa. Obtenga m\u00e1s informaci\u00f3n sobre c\u00f3mo invertir o, si ya es un inversor, obtenga la informaci\u00f3n m\u00e1s reciente sobre los desarrollos de SomnoMed.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-18f99f91 elementor-widget elementor-widget-button\" data-id=\"18f99f91\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/somnomed.com\/es\/about-us\/investors-partners\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">M\u00e1s informaci\u00f3n<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5036e1ef\" data-id=\"5036e1ef\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-29547f9b elementor-widget elementor-widget-image\" data-id=\"29547f9b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/somnomed.com\/es\/wp-content\/uploads\/sites\/14\/elementor\/thumbs\/A-Global-Company-pfshewbp7522vljiakefnem04dpcn5hbju0cjjtqug.jpg\" title=\"A Global Company\" alt=\"A Global Company\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Qui\u00e9nes somos SomnoMed\u00ae, fundada en 2004, es un compa\u00f1\u00eda de dispositivos m\u00e9dicos cotizada en el \u00edndice ASX con presencia en 28 pa\u00edses. Con sede en S\u00eddney (Australia) y oficinas en Europa y Estados Unidos, SomnoMed se dedica al desarrollo y fabricaci\u00f3n de dispositivos m\u00e9dicos cl\u00ednicamente probados para el tratamiento de la apnea obstructiva del sue\u00f1o &#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-748","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/somnomed.com\/es\/wp-json\/wp\/v2\/pages\/748","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/somnomed.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/somnomed.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/somnomed.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/somnomed.com\/es\/wp-json\/wp\/v2\/comments?post=748"}],"version-history":[{"count":9,"href":"https:\/\/somnomed.com\/es\/wp-json\/wp\/v2\/pages\/748\/revisions"}],"predecessor-version":[{"id":18106,"href":"https:\/\/somnomed.com\/es\/wp-json\/wp\/v2\/pages\/748\/revisions\/18106"}],"wp:attachment":[{"href":"https:\/\/somnomed.com\/es\/wp-json\/wp\/v2\/media?parent=748"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}