{"id":3545,"date":"2021-07-05T05:00:40","date_gmt":"2021-07-05T09:00:40","guid":{"rendered":"http:\/\/somnomed.gsqtest1.com\/en\/?page_id=3545"},"modified":"2024-11-01T14:53:12","modified_gmt":"2024-11-01T13:53:12","slug":"somnodent-classic","status":"publish","type":"page","link":"https:\/\/somnomed.com\/nl\/dentists\/products\/somnodent\/somnodent-classic\/","title":{"rendered":"SomnoDent<sup>\u00ae<\/sup> Classic"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"3545\" class=\"elementor elementor-3545\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-259c65d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"259c65d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-aeb4a2a\" data-id=\"aeb4a2a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-fe4d0b9\" data-id=\"fe4d0b9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-628e76e2 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"628e76e2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1bf411e8\" data-id=\"1bf411e8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7ab490c elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"7ab490c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Afbeelding carrousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 van 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/somnomed.com\/nl\/wp-content\/uploads\/sites\/13\/2021\/07\/SomnoDent-Classic-angle-product-image.jpg\" alt=\"SomnoDent Classic angle product image\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 van 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/somnomed.com\/nl\/wp-content\/uploads\/sites\/13\/2021\/07\/SomnoDent-Classic-with-typodont-side-2-product-image.jpg\" alt=\"SomnoDent Classic side 2 product image\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 van 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/somnomed.com\/nl\/wp-content\/uploads\/sites\/13\/2021\/07\/SomnoDent-Classic-back-product-image.jpg\" alt=\"SomnoDent Classic back product image\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 van 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/somnomed.com\/nl\/wp-content\/uploads\/sites\/13\/2021\/07\/SomnoDent-Classic-side-product-image.jpg\" alt=\"SomnoDent Classic side product image\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 van 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/somnomed.com\/nl\/wp-content\/uploads\/sites\/13\/2021\/07\/SomnoDent-Classic-close-up-product-image.jpg\" alt=\"SomnoDent Classic close up product image\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 van 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/somnomed.com\/nl\/wp-content\/uploads\/sites\/13\/2021\/07\/SomnoDent-Classic-front-product-image.jpg\" alt=\"SomnoDent Classic front product image\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 van 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/somnomed.com\/nl\/wp-content\/uploads\/sites\/13\/2021\/07\/SomnoDent-Classic-separated-product-image.jpg\" alt=\"SomnoDent Classic separated product image\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 van 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/staging.somnomed.com\/en\/wp-content\/uploads\/sites\/2\/2021\/07\/SomnoDent-Classic-with-container-product-image.jpg\" alt=\"\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 van 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/somnomed.com\/nl\/wp-content\/uploads\/sites\/13\/2021\/07\/SomnoDent-Classic-with-typodont-angle-product-image.jpg\" alt=\"SomnoDent Classic with typodont angle product image\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 van 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/somnomed.com\/nl\/wp-content\/uploads\/sites\/13\/2021\/07\/SomnoDent-Classic-with-typodont-front-product-image.jpg\" alt=\"SomnoDent Classic with typodont front product image\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 van 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/somnomed.com\/nl\/wp-content\/uploads\/sites\/13\/2021\/07\/SomnoDent-Classic-with-typodont-side-product-image.jpg\" alt=\"SomnoDent Classic with typodont side product image\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-06a42a7 elementor-widget elementor-widget-image\" data-id=\"06a42a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"141\" src=\"https:\/\/somnomed.com\/nl\/wp-content\/uploads\/sites\/13\/2021\/06\/somnodent-classic-logo-full-color-rgb-1000px@72ppi-768x141.png\" class=\"attachment-medium_large size-medium_large wp-image-1673\" alt=\"SomnoDent Classic logo\" srcset=\"https:\/\/somnomed.com\/nl\/wp-content\/uploads\/sites\/13\/2021\/06\/somnodent-classic-logo-full-color-rgb-1000px@72ppi-768x141.png 768w, https:\/\/somnomed.com\/nl\/wp-content\/uploads\/sites\/13\/2021\/06\/somnodent-classic-logo-full-color-rgb-1000px@72ppi-300x55.png 300w, https:\/\/somnomed.com\/nl\/wp-content\/uploads\/sites\/13\/2021\/06\/somnodent-classic-logo-full-color-rgb-1000px@72ppi.png 1000w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7894c723\" data-id=\"7894c723\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-7e3e568b elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"7e3e568b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-280a8fb1\" data-id=\"280a8fb1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-34b36f03 elementor-widget elementor-widget-heading\" data-id=\"34b36f03\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">SomnoDent<sup>\u00ae<\/sup> Classic<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-42a0f20b elementor-widget elementor-widget-text-editor\" data-id=\"42a0f20b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>De SomnoDent Classic werd gelanceerd in 2005 en was een van de eerste MRA\u2019s die we maakten voor verkoop op de wereldmarkt.<\/p><p>De klassieke variant is gemaakt van hoogwaardig acryl. Deze acrylsoort is speciaal ontwikkeld voor beugels die moeten voldoen aan de hoogste stabiliteitseisen. De Classic heeft knopankers en biedt hierdoor een hoge retentie die eenvoudig kan worden aangepast.<\/p><p>Dit is de klassieke SomnoDent die niet word uitgevoerd met een zachte voering, maar met knopankers. Deze SomnoDent wordt nog wel eens gevraagd bij pati\u00ebnten met veel amalgaamvullingen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fcd779a elementor-widget elementor-widget-button\" data-id=\"fcd779a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/somnomed.com\/nl\/find-a-clinic\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Zoek een tandarts<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-7659d16 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7659d16\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;motion_fx_translateY_direction&quot;:&quot;negative&quot;,&quot;motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:4,&quot;sizes&quot;:[]},&quot;motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-53b7ab3\" data-id=\"53b7ab3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4f281cd elementor-widget elementor-widget-heading\" data-id=\"4f281cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><b>Download onze SomnoDent<\/b><sup>\u00ae<\/sup><b> Classic gebruiksaanwijzing<\/b><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e18705f\" data-id=\"e18705f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cc80f6c elementor-align-left elementor-widget elementor-widget-button\" data-id=\"cc80f6c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/cdn.somnomed.com\/uploads\/XzoXQbjCa5248uLaT\/original.pdf\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Download<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-fa69d1f elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"fa69d1f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c874f40\" data-id=\"c874f40\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-02309c6 elementor-widget elementor-widget-template\" data-id=\"02309c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"7309\" class=\"elementor elementor-7309\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-3363410 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3363410\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9705a78\" data-id=\"9705a78\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7a8ef5b elementor-widget elementor-widget-spacer\" data-id=\"7a8ef5b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8e25a0c elementor-widget elementor-widget-heading\" data-id=\"8e25a0c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">De SomPledge<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dde5255 elementor-widget elementor-widget-heading\" data-id=\"dde5255\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Onze toewijding aan kwaliteit<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c945d60 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"c945d60\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-afcb9e9 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"afcb9e9\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a1fe38c\" data-id=\"a1fe38c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f713f5f elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"f713f5f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tISO 13485\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tAlle MRA's worden vervaardigd volgens de ISO 13485-normen voor kwaliteitsfabricage van medische hulpmiddelen.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8a81c9b elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"8a81c9b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-microscope\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tKwaliteitscontrole \t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tVan begin tot eind bewaken wij de kwaliteit van uw MRA: tijdens productie, van scans tot fabricage tot aan de levering.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ff1a88 elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"3ff1a88\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-file-medical\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tMaterialen van medische kwaliteit\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tHoge kwaliteit van materialen, waaronder dentaal acryl en de b-flex Comfort Liner zachte binnenvoering.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b22c84 elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"6b22c84\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-star\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tPerfecte fit\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t100% beoordeling van IOS-scans of -afdrukken v\u00f3\u00f3r fabricage om ervoor te zorgen dat het MRA comfortabel is voor uw pati\u00ebnt.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-59c3aa8 elementor-widget elementor-widget-spacer\" data-id=\"59c3aa8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-287acc3\" data-id=\"287acc3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-90fab0b elementor-widget elementor-widget-template\" data-id=\"90fab0b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"241\" class=\"elementor elementor-241\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-4a295eb elementor-section-content-middle elementor-section-full_width elementor-reverse-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"4a295eb\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f93fe14 padding-col--left\" data-id=\"f93fe14\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-a4086c2 elementor-section-full_width elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"a4086c2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-0dcdcaa\" data-id=\"0dcdcaa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-72cff3b elementor-widget elementor-widget-heading\" data-id=\"72cff3b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/vimeo.com\/573281862\" target=\"_blank\" rel=\"noopener\">Wat zeggen onze SomnoDent MRA gebruikers <\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c99b2c elementor-widget elementor-widget-text-editor\" data-id=\"1c99b2c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #00549d;\"><strong>Elke pati\u00ebnt is anders en we hebben individuele pati\u00ebnten geholpen op hun reis bij het vinden van een oplossing.<\/strong><\/span><\/p><p>Ontdek wat ze hebben meegemaakt en hoe het voelt om een SomnoDent<sup>\u00ae<\/sup> MRA te gebruiken.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-01e762d\" data-id=\"01e762d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eccdfbe elementor-invisible elementor-widget elementor-widget-video\" data-id=\"eccdfbe\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;lazy_load&quot;:&quot;yes&quot;,&quot;show_image_overlay&quot;:&quot;yes&quot;,&quot;image_overlay&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/somnomed.com\\\/nl\\\/wp-content\\\/uploads\\\/sites\\\/13\\\/2021\\\/06\\\/Wat-zeggen-onze-SomnoDent-MRA-gebruikers.jpg&quot;,&quot;id&quot;:14909,&quot;size&quot;:&quot;&quot;,&quot;alt&quot;:&quot;&quot;,&quot;source&quot;:&quot;library&quot;},&quot;video_type&quot;:&quot;vimeo&quot;,&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<iframe class=\"elementor-video-iframe\" allowfullscreen allow=\"clipboard-write\" title=\"vimeo videospeler\" data-lazy-load=\"https:\/\/player.vimeo.com\/video\/573281862?color&amp;autopause=0&amp;loop=0&amp;muted=0&amp;title=0&amp;portrait=0&amp;byline=0#t=\"><\/iframe>\t\t\t\t<div class=\"elementor-custom-embed-image-overlay\" style=\"background-image: url(https:\/\/somnomed.com\/nl\/wp-content\/uploads\/sites\/13\/2021\/06\/Wat-zeggen-onze-SomnoDent-MRA-gebruikers.jpg);\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-4442681 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"4442681\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8ae51aa\" data-id=\"8ae51aa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2bc5e5c elementor-widget elementor-widget-heading\" data-id=\"2bc5e5c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pati\u00ebnt testimonials<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fb7c08b elementor-widget elementor-widget-Custom_El_Slider_Text\" data-id=\"fb7c08b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"Custom_El_Slider_Text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t          <div id=\"el-slider-text-6a04df83b0ad4\" class=\"el-slider-text\">\r\n        <div class=\"el-slider-text__slider\">\r\n                      <div class=\"el-slider-text__slide\">\r\n              <div class=\"el-slider-text__slide-inner balance-elements\" style=\"background-color: #C3E7EF; color: #000000; \">\r\n                <h3>Pieter, 69 jaar<\/h3>\n<p class=\"_04xlpA direction-ltr align-justify para-style-body\"><span class=\"JsGRdQ\">Ik ben een gelukkig mens en blij dat ik \u2019s morgens uitgerust wakker word zonder het gevoel te hebben dat ik op \u2018Darth Vader\u2019 van Star Wars of een straaljagerpiloot lijk.<\/span><\/p>\n<p class=\"_04xlpA direction-ltr align-justify para-style-body\"><span class=\"JsGRdQ\"> SomnoMed en artsen en verpleging van het Gelre ziekenhuis: bedankt voor het teruggeven van mijn nachtrust!<\/span><\/p>\n<p style=\"text-align: right;\">\n              <\/div>\r\n            <\/div>\r\n                      <div class=\"el-slider-text__slide\">\r\n              <div class=\"el-slider-text__slide-inner balance-elements\" style=\"background-color: #C1CAE3; color: #000000; \">\r\n                <h3>Anita, 57 jaar<\/h3>\n<p class=\"_04xlpA direction-ltr align-justify para-style-body\"><span class=\"JsGRdQ\">Al 4 jaar heb ik hoofdpijn \u2018s nachts. Dan word ik wakker en dan kan ik niet meer slapen. Ik heb al vele medicijnen uitgeprobeerd. <\/span><span class=\"JsGRdQ\">Niets hielp.<\/span><\/p>\n<p class=\"_04xlpA direction-ltr align-justify para-style-body\"><span class=\"JsGRdQ\">Uiteindelijk ben ik via de huisarts en KNO-arts bij jullie terechtgekomen. En sinds 11 augustus 2021 draag ik \u2018s nachts een beugel (slaapbeugel).<\/span><\/p>\n<p class=\"_04xlpA direction-ltr align-justify para-style-body\"><span class=\"JsGRdQ\">Sindsdien snurk ik niet meer en hoef ik niet meer \u2018s nachts te plassen en slaap ik door zonder hoofdpijn.<\/span><\/p>\n              <\/div>\r\n            <\/div>\r\n                      <div class=\"el-slider-text__slide\">\r\n              <div class=\"el-slider-text__slide-inner balance-elements\" style=\"background-color: #7B91C4; color: #FFFFFF; \">\r\n                <h3>Jan, 62 jaar<\/h3>\n<p class=\"_04xlpA direction-ltr align-justify para-style-body\"><span class=\"JsGRdQ\">Sinds twee jaar kreeg ik vage klachten, zoals extreme vermoeidheid, pijnlijke spieren, concentratiestoornis, lusteloosheid, kortademigheid en stemmingswisselingen. Het leek erg op een burn-out, wat ik me echter niet kon voorstellen. De klachten resulteerden in het feit dat ik me op wilskracht de dag door moest slepen.<\/span><\/p>\n<p class=\"_04xlpA direction-ltr align-justify para-style-body\"><span class=\"JsGRdQ\">Door de huisarts werd ik doorverwezen naar de KNO-arts. Hier werd middels een slaaptest dusdanige ademstops\/zuurstoftekort vastgesteld dat ik hiervoor behandeld moest\/kon gaan worden.<\/span><\/p>\n<p class=\"_04xlpA direction-ltr align-justify para-style-body\"><span class=\"JsGRdQ\">De behandeling houdt in dat ik gebruikmaak van een door SomnoMed-Goedegebuure aangemeten en door de basiszorgverzekering vergoede MRA-beugel.<\/span><\/p>\n<p class=\"_04xlpA direction-ltr align-justify para-style-body\"><span class=\"JsGRdQ\">Hierdoor voelde ik me na het eerste gebruik onmiddellijk als herboren en de klachten zijn geheel verdwenen. Dit had ik dus 2 jaar eerder moeten doen.<\/span><\/p>\n              <\/div>\r\n            <\/div>\r\n                      <div class=\"el-slider-text__slide\">\r\n              <div class=\"el-slider-text__slide-inner balance-elements\" style=\"background-color: #5175B3; color: #ffffff; \">\r\n                <h3>Susan, 49 jaar<\/h3>\n<p class=\"_04xlpA direction-ltr align-justify para-style-body\"><span class=\"JsGRdQ\">Vanwege slaapapneu heb ik een aantal jaren geleden een CPAP-apparaat gekregen waar ik helemaal gek van werd, en waar ik nog slechter van ging slapen. Deze heb ik teruggestuurd en ik ben op zoek gegaan via het internet naar een andere oplossing.<\/span><\/p>\n<p class=\"_04xlpA direction-ltr align-justify para-style-body\"><span class=\"JsGRdQ\">Dit werd een bitje van een kliniek uit Bilthoven. Op zich beviel mij dit beter en ik sliep een stuk beter. Echter op enig moment was dit bedrijf verdwenen en kon ik daar niet meer terecht.<\/span><\/p>\n<p class=\"_04xlpA direction-ltr align-justify para-style-body\"><span class=\"JsGRdQ\">Toen ben ik via een doorverwijzing van mijn arts bij het team in het Gelre ziekenhuis terechtgekomen en werd mij een bitje aangemeten van SomnoMed. Dit was letterlijk een verademing!<\/span><\/p>\n              <\/div>\r\n            <\/div>\r\n                  <\/div>\r\n      <\/div>\r\n\r\n      <script>\r\n        jQuery(document).ready(function($) {\r\n          $('#el-slider-text-6a04df83b0ad4 .el-slider-text__slider').slick({\r\n            centerMode: true,\r\n            centerPadding: '300px',\r\n            slidesToShow: 2,\r\n            arrows: true,\r\n            dots: false,\r\n            infinite: true,\r\n            responsive: [\r\n              {\r\n                breakpoint: 1600,\r\n                settings: {\r\n                  arrows: false,\r\n                  dots: true,\r\n                  centerPadding: '150px',\r\n                  slidesToShow: 2\r\n                }\r\n              },\r\n              {\r\n                breakpoint: 768,\r\n                settings: {\r\n                  arrows: false,\r\n                  dots: true,\r\n                  centerPadding: '5px',\r\n                  slidesToShow: 1\r\n                }\r\n              }\r\n            ]\r\n          });\r\n        });\r\n      <\/script>\r\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>De SomnoDent Classic werd gelanceerd in 2005 en was een van de eerste MRA\u2019s die we maakten voor verkoop op de wereldmarkt. De klassieke variant is gemaakt van hoogwaardig acryl. Deze acrylsoort is speciaal ontwikkeld voor beugels die moeten voldoen aan de hoogste stabiliteitseisen. De Classic heeft knopankers en biedt hierdoor een hoge retentie die &#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":3540,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-3545","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/somnomed.com\/nl\/wp-json\/wp\/v2\/pages\/3545","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/somnomed.com\/nl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/somnomed.com\/nl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/somnomed.com\/nl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/somnomed.com\/nl\/wp-json\/wp\/v2\/comments?post=3545"}],"version-history":[{"count":3,"href":"https:\/\/somnomed.com\/nl\/wp-json\/wp\/v2\/pages\/3545\/revisions"}],"predecessor-version":[{"id":15626,"href":"https:\/\/somnomed.com\/nl\/wp-json\/wp\/v2\/pages\/3545\/revisions\/15626"}],"up":[{"embeddable":true,"href":"https:\/\/somnomed.com\/nl\/wp-json\/wp\/v2\/pages\/3540"}],"wp:attachment":[{"href":"https:\/\/somnomed.com\/nl\/wp-json\/wp\/v2\/media?parent=3545"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}